{"id":23644,"date":"2025-05-15T15:32:13","date_gmt":"2025-05-15T14:32:13","guid":{"rendered":"https:\/\/sgciafrica.org\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/"},"modified":"2025-06-05T17:21:53","modified_gmt":"2025-06-05T16:21:53","slug":"incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao","status":"publish","type":"resource","link":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/","title":{"rendered":"Incorporar a transforma\u00e7\u00e3o de g\u00e9nero na ci\u00eancia, tecnologia e inova\u00e7\u00e3o"},"content":{"rendered":"\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-1165aa55\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-d59a06ed wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/Gender-and-inclusivity_Regional-Brief-English-WEB.pdf\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">DESCARREGA O RELAT\u00d3RIO AQUI<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M438.6 278.6l-160 160C272.4 444.9 264.2 448 256 448s-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L338.8 288H32C14.33 288 .0016 273.7 .0016 256S14.33 224 32 224h306.8l-105.4-105.4c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l160 160C451.1 245.9 451.1 266.1 438.6 278.6z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n\n<p><\/p>\n\n<p>As desigualdades de g\u00e9nero na ci\u00eancia, tecnologia e inova\u00e7\u00e3o (CTI) continuam a ser um desafio global. A representa\u00e7\u00e3o das mulheres diminui \u00e0 medida que avan\u00e7am na cadeia de CTI (Huyer, 2019). Abordar a igualdade e a inclus\u00e3o de g\u00e9nero (GEI) na CTI \u00e9 uma quest\u00e3o de justi\u00e7a social e de promo\u00e7\u00e3o socioecon\u00f3mica \u00e0 escala nacional.    <\/p>\n\n<p>A transforma\u00e7\u00e3o do g\u00e9nero \u00e9 uma prioridade da UNESCO e est\u00e1 integrada nos <a href=\"https:\/\/sdgs.un.org\/goals\/goal5\">Objectivos de Desenvolvimento Sustent\u00e1vel<\/a>. Isto obriga os governos a promover a igualdade de g\u00e9nero em todos os aspectos do panorama das CTI.   <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-the-role-of-sgcs-in-driving-gender-equality-in-science-and-innovation\">O papel dos CGS na promo\u00e7\u00e3o da igualdade de g\u00e9nero na ci\u00eancia e na inova\u00e7\u00e3o<\/h3>\n\n<p>Enquanto actores centrais dos sistemas nacionais de inova\u00e7\u00e3o, os Conselhos para a Concess\u00e3o de Apoio Cient\u00edfico (CCG) podem desempenhar um papel fundamental na resolu\u00e7\u00e3o deste problema. Especificamente, podem reduzir as disparidades de g\u00e9nero no desenvolvimento do capital humano em CTI e promover a integra\u00e7\u00e3o do g\u00e9nero na investiga\u00e7\u00e3o e inova\u00e7\u00e3o. Consequentemente, ajudam a garantir que os investimentos cient\u00edficos beneficiam todos.  <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-the-sgci-gender-and-inclusivity-project\">O Projeto de G\u00e9nero e Inclus\u00e3o da SGCI<\/h3>\n\n<p>Este resumo partilha as ideias e recomenda\u00e7\u00f5es da primeira fase do Projeto de G\u00e9nero e Inclus\u00e3o da SGCI. Este projeto inovador de tr\u00eas anos centrou-se na promo\u00e7\u00e3o da igualdade de g\u00e9nero na ci\u00eancia e na inova\u00e7\u00e3o. Utilizou uma abordagem de aprendizagem de a\u00e7\u00e3o participativa para impulsionar a mudan\u00e7a inclusiva. Em particular, o projeto colaborou com 13 Conselhos Africanos de Concess\u00e3o de Ci\u00eancia (SGCs). Em conjunto, desenvolveram e implementaram ac\u00e7\u00f5es-chave para promover a igualdade de g\u00e9nero na CTI. Os conselhos participantes est\u00e3o sediados no Botsuana, Burkina Faso, Costa do Marfim e Gana. Incluem tamb\u00e9m o Qu\u00e9nia, o Malawi, Mo\u00e7ambique, a Nam\u00edbia, o Senegal, a Tanz\u00e2nia, o Uganda, a Z\u00e2mbia e o Zimbabu\u00e9&#8221;.      <\/p>\n\n<p>O Projeto de G\u00e9nero e Inclus\u00e3o da SGCI promove <strong>a igualdade de g\u00e9nero na ci\u00eancia e na inova\u00e7\u00e3o<\/strong> atrav\u00e9s de uma parceria com 13 Conselhos Africanos de Concess\u00e3o de Apoio Cient\u00edfico. Esta iniciativa inovadora de tr\u00eas anos utiliza uma abordagem de aprendizagem de a\u00e7\u00e3o participativa para desenvolver e implementar estrat\u00e9gias eficazes que reduzam as disparidades de g\u00e9nero. Ao promover pol\u00edticas e pr\u00e1ticas inclusivas, a SGCI refor\u00e7a o papel das mulheres na investiga\u00e7\u00e3o e inova\u00e7\u00e3o em todo o continente, promovendo o progresso cient\u00edfico sustent\u00e1vel e equitativo para todas as partes interessadas envolvidas.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>As desigualdades de g\u00e9nero na ci\u00eancia, tecnologia e inova\u00e7\u00e3o (CTI) continuam a ser um desafio global. A representa\u00e7\u00e3o das mulheres diminui \u00e0 medida que avan\u00e7am na cadeia de CTI (Huyer, 2019). Abordar a igualdade e a inclus\u00e3o de g\u00e9nero (GEI) na CTI \u00e9 uma quest\u00e3o de justi\u00e7a social e de promo\u00e7\u00e3o socioecon\u00f3mica \u00e0 escala nacional.&hellip;<\/p>\n","protected":false},"featured_media":23377,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_country":0,"wds_primary_resource-category":0,"wds_primary_sg_theme":0,"wds_primary_sg_type":0},"country":[256,250,172],"resource-category":[],"sg_theme":[150],"sg_type":[],"class_list":["post-23644","resource","type-resource","status-publish","has-post-thumbnail","hentry","country-burkina-faso-2","country-malawi-2","country-senegal","sg_theme-gender-and-inclusivity"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Integrar a igualdade de g\u00e9nero na ci\u00eancia e na inova\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"resultados do projeto SGCI Gender and Inclusivity, destinado a refor\u00e7ar a igualdade entre homens e mulheres na ci\u00eancia e na inova\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incorporar a transforma\u00e7\u00e3o de g\u00e9nero na ci\u00eancia, tecnologia e inova\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"resultados do projeto SGCI Gender and Inclusivity, destinado a refor\u00e7ar a igualdade entre homens e mulheres na ci\u00eancia e na inova\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T16:21:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/resource\\\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/resource\\\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\\\/\",\"name\":\"Integrar a igualdade de g\u00e9nero na ci\u00eancia e na inova\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/resource\\\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/resource\\\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-scaled.jpg\",\"datePublished\":\"2025-05-15T14:32:13+00:00\",\"dateModified\":\"2025-06-05T16:21:53+00:00\",\"description\":\"resultados do projeto SGCI Gender and Inclusivity, destinado a refor\u00e7ar a igualdade entre homens e mulheres na ci\u00eancia e na inova\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/resource\\\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/resource\\\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/resource\\\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Two individuals collaborating on a computer in an office - gender transformation in science, technology and innovation\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/resource\\\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incorporar a transforma\u00e7\u00e3o de g\u00e9nero na ci\u00eancia, tecnologia e inova\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Integrar a igualdade de g\u00e9nero na ci\u00eancia e na inova\u00e7\u00e3o","description":"resultados do projeto SGCI Gender and Inclusivity, destinado a refor\u00e7ar a igualdade entre homens e mulheres na ci\u00eancia e na inova\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Incorporar a transforma\u00e7\u00e3o de g\u00e9nero na ci\u00eancia, tecnologia e inova\u00e7\u00e3o","og_description":"resultados do projeto SGCI Gender and Inclusivity, destinado a refor\u00e7ar a igualdade entre homens e mulheres na ci\u00eancia e na inova\u00e7\u00e3o.","og_url":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/","og_site_name":"SGCI Africa","article_modified_time":"2025-06-05T16:21:53+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SGCIAfrica","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/","url":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/","name":"Integrar a igualdade de g\u00e9nero na ci\u00eancia e na inova\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-scaled.jpg","datePublished":"2025-05-15T14:32:13+00:00","dateModified":"2025-06-05T16:21:53+00:00","description":"resultados do projeto SGCI Gender and Inclusivity, destinado a refor\u00e7ar a igualdade entre homens e mulheres na ci\u00eancia e na inova\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-scaled.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-scaled.jpg","width":2560,"height":1707,"caption":"Two individuals collaborating on a computer in an office - gender transformation in science, technology and innovation"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/pt\/resource\/incorporar-a-transformacao-de-genero-na-ciencia-tecnologia-e-inovacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Incorporar a transforma\u00e7\u00e3o de g\u00e9nero na ci\u00eancia, tecnologia e inova\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-scaled.jpg",2560,1707,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-300x200.jpg",300,200,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-768x512.jpg",768,512,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-2048x1365.jpg",2048,1365,true],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-1920x1280.jpg",1920,1280,true],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-1696x1131.jpg",1696,1131,true],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-1352x901.jpg",1352,901,true],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-1294x852.jpg",1294,852,true],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/desola-lanre-ologun-kwzWjTnDPLk-unsplash-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Emily Skivington","author_link":"https:\/\/sgciafrica.org\/pt\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"As desigualdades de g\u00e9nero na ci\u00eancia, tecnologia e inova\u00e7\u00e3o (CTI) continuam a ser um desafio global. A representa\u00e7\u00e3o das mulheres diminui \u00e0 medida que avan\u00e7am na cadeia de CTI (Huyer, 2019). Abordar a igualdade e a inclus\u00e3o de g\u00e9nero (GEI) na CTI \u00e9 uma quest\u00e3o de justi\u00e7a social e de promo\u00e7\u00e3o socioecon\u00f3mica \u00e0 escala nacional.&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/resource\/23644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media\/23377"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media?parent=23644"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/country?post=23644"},{"taxonomy":"resource-category","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/resource-category?post=23644"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/sg_theme?post=23644"},{"taxonomy":"sg_type","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/sg_type?post=23644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}