{"id":25693,"date":"2026-03-06T11:29:30","date_gmt":"2026-03-06T11:29:30","guid":{"rendered":"https:\/\/sgciafrica.org\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/"},"modified":"2026-03-06T11:30:42","modified_gmt":"2026-03-06T11:30:42","slug":"namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/","title":{"rendered":"Nam\u00edbia lan\u00e7a relat\u00f3rio do inqu\u00e9rito nacional sobre infraestruturas de investiga\u00e7\u00e3o"},"content":{"rendered":"\n<p>A Comiss\u00e3o <a href=\"https:\/\/www.ncrst.na\/\">Nacional<\/a> de Investiga\u00e7\u00e3o, Ci\u00eancia e Tecnologia da Nam\u00edbia lan\u00e7ou oficialmente o Relat\u00f3rio do Inqu\u00e9rito sobre Infraestruturas de Investiga\u00e7\u00e3o do pa\u00eds, delineando as instala\u00e7\u00f5es de investiga\u00e7\u00e3o existentes, as principais lacunas e as \u00e1reas priorit\u00e1rias para o desenvolvimento.<\/p>\n\n<p>O relat\u00f3rio foi apresentado a 3 de mar\u00e7o no Centro Cultural Franco-Namibiano, em Windhoek, perante uma audi\u00eancia de partes interessadas provenientes do governo, da academia e da ind\u00fastria.<\/p>\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-92040767 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-at-the-launch-of-NCRST-survey-1-1024x683.jpg ,https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-at-the-launch-of-NCRST-survey-1.jpg 780w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-at-the-launch-of-NCRST-survey-1.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-at-the-launch-of-NCRST-survey-1-1024x683.jpg\" alt=\"\" class=\"uag-image-25689\" width=\"408\" height=\"272\" title=\"Anicia Peters no lan\u00e7amento do inqu\u00e9rito da NCRST\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n<p>A diretora executiva da NCRST, Anicia Peters, afirmou que as conclus\u00f5es teriam implica\u00e7\u00f5es concretas para o desenvolvimento do setor.<\/p>\n\n<p>\u201cO relat\u00f3rio orientar\u00e1 o nosso planeamento estrat\u00e9gico, informar\u00e1 as decis\u00f5es de investimento e refor\u00e7ar\u00e1 a coordena\u00e7\u00e3o em todo o setor da investiga\u00e7\u00e3o, ci\u00eancia e inova\u00e7\u00e3o da Nam\u00edbia\u201d, afirmou.<\/p>\n\n<p>O relat\u00f3rio fornece uma avalia\u00e7\u00e3o abrangente das infraestruturas de investiga\u00e7\u00e3o da Nam\u00edbia, mapeando as instala\u00e7\u00f5es existentes em todo o pa\u00eds, avaliando as capacidades institucionais e identificando as necessidades nacionais de investiga\u00e7\u00e3o e as \u00e1reas priorit\u00e1rias cr\u00edticas.<\/p>\n\n<p>Baseia-se tamb\u00e9m em dados de refer\u00eancia do inqu\u00e9rito de 2017, permitindo uma vis\u00e3o longitudinal da evolu\u00e7\u00e3o do panorama e refor\u00e7ando a base de evid\u00eancias para a futura formula\u00e7\u00e3o de pol\u00edticas em mat\u00e9ria de investiga\u00e7\u00e3o, ci\u00eancia e tecnologia.<\/p>\n\n<p class=\"has-large-font-size\"><strong>O lan\u00e7amento<\/strong><strong><\/strong><\/p>\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-aca60c87 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-and-staff-of-the-NCRST-at-the-launch-of-the-survey-report-1024x683.jpg ,https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-and-staff-of-the-NCRST-at-the-launch-of-the-survey-report.jpg 780w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-and-staff-of-the-NCRST-at-the-launch-of-the-survey-report.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-and-staff-of-the-NCRST-at-the-launch-of-the-survey-report-1024x683.jpg\" alt=\"\" class=\"uag-image-25690\" width=\"1080\" height=\"720\" title=\"Anicia Peters e funcion\u00e1rios da NCRST no lan\u00e7amento do relat\u00f3rio do inqu\u00e9rito\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n<p>As observa\u00e7\u00f5es de abertura foram proferidas por Nhlanhla Lupahla, gestor geral de Apoio \u00e0 Investiga\u00e7\u00e3o, Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o.<\/p>\n\n<p>Descreveu o lan\u00e7amento como \u201cum passo importante para o refor\u00e7o do panorama das infraestruturas de investiga\u00e7\u00e3o da Nam\u00edbia, promovendo o acesso equitativo \u00e0s instala\u00e7\u00f5es e fazendo avan\u00e7ar a agenda nacional de investiga\u00e7\u00e3o\u201d.<\/p>\n\n<p>As conclus\u00f5es do inqu\u00e9rito foram depois apresentadas por Hilya Shikongo, gestora geral interina da Divis\u00e3o de Inova\u00e7\u00e3o e Desenvolvimento Tecnol\u00f3gico, que explicou aos presentes a metodologia, os dados e as principais recomenda\u00e7\u00f5es do relat\u00f3rio.<\/p>\n\n<p><strong>Do inqu\u00e9rito \u00e0 a\u00e7\u00e3o<\/strong><strong><\/strong><\/p>\n\n<p>O relat\u00f3rio serve de base para um trabalho mais amplo de refor\u00e7o de capacidades. Os conselhos de fomento \u00e0 <a href=\"https:\/\/sgciafrica.org\/pt\/council\/comissao-nacional-de-pesquisa-em-ciencia-e-tecnologia-namibia\/\">ci\u00eancia<\/a> em todo o continente aprenderam que ecossistemas de investiga\u00e7\u00e3o sustent\u00e1veis exigem mais do que financiamento.<\/p>\n\n<p>Exigem infraestruturas que sejam acess\u00edveis, bem mantidas e distribu\u00eddas de forma a servir todo o pa\u00eds, e n\u00e3o apenas os seus principais centros.<\/p>\n\n<p>Com o relat\u00f3rio do inqu\u00e9rito agora p\u00fablico, a Nam\u00edbia tem uma imagem mais clara de qu\u00e3o longe chegou e do caminho que ainda tem de percorrer.<\/p>\n\n<p><strong><em>Consulta as <\/em><\/strong><a href=\"https:\/\/sgciafrica.org\/pt\/noticias\/\"><em>hist\u00f3rias<\/em><\/a><strong><em>  e diz-nos o que pensas. Gostar\u00edamos muito de ouvir a tua opini\u00e3o! <\/em><\/strong><em><\/em><\/p>\n\n<p><em>Continua a conversa<\/em><em> nas nossas redes sociais<\/em><\/p>\n\n<p><em>Segue-nos no <\/em><a href=\"https:\/\/www.linkedin.com\/company\/science-granting-councils-initiative\/\"><em>LinkedIn<\/em><\/a><em> e <\/em><a href=\"https:\/\/x.com\/SGCIAfrica\"><em>X<\/em><\/a><em><\/em><\/p>\n\n<p><em>Publicado a 6 de mar\u00e7o de 2026<\/em><\/p>\n\n<p><em>Escrito por Jackie Opara-Fatoye,<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o Nacional de Investiga\u00e7\u00e3o, Ci\u00eancia e Tecnologia da Nam\u00edbia lan\u00e7ou oficialmente o Relat\u00f3rio do Inqu\u00e9rito sobre Infraestruturas de Investiga\u00e7\u00e3o do pa\u00eds, delineando as instala\u00e7\u00f5es de investiga\u00e7\u00e3o existentes, as principais lacunas e as \u00e1reas priorit\u00e1rias para o desenvolvimento. O relat\u00f3rio foi apresentado a 3 de mar\u00e7o no Centro Cultural Franco-Namibiano, em Windhoek, perante uma audi\u00eancia&hellip;<\/p>\n","protected":false},"author":14,"featured_media":25694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[159],"tags":[421,219,216,371],"country":[252],"objective":[273],"sg_theme":[279],"class_list":["post-25693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-infraestrutura","tag-namibia-pt","tag-research-pt","tag-sgci-pt","country-namibia-pt","objective-develop-industry-pt","sg_theme-research-management-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia - SGCI Africa<\/title>\n<meta name=\"description\" content=\"O novo relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia revela lacunas fundamentais e \u00e1reas priorit\u00e1rias para desenvolvimento e investimento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nam\u00edbia lan\u00e7a relat\u00f3rio do inqu\u00e9rito nacional sobre infraestruturas de investiga\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O novo relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia revela lacunas fundamentais e \u00e1reas priorit\u00e1rias para desenvolvimento e investimento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-06T11:29:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-06T11:30:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Titilope Fadare\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Titilope Fadare\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/\"},\"author\":{\"name\":\"Titilope Fadare\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/805409d9d7ecdd7dd47541c544a540ad\"},\"headline\":\"Nam\u00edbia lan\u00e7a relat\u00f3rio do inqu\u00e9rito nacional sobre infraestruturas de investiga\u00e7\u00e3o\",\"datePublished\":\"2026-03-06T11:29:30+00:00\",\"dateModified\":\"2026-03-06T11:30:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/\"},\"wordCount\":494,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Launching-of-the-survey-report.jpg\",\"keywords\":[\"Infraestrutura\",\"Nam\u00edbia\",\"Research\",\"SGCI\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/\",\"name\":\"Relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Launching-of-the-survey-report.jpg\",\"datePublished\":\"2026-03-06T11:29:30+00:00\",\"dateModified\":\"2026-03-06T11:30:42+00:00\",\"description\":\"O novo relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia revela lacunas fundamentais e \u00e1reas priorit\u00e1rias para desenvolvimento e investimento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Launching-of-the-survey-report.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Launching-of-the-survey-report.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Lan\u00e7amento do relat\u00f3rio do inqu\u00e9rito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nam\u00edbia lan\u00e7a relat\u00f3rio do inqu\u00e9rito nacional sobre infraestruturas de investiga\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/805409d9d7ecdd7dd47541c544a540ad\",\"name\":\"Titilope Fadare\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/b7b\\\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/b7b\\\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/b7b\\\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg\",\"caption\":\"Titilope Fadare\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/author\\\/titilopefadare\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia - SGCI Africa","description":"O novo relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia revela lacunas fundamentais e \u00e1reas priorit\u00e1rias para desenvolvimento e investimento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Nam\u00edbia lan\u00e7a relat\u00f3rio do inqu\u00e9rito nacional sobre infraestruturas de investiga\u00e7\u00e3o","og_description":"O novo relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia revela lacunas fundamentais e \u00e1reas priorit\u00e1rias para desenvolvimento e investimento.","og_url":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/","og_site_name":"SGCI Africa","article_published_time":"2026-03-06T11:29:30+00:00","article_modified_time":"2026-03-06T11:30:42+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","type":"image\/jpeg"}],"author":"Titilope Fadare","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"Escrito por":"Titilope Fadare","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/"},"author":{"name":"Titilope Fadare","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/805409d9d7ecdd7dd47541c544a540ad"},"headline":"Nam\u00edbia lan\u00e7a relat\u00f3rio do inqu\u00e9rito nacional sobre infraestruturas de investiga\u00e7\u00e3o","datePublished":"2026-03-06T11:29:30+00:00","dateModified":"2026-03-06T11:30:42+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/"},"wordCount":494,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","keywords":["Infraestrutura","Nam\u00edbia","Research","SGCI"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/","url":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/","name":"Relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","datePublished":"2026-03-06T11:29:30+00:00","dateModified":"2026-03-06T11:30:42+00:00","description":"O novo relat\u00f3rio sobre a Melhoria das Infraestruturas de Investiga\u00e7\u00e3o na Nam\u00edbia revela lacunas fundamentais e \u00e1reas priorit\u00e1rias para desenvolvimento e investimento.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","width":1080,"height":720,"caption":"Lan\u00e7amento do relat\u00f3rio do inqu\u00e9rito"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/pt\/namibia-lanca-relatorio-do-inquerito-nacional-sobre-infraestruturas-de-investigacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Nam\u00edbia lan\u00e7a relat\u00f3rio do inqu\u00e9rito nacional sobre infraestruturas de investiga\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/805409d9d7ecdd7dd47541c544a540ad","name":"Titilope Fadare","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/b7b\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/b7b\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/b7b\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg","caption":"Titilope Fadare"},"url":"https:\/\/sgciafrica.org\/pt\/author\/titilopefadare\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-300x200.jpg",300,200,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-768x512.jpg",768,512,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Titilope Fadare","author_link":"https:\/\/sgciafrica.org\/pt\/author\/titilopefadare\/"},"uagb_comment_info":0,"uagb_excerpt":"A Comiss\u00e3o Nacional de Investiga\u00e7\u00e3o, Ci\u00eancia e Tecnologia da Nam\u00edbia lan\u00e7ou oficialmente o Relat\u00f3rio do Inqu\u00e9rito sobre Infraestruturas de Investiga\u00e7\u00e3o do pa\u00eds, delineando as instala\u00e7\u00f5es de investiga\u00e7\u00e3o existentes, as principais lacunas e as \u00e1reas priorit\u00e1rias para o desenvolvimento. O relat\u00f3rio foi apresentado a 3 de mar\u00e7o no Centro Cultural Franco-Namibiano, em Windhoek, perante uma audi\u00eancia&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/25693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/comments?post=25693"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/25693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media\/25694"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media?parent=25693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/categories?post=25693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/tags?post=25693"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/country?post=25693"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/objective?post=25693"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/sg_theme?post=25693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}