{"id":25474,"date":"2026-01-21T12:47:12","date_gmt":"2026-01-21T12:47:12","guid":{"rendered":"https:\/\/sgciafrica.org\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/"},"modified":"2026-01-21T12:50:48","modified_gmt":"2026-01-21T12:50:48","slug":"a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/","title":{"rendered":"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim"},"content":{"rendered":"\n<p>A comunica\u00e7\u00e3o eficaz da investiga\u00e7\u00e3o \u00e9 fundamental para garantir que a ci\u00eancia informe as pol\u00edticas, chegue \u00e0s comunidades e inspire a pr\u00f3xima gera\u00e7\u00e3o de cientistas.<\/p>\n\n<p>No \u00e2mbito da Science Granting Councils Initiative (SGCI), os membros est\u00e3o a experimentar cada vez mais formas criativas e centradas nas pessoas de tornar a investiga\u00e7\u00e3o mais vis\u00edvel, acess\u00edvel e relevante para al\u00e9m dos c\u00edrculos acad\u00e9micos e como uma fun\u00e7\u00e3o essencial dos sistemas cient\u00edficos nacionais.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"632\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONTI_BODY.jpg\" alt=\"\" class=\"wp-image-25469\" srcset=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONTI_BODY.jpg 450w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONTI_BODY-214x300.jpg 214w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/figure>\n<\/div>\n<p>Um exemplo \u00e9 a <a href=\"https:\/\/fonsti.org\/wp-content\/uploads\/2026\/01\/FONTSI-MAG-3.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FONSTI Mag<\/a>, a principal revista de ci\u00eancia, tecnologia e inova\u00e7\u00e3o do <em>Fonds pour la Science, la Technologie et l&#8217;Innovation (<\/em><a href=\"https:\/\/fonsti.org\">FONSTI<\/a><em>)<\/em> da Costa do Marfim.<\/p>\n\n<p>A revista \u00e9 um investimento na narra\u00e7\u00e3o de hist\u00f3rias cient\u00edficas como ponte entre investigadores, decisores pol\u00edticos e o p\u00fablico.<\/p>\n\n<p>Esta edi\u00e7\u00e3o leva os leitores a aprofundar as oportunidades e os desafios que moldam o panorama da IA em \u00c1frica e oferece uma perspetiva estrat\u00e9gica da Costa do Marfim na era da IA, explorando as vis\u00f5es nacionais, os desafios emergentes e as vias futuras para uma ado\u00e7\u00e3o respons\u00e1vel e inclusiva.<\/p>\n\n<p>A FONSTI Mag mostra como a comunica\u00e7\u00e3o da investiga\u00e7\u00e3o pode servir como uma infraestrutura estrat\u00e9gica para ajudar a colmatar a lacuna entre a produ\u00e7\u00e3o e a utiliza\u00e7\u00e3o do conhecimento, bem como apoiar a elabora\u00e7\u00e3o de pol\u00edticas baseadas em provas, refor\u00e7ar a confian\u00e7a do p\u00fablico na ci\u00eancia, elevar a investiga\u00e7\u00e3o africana a n\u00edvel mundial e inspirar os jovens a verem-se a si pr\u00f3prios como parte do ecossistema de CTI.<\/p>\n\n<p>A SGCI continua a defender abordagens inovadoras \u00e0 comunica\u00e7\u00e3o da investiga\u00e7\u00e3o. A FONSTI Mag \u00e9 um exemplo convincente de como os conselhos de financiamento da ci\u00eancia podem aproximar a investiga\u00e7\u00e3o das pessoas e garantir que o conhecimento conduz \u00e0 a\u00e7\u00e3o. <\/p>\n\n<p><em>D\u00e1 uma vista de olhos nas <a href=\"https:\/\/sgciafrica.org\/pt\/noticias\/\">hist\u00f3rias<\/a> e diz-nos o que pensas. Gostar\u00edamos muito de ouvir a tua opini\u00e3o! <\/em><\/p>\n\n<p><em>Vamos continuar a conversa nas nossas redes sociais<\/em><\/p>\n\n<p><em>Segue-nos no <\/em><a href=\"https:\/\/www.linkedin.com\/company\/science-granting-councils-initiative\/\"><em>LinkedIn<\/em><\/a><em> e <\/em><a href=\"https:\/\/x.com\/SGCIAfrica\"><em>X<\/em><\/a><\/p>\n\n<p><em>Publicado em 21 de janeiro de 2026<\/em><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A comunica\u00e7\u00e3o eficaz da investiga\u00e7\u00e3o \u00e9 fundamental para garantir que a ci\u00eancia informe as pol\u00edticas, chegue \u00e0s comunidades e inspire a pr\u00f3xima gera\u00e7\u00e3o de cientistas. No \u00e2mbito da Science Granting Councils Initiative (SGCI), os membros est\u00e3o a experimentar cada vez mais formas criativas e centradas nas pessoas de tornar a investiga\u00e7\u00e3o mais vis\u00edvel, acess\u00edvel e&hellip;<\/p>\n","protected":false},"author":13,"featured_media":25468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[159],"tags":[],"country":[259],"objective":[],"sg_theme":[],"class_list":["post-25474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","country-cote-d-ivoire-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim - SGCI Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim\" \/>\n<meta property=\"og:description\" content=\"A comunica\u00e7\u00e3o eficaz da investiga\u00e7\u00e3o \u00e9 fundamental para garantir que a ci\u00eancia informe as pol\u00edticas, chegue \u00e0s comunidades e inspire a pr\u00f3xima gera\u00e7\u00e3o de cientistas. No \u00e2mbito da Science Granting Councils Initiative (SGCI), os membros est\u00e3o a experimentar cada vez mais formas criativas e centradas nas pessoas de tornar a investiga\u00e7\u00e3o mais vis\u00edvel, acess\u00edvel e&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-21T12:47:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T12:50:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davis Weddi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davis Weddi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/\"},\"author\":{\"name\":\"Davis Weddi\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\"},\"headline\":\"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim\",\"datePublished\":\"2026-01-21T12:47:12+00:00\",\"dateModified\":\"2026-01-21T12:50:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/\"},\"wordCount\":376,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/FONSTIYayaSangare_MAIN.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/\",\"name\":\"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/FONSTIYayaSangare_MAIN.jpg\",\"datePublished\":\"2026-01-21T12:47:12+00:00\",\"dateModified\":\"2026-01-21T12:50:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/FONSTIYayaSangare_MAIN.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/FONSTIYayaSangare_MAIN.jpg\",\"width\":996,\"height\":567,\"caption\":\"Yaya Sangare\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\",\"name\":\"Davis Weddi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"caption\":\"Davis Weddi\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/author\\\/davisweddi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim - SGCI Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/","og_locale":"pt_BR","og_type":"article","og_title":"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim","og_description":"A comunica\u00e7\u00e3o eficaz da investiga\u00e7\u00e3o \u00e9 fundamental para garantir que a ci\u00eancia informe as pol\u00edticas, chegue \u00e0s comunidades e inspire a pr\u00f3xima gera\u00e7\u00e3o de cientistas. No \u00e2mbito da Science Granting Councils Initiative (SGCI), os membros est\u00e3o a experimentar cada vez mais formas criativas e centradas nas pessoas de tornar a investiga\u00e7\u00e3o mais vis\u00edvel, acess\u00edvel e&hellip;","og_url":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/","og_site_name":"SGCI Africa","article_published_time":"2026-01-21T12:47:12+00:00","article_modified_time":"2026-01-21T12:50:48+00:00","og_image":[{"width":996,"height":567,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg","type":"image\/jpeg"}],"author":"Davis Weddi","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"Escrito por":"Davis Weddi","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/"},"author":{"name":"Davis Weddi","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92"},"headline":"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim","datePublished":"2026-01-21T12:47:12+00:00","dateModified":"2026-01-21T12:50:48+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/"},"wordCount":376,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/","url":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/","name":"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg","datePublished":"2026-01-21T12:47:12+00:00","dateModified":"2026-01-21T12:50:48+00:00","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg","width":996,"height":567,"caption":"Yaya Sangare"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/pt\/a-revista-fonsti-uma-nova-era-para-a-narracao-de-historias-sobre-ciencia-na-costa-do-marfim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/pt\/"},{"@type":"ListItem","position":2,"name":"A revista FONSTI: Uma nova era para a narra\u00e7\u00e3o de hist\u00f3rias sobre ci\u00eancia na Costa do Marfim"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92","name":"Davis Weddi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","caption":"Davis Weddi"},"url":"https:\/\/sgciafrica.org\/pt\/author\/davisweddi\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg",996,567,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN-300x171.jpg",300,171,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN-768x437.jpg",768,437,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg",996,567,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg",996,567,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg",996,567,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg",996,567,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg",996,567,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg",996,567,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN.jpg",996,567,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/01\/FONSTIYayaSangare_MAIN-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Davis Weddi","author_link":"https:\/\/sgciafrica.org\/pt\/author\/davisweddi\/"},"uagb_comment_info":0,"uagb_excerpt":"A comunica\u00e7\u00e3o eficaz da investiga\u00e7\u00e3o \u00e9 fundamental para garantir que a ci\u00eancia informe as pol\u00edticas, chegue \u00e0s comunidades e inspire a pr\u00f3xima gera\u00e7\u00e3o de cientistas. No \u00e2mbito da Science Granting Councils Initiative (SGCI), os membros est\u00e3o a experimentar cada vez mais formas criativas e centradas nas pessoas de tornar a investiga\u00e7\u00e3o mais vis\u00edvel, acess\u00edvel e&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/25474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/comments?post=25474"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/25474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media\/25468"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media?parent=25474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/categories?post=25474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/tags?post=25474"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/country?post=25474"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/objective?post=25474"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/sg_theme?post=25474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}