{"id":23590,"date":"2025-05-15T16:12:45","date_gmt":"2025-05-15T15:12:45","guid":{"rendered":"https:\/\/sgciafrica.org\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/"},"modified":"2026-02-13T13:31:10","modified_gmt":"2026-02-13T13:31:10","slug":"a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/","title":{"rendered":"NRF destaca dez anos de progresso da SGCI na gest\u00e3o de investiga\u00e7\u00e3o"},"content":{"rendered":"\n<p>Em abril de 2025, a Iniciativa dos Conselhos de Concess\u00e3o de Bolsas de Investiga\u00e7\u00e3o Cient\u00edfica (SGCI) na \u00c1frica Subsariana assinalou dez anos de refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o. <\/p>\n\n<p>Desde a sua cria\u00e7\u00e3o, a SGCI tem trabalhado em 17 pa\u00edses para fortalecer os sistemas de ci\u00eancia, tecnologia e inova\u00e7\u00e3o (CTI), atrav\u00e9s de parcerias com conselhos de investiga\u00e7\u00e3o, ag\u00eancias de desenvolvimento e organiza\u00e7\u00f5es regionais e internacionais. <\/p>\n\n<p>Um estudo de 2014 que levou \u00e0 forma\u00e7\u00e3o da SGCI revelou que, embora os <a href=\"https:\/\/sgciafrica.org\/pt\/conselhos-de-concessao-de-ciencia\/\">Conselhos de Concess\u00e3o de Bolsas de Investiga\u00e7\u00e3o Cient\u00edfica (SGCs)<\/a> desempenhem pap\u00e9is vitais, tais como o financiamento da investiga\u00e7\u00e3o, o aconselhamento de governos e a gest\u00e3o de parcerias, necessitavam de capacidade institucional, particularmente na gest\u00e3o de investiga\u00e7\u00e3o.<\/p>\n\n<p>A SGCI colocou a gest\u00e3o de investiga\u00e7\u00e3o no centro da sua programa\u00e7\u00e3o inicial para dar resposta a esta quest\u00e3o. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-training-and-tools-focused-on-enhancing-the-capacity-of-research-managers\"><strong>Forma\u00e7\u00e3o e ferramentas focadas no refor\u00e7o da capacidade dos gestores de investiga\u00e7\u00e3o<\/strong><\/h2>\n\n<p>O fortalecimento da Gest\u00e3o e Administra\u00e7\u00e3o de Investiga\u00e7\u00e3o (RMA) tornou-se uma prioridade estrat\u00e9gica, uma vez que os conselhos necessitavam de sistemas robustos de gest\u00e3o de investiga\u00e7\u00e3o e de profissionais qualificados para gerir os fundos de investiga\u00e7\u00e3o de forma eficaz. <\/p>\n\n<p>A <a href=\"https:\/\/www.sarima.co.za\/\">Associa\u00e7\u00e3o de Gest\u00e3o de Investiga\u00e7\u00e3o e Inova\u00e7\u00e3o da \u00c1frica Austral (SARIMA)<\/a> e as suas organiza\u00e7\u00f5es cong\u00e9neres, as Associa\u00e7\u00f5es de Gest\u00e3o de Investiga\u00e7\u00e3o e Inova\u00e7\u00e3o (RIMAs), CARIMA, EARIMA e WARIMA, foram fundamentais para este esfor\u00e7o, oferecendo forma\u00e7\u00e3o, apoio t\u00e9cnico e oportunidades de aprendizagem entre pares que abrangeram todo o ciclo de vida das bolsas de investiga\u00e7\u00e3o.<\/p>\n\n<p>Atrav\u00e9s destas colabora\u00e7\u00f5es, a SGCI apoiou o desenvolvimento de um quadro de compet\u00eancias profissionais e lan\u00e7ou cursos online acreditados atrav\u00e9s da Universidade de Witwatersrand. <\/p>\n\n<p>Foram tamb\u00e9m introduzidas ferramentas pr\u00e1ticas, como manuais de gest\u00e3o de bolsas e diretrizes de concursos. <\/p>\n\n<p>Estes esfor\u00e7os ajudaram a definir a RMA como uma profiss\u00e3o leg\u00edtima dentro dos conselhos de financiamento, distinta das fun\u00e7\u00f5es baseadas em universidades, e levaram ao surgimento de gestores de investiga\u00e7\u00e3o certificados.<\/p>\n\n<p>Um exemplo deste impacto \u00e9 Luiza Mazazire, da Nam\u00edbia, que se tornou a primeira pessoa no seu pa\u00eds a ser reconhecida profissionalmente atrav\u00e9s do Conselho Internacional de Reconhecimento Profissional. <\/p>\n\n<p>A sua progress\u00e3o na carreira ilustra como o refor\u00e7o das capacidades individuais contribui para o avan\u00e7o institucional e sist\u00e9mico. <\/p>\n\n<p>Atualmente, continua a defender a gest\u00e3o de investiga\u00e7\u00e3o na Universidade de Ci\u00eancia e Tecnologia da Nam\u00edbia.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-sgci-s-ongoing-support-in-enhancing-the-capacity-of-research-councils\"><strong>O apoio cont\u00ednuo da SGCI no refor\u00e7o da capacidade dos conselhos de investiga\u00e7\u00e3o<\/strong><\/h2>\n\n<p>A procura por forma\u00e7\u00e3o e reconhecimento est\u00e1 a crescer, com o apoio cont\u00ednuo alargado a pa\u00edses como a Eti\u00f3pia, o Gana e o Zimbabu\u00e9. <\/p>\n\n<p>A SARIMA foca-se agora na constru\u00e7\u00e3o de percursos estruturados a longo prazo para indiv\u00edduos e institui\u00e7\u00f5es. <\/p>\n\n<p>Reconhecendo que a rotatividade de pessoal pode dificultar a continuidade, a difus\u00e3o de pessoal formado por todo o ecossistema de investiga\u00e7\u00e3o \u00e9 vista como uma for\u00e7a, e n\u00e3o como um rev\u00e9s.<\/p>\n\n<p>Olhando para o futuro, a integra\u00e7\u00e3o da forma\u00e7\u00e3o em RMA como uma fun\u00e7\u00e3o institucional permanente \u00e9 essencial. Modelos internos de forma\u00e7\u00e3o de formadores, estrat\u00e9gias de envolvimento abrangentes e desenvolvimento profissional adaptado a profissionais experientes ser\u00e3o fundamentais para a pr\u00f3xima fase.  <\/p>\n\n<p>A vis\u00e3o da SGCI para o futuro \u00e9 uma cultura de gest\u00e3o de investiga\u00e7\u00e3o profundamente enraizada que apoie sistemas de CTI resilientes e eficazes em toda a \u00c1frica.<\/p>\n\n<p>Leia mais <a href=\"https:\/\/www.nrf.ac.za\/from-foundations-to-futures-strengthening-research-management-in-african-science-granting-councils\/\">aqui<\/a><strong> <\/strong><\/p>\n\n<p>Consulte as <a href=\"https:\/\/sgciafrica.org\/pt\/noticias\/\">hist\u00f3rias<\/a> e diga-nos o que pensa. Gostar\u00edamos muito de o ouvir!<\/p>\n\n<p>Vamos continuar a conversa nas nossas redes sociais<\/p>\n\n<p>Segue-nos no <a href=\"https:\/\/www.linkedin.com\/company\/science-granting-councils-initiative\/\">LinkedIn<\/a><\/p>\n\n<p><em>Publicado a 15 de maio de 2025<\/em><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em abril de 2025, a Iniciativa dos Conselhos de Concess\u00e3o de Bolsas de Investiga\u00e7\u00e3o Cient\u00edfica (SGCI) na \u00c1frica Subsariana assinalou dez anos de refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o. Desde a sua cria\u00e7\u00e3o, a SGCI tem trabalhado em 17 pa\u00edses para fortalecer os sistemas de ci\u00eancia, tecnologia e inova\u00e7\u00e3o (CTI), atrav\u00e9s de&hellip;<\/p>\n","protected":false},"author":13,"featured_media":23381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[159],"tags":[],"country":[],"objective":[],"sg_theme":[],"class_list":["post-23590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NRF assinala dez anos de progresso da SGCI no refor\u00e7o de capacidades<\/title>\n<meta name=\"description\" content=\"A NRF da \u00c1frica do Sul assinala dez anos de progresso da SGCI no refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o em toda a \u00c1frica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NRF destaca dez anos de progresso da SGCI na gest\u00e3o de investiga\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"A NRF da \u00c1frica do Sul assinala dez anos de progresso da SGCI no refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o em toda a \u00c1frica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T15:12:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-13T13:31:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davis Weddi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davis Weddi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/\"},\"author\":{\"name\":\"Davis Weddi\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\"},\"headline\":\"NRF destaca dez anos de progresso da SGCI na gest\u00e3o de investiga\u00e7\u00e3o\",\"datePublished\":\"2025-05-15T15:12:45+00:00\",\"dateModified\":\"2026-02-13T13:31:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/\"},\"wordCount\":670,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/nrf-pic_MAIN.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/\",\"name\":\"NRF assinala dez anos de progresso da SGCI no refor\u00e7o de capacidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/nrf-pic_MAIN.jpg\",\"datePublished\":\"2025-05-15T15:12:45+00:00\",\"dateModified\":\"2026-02-13T13:31:10+00:00\",\"description\":\"A NRF da \u00c1frica do Sul assinala dez anos de progresso da SGCI no refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o em toda a \u00c1frica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/nrf-pic_MAIN.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/nrf-pic_MAIN.jpg\",\"width\":996,\"height\":567,\"caption\":\"NRF - Em abril de 2025, a Science Granting Councils Initiative (SGCI) na \u00c1frica Subsariana assinalou dez anos de refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NRF destaca dez anos de progresso da SGCI na gest\u00e3o de investiga\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\",\"name\":\"Davis Weddi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"caption\":\"Davis Weddi\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/author\\\/davisweddi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NRF assinala dez anos de progresso da SGCI no refor\u00e7o de capacidades","description":"A NRF da \u00c1frica do Sul assinala dez anos de progresso da SGCI no refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o em toda a \u00c1frica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/","og_locale":"pt_BR","og_type":"article","og_title":"NRF destaca dez anos de progresso da SGCI na gest\u00e3o de investiga\u00e7\u00e3o","og_description":"A NRF da \u00c1frica do Sul assinala dez anos de progresso da SGCI no refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o em toda a \u00c1frica.","og_url":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/","og_site_name":"SGCI Africa","article_published_time":"2025-05-15T15:12:45+00:00","article_modified_time":"2026-02-13T13:31:10+00:00","og_image":[{"width":996,"height":567,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg","type":"image\/jpeg"}],"author":"Davis Weddi","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"Escrito por":"Davis Weddi","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/"},"author":{"name":"Davis Weddi","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92"},"headline":"NRF destaca dez anos de progresso da SGCI na gest\u00e3o de investiga\u00e7\u00e3o","datePublished":"2025-05-15T15:12:45+00:00","dateModified":"2026-02-13T13:31:10+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/"},"wordCount":670,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/","url":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/","name":"NRF assinala dez anos de progresso da SGCI no refor\u00e7o de capacidades","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg","datePublished":"2025-05-15T15:12:45+00:00","dateModified":"2026-02-13T13:31:10+00:00","description":"A NRF da \u00c1frica do Sul assinala dez anos de progresso da SGCI no refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o em toda a \u00c1frica.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg","width":996,"height":567,"caption":"NRF - Em abril de 2025, a Science Granting Councils Initiative (SGCI) na \u00c1frica Subsariana assinalou dez anos de refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o."},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/pt\/a-nrf-destaca-dez-anos-de-progressos-do-sgci-na-gestao-da-investigacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/pt\/"},{"@type":"ListItem","position":2,"name":"NRF destaca dez anos de progresso da SGCI na gest\u00e3o de investiga\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92","name":"Davis Weddi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","caption":"Davis Weddi"},"url":"https:\/\/sgciafrica.org\/pt\/author\/davisweddi\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg",996,567,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN-300x171.jpg",300,171,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN-768x437.jpg",768,437,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg",996,567,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg",996,567,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg",996,567,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg",996,567,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg",996,567,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg",996,567,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN.jpg",996,567,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/05\/nrf-pic_MAIN-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Davis Weddi","author_link":"https:\/\/sgciafrica.org\/pt\/author\/davisweddi\/"},"uagb_comment_info":0,"uagb_excerpt":"Em abril de 2025, a Iniciativa dos Conselhos de Concess\u00e3o de Bolsas de Investiga\u00e7\u00e3o Cient\u00edfica (SGCI) na \u00c1frica Subsariana assinalou dez anos de refor\u00e7o da capacidade dos financiadores p\u00fablicos nacionais de investiga\u00e7\u00e3o. Desde a sua cria\u00e7\u00e3o, a SGCI tem trabalhado em 17 pa\u00edses para fortalecer os sistemas de ci\u00eancia, tecnologia e inova\u00e7\u00e3o (CTI), atrav\u00e9s de&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/23590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/comments?post=23590"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/23590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media\/23381"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media?parent=23590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/categories?post=23590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/tags?post=23590"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/country?post=23590"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/objective?post=23590"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/sg_theme?post=23590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}