{"id":23578,"date":"2025-03-28T16:33:09","date_gmt":"2025-03-28T16:33:09","guid":{"rendered":"https:\/\/sgciafrica.org\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/"},"modified":"2026-02-12T15:53:29","modified_gmt":"2026-02-12T15:53:29","slug":"projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/","title":{"rendered":"Projeto alimentar namibiano visa culturas ricas em prote\u00edna"},"content":{"rendered":"\n<p>[NAM\u00cdBIA] A falta de prote\u00edna \u00e9 um dos principais fatores que contribuem para a <a href=\"https:\/\/www.scidev.net\/global\/health\/nutrition\/\">subnutri\u00e7\u00e3o<\/a> em pa\u00edses de baixo e m\u00e9dio rendimento, onde a alimenta\u00e7\u00e3o de muitas pessoas depende fortemente de culturas b\u00e1sicas.<\/p>\n\n<p>Para enfrentar este problema na Nam\u00edbia, investigadores iniciaram um projeto de alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o para formar agricultores na utiliza\u00e7\u00e3o de um biofertilizante para produzir leguminosas enriquecidas em prote\u00edna.<\/p>\n\n<p>O projeto, liderado por investigadores da <a href=\"https:\/\/www.nust.na\/\">Namibia University of Science and Technology<\/a>, apresenta a pequenos <a href=\"https:\/\/www.scidev.net\/global\/agriculture\/farming\/\">agricultores<\/a> da comunidade de Mayana, na regi\u00e3o de Kavango East, t\u00e9cnicas de <a href=\"https:\/\/www.scidev.net\/global\/enterprise\/biotechnology\/\">biotecnologia<\/a>, com o objetivo de responder a desafios cr\u00edticos na produtividade agr\u00edcola e na nutri\u00e7\u00e3o.<\/p>\n\n<p>Natilia Rengi, agricultora da comunidade, em tempos teve dificuldades em produzir alimentos suficientes para a sua fam\u00edlia de 12 pessoas, mas viu as colheitas aumentarem desde que adotou o biofertilizante.<\/p>\n\n<p>\u201cN\u00e3o costum\u00e1vamos cultivar tanto\u201d, afirma.<\/p>\n\n<p>\u201c[Mas] posso dizer com orgulho que agora colhemos o suficiente para alimentar a nossa fam\u00edlia.\u201d<\/p>\n\n<p>Para Rengi, o projeto significa a diferen\u00e7a entre lutar para sustentar a sua grande fam\u00edlia e conseguir aliment\u00e1-la com refei\u00e7\u00f5es nutritivas.<\/p>\n\n<p>A sua hist\u00f3ria \u00e9 uma entre muitas na regi\u00e3o, onde os agricultores est\u00e3o a registar melhorias na produ\u00e7\u00e3o alimentar e nos seus meios de subsist\u00eancia gra\u00e7as a esta iniciativa, financiada pela <a href=\"https:\/\/sgciafrica.org\/pt\/\">Science Granting Councils Initiative<\/a>.<\/p>\n\n<p>Segundo Oswald Mughongora, respons\u00e1vel s\u00e9nior de programa para a gest\u00e3o de subven\u00e7\u00f5es na Comiss\u00e3o Nacional de Investiga\u00e7\u00e3o, Ci\u00eancia e Tecnologia da Nam\u00edbia, o programa est\u00e1 alinhado com os objetivos mais amplos do pa\u00eds em mat\u00e9ria de agricultura inteligente face ao clima e integra\u00e7\u00e3o de conhecimentos ind\u00edgenas.<\/p>\n\n<p>O projeto, denominado Food Security and Nutrition Improvement through Protein-Rich Legume and Low-Cost Biotechnology in Namibia (FOODSECBIO), come\u00e7ou em 2021 e est\u00e1 previsto ser conclu\u00eddo at\u00e9 julho de 2025.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-five-biofertilisers\"><strong>Cinco biofertilizantes<\/strong><\/h2>\n\n<p>\u201cUm dos principais resultados desta iniciativa \u00e9 o desenvolvimento de um biofertilizante produzido localmente\u201d, afirma Mughongora.<\/p>\n\n<p>Segundo ele, o projeto ajuda a responder a quest\u00f5es de fertilidade do solo, bem como a preocupa\u00e7\u00f5es relacionadas com a subnutri\u00e7\u00e3o e a <a href=\"https:\/\/www.scidev.net\/global\/agriculture\/food-security\/\">seguran\u00e7a alimentar<\/a> na Nam\u00edbia.<\/p>\n\n<p>Percy Chimwamurombe, investigador principal do projeto na Namibia University of Science and Technology, refere que a sua equipa desenvolveu cinco biofertilizantes. Come\u00e7aram por identificar as bact\u00e9rias mais adequadas para promover o crescimento. <\/p>\n\n<p>Os investigadores isolaram bact\u00e9rias do ambiente do solo de plantas leguminosas e selecionaram, em laborat\u00f3rio, as bact\u00e9rias com caracter\u00edsticas promotoras do crescimento das plantas.<\/p>\n\n<p>\u201cInteress\u00e1vamo-nos sobretudo pela sua capacidade de fixa\u00e7\u00e3o de azoto\u201d, afirma Chimwamurombe.<\/p>\n\n<p>Cerca de 30 agricultores j\u00e1 receberam forma\u00e7\u00e3o sobre como utilizar os biofertilizantes. Os agricultores tamb\u00e9m foram formados em m\u00e9todos de produ\u00e7\u00e3o para feij\u00e3o-frade, milho-pain\u00e7o e feij\u00e3o bambara, todos ricos em prote\u00edna, e sobre como produzir farinhas de milho-pain\u00e7o enriquecidas em prote\u00edna para alimentar beb\u00e9s. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-effective-farming\"><strong>Agricultura eficaz<\/strong><\/h2>\n\n<p>Sofia Kamburu, agricultora de 34 anos, afirma que alargou as suas culturas para incluir feij\u00e3o, milho-pain\u00e7o, amendoim e feij\u00e3o bambara.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"393\" height=\"700\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/March28Outcome_of_the_fields_after_the_biofertilser_test_BODY.jpg\" alt=\"\" class=\"wp-image-22897\" srcset=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/March28Outcome_of_the_fields_after_the_biofertilser_test_BODY.jpg 393w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/March28Outcome_of_the_fields_after_the_biofertilser_test_BODY-168x300.jpg 168w\" sizes=\"auto, (max-width: 393px) 100vw, 393px\" \/><figcaption class=\"wp-element-caption\"><em>Resultado dos campos ap\u00f3s o teste do biofertilizante.<\/em><\/figcaption><\/figure>\n<\/div>\n<p>\u201cAprendemos a planear e quando plantar, consoante as diferentes esta\u00e7\u00f5es\u201d, afirma.<\/p>\n\n<p>\u201cNo passado, depend\u00edamos de boas chuvas em novembro e dezembro; no entanto, este ano prepar\u00e1mos os nossos campos antes da \u00e9poca das chuvas, aguardando as chuvas em janeiro para uma melhor germina\u00e7\u00e3o.\u201d<\/p>\n\n<p>A ado\u00e7\u00e3o de biofertilizantes e de t\u00e9cnicas melhoradas de prepara\u00e7\u00e3o do solo refor\u00e7ou os seus conhecimentos agr\u00edcolas, acrescenta.<\/p>\n\n<p>Alta Ngoma, 30 anos, esteve desempregada durante tr\u00eas anos quando aprendeu novas compet\u00eancias de colheita atrav\u00e9s do projeto. Espera agora vir a cultivar o seu pr\u00f3prio campo no futuro. <\/p>\n\n<p>\u201cEste projeto mudou completamente a minha vida\u201d, afirma Ngoma.<\/p>\n\n<p>\u201cAntes, n\u00e3o tinha rendimento nem experi\u00eancia. Muitas vezes t\u00ednhamos dificuldade em comprar fuba de milho, que custava cerca de 150 d\u00f3lares namibianos [US$8,3] por um saco de dez quilos. <\/p>\n\n<p>Desde outubro, Ngoma tem vindo a obter um rendimento, o que lhe permite pagar as propinas escolares do seu filho.<\/p>\n\n<p>Outra agricultora, Apolionia Kavahu, afirma: \u201cAprendemos a cultivar de forma eficaz. Cheguei a duvidar que algu\u00e9m pudesse ganhar a vida com a agricultura, mas agora tamb\u00e9m podemos ensinar os nossos filhos a faz\u00ea-lo melhor no futuro.\u201d<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-child-malnutrition\"><strong>Subnutri\u00e7\u00e3o infantil<\/strong><\/h2>\n\n<p>Chimwamurombe acredita que o projeto FOODSECBIO poder\u00e1 desempenhar um papel importante ao disponibilizar alternativas nutricionais para combater a subnutri\u00e7\u00e3o infantil no pa\u00eds.<\/p>\n\n<p>Est\u00e1 confiante de que a defici\u00eancia de prote\u00edna \u00e9 um problema que este projeto pode superar, se todas as partes interessadas se unirem em torno da quest\u00e3o.<\/p>\n\n<p>A primeira doutorada da Nam\u00edbia em melhoramento de plantas, Lydia Horn, sublinha que a disponibilidade de sementes \u00e9 importante para promover a seguran\u00e7a alimentar e combater a fome.<\/p>\n\n<p>Afirma: \u201cPodem ser criados empregos e a seguran\u00e7a alimentar pode ser melhorada disponibilizando sementes a um pre\u00e7o baixo, para que todos possam cultivar os seus alimentos.\u201d<\/p>\n\n<p><em>Este artigo foi escrito por Charlotte Nambadja<\/em>.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[NAM\u00cdBIA] A falta de prote\u00edna \u00e9 um dos principais fatores que contribuem para a subnutri\u00e7\u00e3o em pa\u00edses de baixo e m\u00e9dio rendimento, onde a alimenta\u00e7\u00e3o de muitas pessoas depende fortemente de culturas b\u00e1sicas. Para enfrentar este problema na Nam\u00edbia, investigadores iniciaram um projeto de alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o para formar agricultores na utiliza\u00e7\u00e3o de um biofertilizante&hellip;<\/p>\n","protected":false},"author":13,"featured_media":22902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[159],"tags":[],"country":[],"objective":[],"sg_theme":[],"class_list":["post-23578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Projeto alimentar namibiano visa culturas ricas em prote\u00edna - SGCI Africa<\/title>\n<meta name=\"description\" content=\"Investigadores namibianos lan\u00e7am um projeto de alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o que forma agricultores na utiliza\u00e7\u00e3o de um biofertilizante para leguminosas ricas em prote\u00edna.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto alimentar namibiano visa culturas ricas em prote\u00edna\" \/>\n<meta property=\"og:description\" content=\"Investigadores namibianos lan\u00e7am um projeto de alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o que forma agricultores na utiliza\u00e7\u00e3o de um biofertilizante para leguminosas ricas em prote\u00edna.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-28T16:33:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T15:53:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davis Weddi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davis Weddi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/\"},\"author\":{\"name\":\"Davis Weddi\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\"},\"headline\":\"Projeto alimentar namibiano visa culturas ricas em prote\u00edna\",\"datePublished\":\"2025-03-28T16:33:09+00:00\",\"dateModified\":\"2026-02-12T15:53:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/\"},\"wordCount\":866,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/beans-legume-food-proteins-MAIN.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/\",\"name\":\"Projeto alimentar namibiano visa culturas ricas em prote\u00edna - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/beans-legume-food-proteins-MAIN.jpg\",\"datePublished\":\"2025-03-28T16:33:09+00:00\",\"dateModified\":\"2026-02-12T15:53:29+00:00\",\"description\":\"Investigadores namibianos lan\u00e7am um projeto de alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o que forma agricultores na utiliza\u00e7\u00e3o de um biofertilizante para leguminosas ricas em prote\u00edna.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/beans-legume-food-proteins-MAIN.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/beans-legume-food-proteins-MAIN.jpg\",\"width\":996,\"height\":567,\"caption\":\"Feij\u00f5es variados. Os investigadores afirmam que a utiliza\u00e7\u00e3o de biofertilizantes e de melhores t\u00e9cnicas para produzir leguminosas enriquecidas em prote\u00edna, como o feij\u00e3o, melhora as colheitas e os meios de subsist\u00eancia e pode ajudar a combater a subnutri\u00e7\u00e3o infantil. Copyright: Georgina Smith \\\/ CIAT (CC BY-NC-SA 2.0)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projeto alimentar namibiano visa culturas ricas em prote\u00edna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\",\"name\":\"Davis Weddi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"caption\":\"Davis Weddi\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/author\\\/davisweddi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Projeto alimentar namibiano visa culturas ricas em prote\u00edna - SGCI Africa","description":"Investigadores namibianos lan\u00e7am um projeto de alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o que forma agricultores na utiliza\u00e7\u00e3o de um biofertilizante para leguminosas ricas em prote\u00edna.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto alimentar namibiano visa culturas ricas em prote\u00edna","og_description":"Investigadores namibianos lan\u00e7am um projeto de alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o que forma agricultores na utiliza\u00e7\u00e3o de um biofertilizante para leguminosas ricas em prote\u00edna.","og_url":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/","og_site_name":"SGCI Africa","article_published_time":"2025-03-28T16:33:09+00:00","article_modified_time":"2026-02-12T15:53:29+00:00","og_image":[{"width":996,"height":567,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg","type":"image\/jpeg"}],"author":"Davis Weddi","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"Escrito por":"Davis Weddi","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/"},"author":{"name":"Davis Weddi","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92"},"headline":"Projeto alimentar namibiano visa culturas ricas em prote\u00edna","datePublished":"2025-03-28T16:33:09+00:00","dateModified":"2026-02-12T15:53:29+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/"},"wordCount":866,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/","url":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/","name":"Projeto alimentar namibiano visa culturas ricas em prote\u00edna - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg","datePublished":"2025-03-28T16:33:09+00:00","dateModified":"2026-02-12T15:53:29+00:00","description":"Investigadores namibianos lan\u00e7am um projeto de alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o que forma agricultores na utiliza\u00e7\u00e3o de um biofertilizante para leguminosas ricas em prote\u00edna.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg","width":996,"height":567,"caption":"Feij\u00f5es variados. Os investigadores afirmam que a utiliza\u00e7\u00e3o de biofertilizantes e de melhores t\u00e9cnicas para produzir leguminosas enriquecidas em prote\u00edna, como o feij\u00e3o, melhora as colheitas e os meios de subsist\u00eancia e pode ajudar a combater a subnutri\u00e7\u00e3o infantil. Copyright: Georgina Smith \/ CIAT (CC BY-NC-SA 2.0)"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/pt\/projeto-alimentar-namibiano-visa-culturas-ricas-em-proteinas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Projeto alimentar namibiano visa culturas ricas em prote\u00edna"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92","name":"Davis Weddi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","caption":"Davis Weddi"},"url":"https:\/\/sgciafrica.org\/pt\/author\/davisweddi\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg",996,567,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN-300x171.jpg",300,171,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN-768x437.jpg",768,437,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg",996,567,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg",996,567,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg",996,567,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg",996,567,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg",996,567,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg",996,567,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN.jpg",996,567,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/03\/beans-legume-food-proteins-MAIN-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Davis Weddi","author_link":"https:\/\/sgciafrica.org\/pt\/author\/davisweddi\/"},"uagb_comment_info":0,"uagb_excerpt":"[NAM\u00cdBIA] A falta de prote\u00edna \u00e9 um dos principais fatores que contribuem para a subnutri\u00e7\u00e3o em pa\u00edses de baixo e m\u00e9dio rendimento, onde a alimenta\u00e7\u00e3o de muitas pessoas depende fortemente de culturas b\u00e1sicas. Para enfrentar este problema na Nam\u00edbia, investigadores iniciaram um projeto de alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o para formar agricultores na utiliza\u00e7\u00e3o de um biofertilizante&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/23578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/comments?post=23578"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/23578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media\/22902"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media?parent=23578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/categories?post=23578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/tags?post=23578"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/country?post=23578"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/objective?post=23578"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/sg_theme?post=23578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}