{"id":21404,"date":"2024-05-01T12:44:27","date_gmt":"2024-05-01T11:44:27","guid":{"rendered":"https:\/\/sgciafrica.org\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/"},"modified":"2024-07-26T18:08:35","modified_gmt":"2024-07-26T17:08:35","slug":"investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/","title":{"rendered":"Investigadores estabelecem parceria com o sector privado no Malawi"},"content":{"rendered":"\n<p>As colabora\u00e7\u00f5es com as empresas e o governo ajudam os investigadores do Malawi a resolver &#8220;problemas do mundo real&#8221;.<\/p>\n\n<ul class=\"wp-block-list\"><\/ul>\n\n<ul class=\"wp-block-list\">\n<li>Parcerias da SGCI com o sector privado e o governo para apoiar a investiga\u00e7\u00e3o no Malawi<\/li>\n\n\n\n<li>O &#8220;modelo da h\u00e9lice tripla&#8221; utilizado para resolver os problemas das empresas<\/li>\n\n\n\n<li>\u00c9 necess\u00e1rio mais financiamento para a intelig\u00eancia artificial centrada em \u00c1frica<\/li>\n<\/ul>\n\n<p><strong>Por: Michael Kaloki<\/strong><\/p>\n\n<p>A Iniciativa dos Conselhos de Concess\u00e3o de Apoio Cient\u00edfico est\u00e1 a utilizar a chamada &#8220;abordagem da h\u00e9lice tripla&#8221; para permitir que os investigadores africanos colaborem com os seus governos, o sector privado e outros cientistas, para fazer avan\u00e7ar a ci\u00eancia e ultrapassar os desafios do financiamento.  <\/p>\n\n<p>Gift Kadzamira, diretor-geral da Comiss\u00e3o Nacional para a Ci\u00eancia e Tecnologia do Malawi, membro do conselho da SGCI, afirma que a colabora\u00e7\u00e3o permite aos investigadores africanos resolver desafios que s\u00e3o \u00fanicos no continente.<\/p>\n\n<p>&#8220;O sistema de h\u00e9lice tripla refere-se \u00e0s interac\u00e7\u00f5es entre a academia, o sector privado e o governo&#8221;, explicou Kadzamira.\n&#8220;O modelo, adotado em v\u00e1rios pa\u00edses, visa fazer avan\u00e7ar a investiga\u00e7\u00e3o e promover o crescimento da inova\u00e7\u00e3o.&#8221; <\/p>\n\n<p>Segundo a Comiss\u00e1ria, este modelo permite \u00e0s universidades &#8220;resolver problemas de investiga\u00e7\u00e3o que o sector privado enfrenta&#8221;, em parceria com outros.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/www.flickr.com\/photos\/icrisat\/10265502014\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/05\/Malawi_Peanuts-1-1024x683.jpg\" alt=\"\" class=\"wp-image-6405\" style=\"width:960px;height:auto\" srcset=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/05\/Malawi_Peanuts-1-1024x683.jpg 1024w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/05\/Malawi_Peanuts-1-300x200.jpg 300w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/05\/Malawi_Peanuts-1-768x512.jpg 768w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/05\/Malawi_Peanuts-1-1536x1024.jpg 1536w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/05\/Malawi_Peanuts-1-1920x1280.jpg 1920w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/05\/Malawi_Peanuts-1-1696x1130.jpg 1696w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/05\/Malawi_Peanuts-1-1352x901.jpg 1352w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/05\/Malawi_Peanuts-1.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Mulheres agricultoras com uma variedade melhorada de amendoins no Malawi.\nDe acordo com Gift Kadzamira, diretor-geral da Comiss\u00e3o Nacional para a Ci\u00eancia e Tecnologia do Malawi, a colabora\u00e7\u00e3o na investiga\u00e7\u00e3o consiste em encontrar solu\u00e7\u00f5es inovadoras e aplica\u00e7\u00f5es pr\u00e1ticas.\nCr\u00e9dito da fotografia: A Diama\/ ICRISAT<a href=\"https:\/\/creativecommons.org\/licenses\/by-nc\/2.0\/\">(CC BY-NC 2.0 DEED<\/a>)  <\/figcaption><\/figure>\n\n<p>O SGCI \u00e9 uma iniciativa multilateral criada em 2015 para aumentar as capacidades institucionais de 16 conselhos p\u00fablicos de financiamento cient\u00edfico na \u00c1frica Subsariana.\nO seu objetivo \u00e9 apoiar a investiga\u00e7\u00e3o e as pol\u00edticas baseadas em provas que contribuam para o desenvolvimento econ\u00f3mico e social. <\/p>\n\n<p>&#8220;A beleza da SGCI \u00e9 que nos permite colaborar em projectos de investiga\u00e7\u00e3o, partilhar recursos e desenvolver capacidades&#8221;, acrescentou Kadzamira. &#8220;N\u00e3o estamos a trabalhar isoladamente; estamos a trabalhar em conjunto para enfrentar os desafios que o nosso continente enfrenta.&#8221;<\/p>\n\n<p><strong>Solu\u00e7\u00f5es inovadoras<\/strong><strong><\/strong><\/p>\n\n<p>O objetivo destas colabora\u00e7\u00f5es \u00e9 encontrar solu\u00e7\u00f5es inovadoras e aplica\u00e7\u00f5es pr\u00e1ticas, disse Kadzamira.<\/p>\n\n<p>&#8220;Estamos a garantir que o sector privado \u00e9 parte integrante do processo de investiga\u00e7\u00e3o, para que as universidades possam resolver problemas do mundo real&#8221;, explicou.<\/p>\n\n<p>&#8220;A ci\u00eancia, a tecnologia e a inova\u00e7\u00e3o s\u00e3o globais. \u00c9 por isso que as parcerias com institui\u00e7\u00f5es como a SGCI s\u00e3o essenciais.&#8221;<\/p>\n\n<p>Agora, quer ver mais apoio \u00e0 investiga\u00e7\u00e3o em intelig\u00eancia artificial (IA), adaptada \u00e0s necessidades africanas.<\/p>\n\n<p>&#8220;N\u00e3o nos podemos dar ao luxo de ficar para tr\u00e1s&#8221;, afirmou.<\/p>\n\n<p>A Comiss\u00e3o Nacional para a Ci\u00eancia e a Tecnologia do Malawi estabelece uma parceria com a SGCI para apoiar a investiga\u00e7\u00e3o e as pol\u00edticas baseadas em dados concretos que contribuem para o desenvolvimento econ\u00f3mico e social.<\/p>\n\n<p>Kadzamira sublinhou a necessidade de inclus\u00e3o do g\u00e9nero na investiga\u00e7\u00e3o, citando os esfor\u00e7os da SGCI para apoiar a igualdade de g\u00e9nero e encomendar investiga\u00e7\u00e3o sobre temas relacionados com o g\u00e9nero.<\/p>\n\n<p>&#8220;Temos de garantir que a nossa investiga\u00e7\u00e3o \u00e9 inclusiva, que tem em conta as necessidades e as perspectivas de todos, incluindo as mulheres e as comunidades marginalizadas&#8221;, afirmou.<\/p>\n\n<p>&#8220;Atrav\u00e9s deste tema, a SGCI pretende apoiar sess\u00f5es de di\u00e1logo sobre igualdade e inclus\u00e3o de g\u00e9nero, bem como encomendar investiga\u00e7\u00e3o sobre temas relacionados com o g\u00e9nero, tais como o estatuto das mulheres enquanto cientistas e a explora\u00e7\u00e3o das barreiras que enfrentam&#8221;.<\/p>\n\n<p><strong>Financiamento da investiga\u00e7\u00e3o<\/strong><\/p>\n\n<p>No Malawi, a iniciativa de financiamento da investiga\u00e7\u00e3o da SGCI apoiou a investiga\u00e7\u00e3o sobre a efic\u00e1cia do etanol como combust\u00edvel alternativo para ve\u00edculos.\nO resultado foi a aprova\u00e7\u00e3o pelo governo do Malawi de uma s\u00e9rie de recomenda\u00e7\u00f5es feitas pelos investigadores, segundo Kadzamira. <\/p>\n\n<p>Para al\u00e9m de conceder bolsas de investiga\u00e7\u00e3o, o SGCI tamb\u00e9m oferece refor\u00e7o de capacidades, como forma\u00e7\u00e3o, aprendizagem entre pares e apoio t\u00e9cnico.  <\/p>\n\n<p>&#8220;Conseguimos obter colabora\u00e7\u00e3o na investiga\u00e7\u00e3o interdisciplinar, por exemplo, analisando quest\u00f5es relacionadas com as altera\u00e7\u00f5es clim\u00e1ticas e a sa\u00fade&#8221;, disse Kadzamira.<\/p>\n\n<p>&#8220;Se investig\u00e1ssemos sozinhos, n\u00e3o ter\u00edamos conseguido obter a qualidade dos resultados de investiga\u00e7\u00e3o que pretend\u00edamos&#8221;.<\/p>\n\n<p>Kadzamira disse que um impacto significativo do financiamento da investiga\u00e7\u00e3o da SGCI tem sido o aumento da visibilidade dos investigadores, n\u00e3o s\u00f3 no Malawi mas em todo o mundo.\n&#8220;A investiga\u00e7\u00e3o em colabora\u00e7\u00e3o que tem vindo a ser realizada permitiu que as na\u00e7\u00f5es do Ocidente reconhecessem que existem investigadores de qualidade em \u00c1frica que podem fazer um trabalho de qualidade&#8221;, acrescentou Kadzamira. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>As colabora\u00e7\u00f5es com as empresas e o governo ajudam os investigadores do Malawi a resolver &#8220;problemas do mundo real&#8221;. Por: Michael Kaloki A Iniciativa dos Conselhos de Concess\u00e3o de Apoio Cient\u00edfico est\u00e1 a utilizar a chamada &#8220;abordagem da h\u00e9lice tripla&#8221; para permitir que os investigadores africanos colaborem com os seus governos, o sector privado e&hellip;<\/p>\n","protected":false},"author":13,"featured_media":20952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[159],"tags":[231,214,215],"country":[],"objective":[],"sg_theme":[],"class_list":["post-21404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-gerenciamento-de-pesquisa","tag-ingles","tag-parcerias-publico-privadas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Investigadores estabelecem parceria com o sector privado no Malawi - SGCI Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investigadores estabelecem parceria com o sector privado no Malawi\" \/>\n<meta property=\"og:description\" content=\"As colabora\u00e7\u00f5es com as empresas e o governo ajudam os investigadores do Malawi a resolver &#8220;problemas do mundo real&#8221;. Por: Michael Kaloki A Iniciativa dos Conselhos de Concess\u00e3o de Apoio Cient\u00edfico est\u00e1 a utilizar a chamada &#8220;abordagem da h\u00e9lice tripla&#8221; para permitir que os investigadores africanos colaborem com os seus governos, o sector privado e&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T11:44:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-26T17:08:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davis Weddi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davis Weddi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/\"},\"author\":{\"name\":\"Davis Weddi\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\"},\"headline\":\"Investigadores estabelecem parceria com o sector privado no Malawi\",\"datePublished\":\"2024-05-01T11:44:27+00:00\",\"dateModified\":\"2024-07-26T17:08:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/\"},\"wordCount\":818,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Selon-Gift-Kadzamira.jpg\",\"keywords\":[\"gerenciamento de pesquisa\",\"Ingl\u00eas\",\"Parcerias p\u00fablico-privadas\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/\",\"name\":\"Investigadores estabelecem parceria com o sector privado no Malawi - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Selon-Gift-Kadzamira.jpg\",\"datePublished\":\"2024-05-01T11:44:27+00:00\",\"dateModified\":\"2024-07-26T17:08:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Selon-Gift-Kadzamira.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Selon-Gift-Kadzamira.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investigadores estabelecem parceria com o sector privado no Malawi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\",\"name\":\"Davis Weddi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"caption\":\"Davis Weddi\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/author\\\/davisweddi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Investigadores estabelecem parceria com o sector privado no Malawi - SGCI Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/","og_locale":"pt_BR","og_type":"article","og_title":"Investigadores estabelecem parceria com o sector privado no Malawi","og_description":"As colabora\u00e7\u00f5es com as empresas e o governo ajudam os investigadores do Malawi a resolver &#8220;problemas do mundo real&#8221;. Por: Michael Kaloki A Iniciativa dos Conselhos de Concess\u00e3o de Apoio Cient\u00edfico est\u00e1 a utilizar a chamada &#8220;abordagem da h\u00e9lice tripla&#8221; para permitir que os investigadores africanos colaborem com os seus governos, o sector privado e&hellip;","og_url":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/","og_site_name":"SGCI Africa","article_published_time":"2024-05-01T11:44:27+00:00","article_modified_time":"2024-07-26T17:08:35+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg","type":"image\/jpeg"}],"author":"Davis Weddi","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"Escrito por":"Davis Weddi","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/"},"author":{"name":"Davis Weddi","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92"},"headline":"Investigadores estabelecem parceria com o sector privado no Malawi","datePublished":"2024-05-01T11:44:27+00:00","dateModified":"2024-07-26T17:08:35+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/"},"wordCount":818,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg","keywords":["gerenciamento de pesquisa","Ingl\u00eas","Parcerias p\u00fablico-privadas"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/","url":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/","name":"Investigadores estabelecem parceria com o sector privado no Malawi - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg","datePublished":"2024-05-01T11:44:27+00:00","dateModified":"2024-07-26T17:08:35+00:00","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/pt\/investigadores-estabelecem-parceria-com-o-sector-privado-no-malawi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Investigadores estabelecem parceria com o sector privado no Malawi"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92","name":"Davis Weddi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","caption":"Davis Weddi"},"url":"https:\/\/sgciafrica.org\/pt\/author\/davisweddi\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg",1024,683,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira-300x200.jpg",300,200,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira-768x512.jpg",768,512,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg",1024,683,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg",1024,683,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg",1024,683,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg",1024,683,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg",1024,683,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg",1024,683,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira.jpg",1024,683,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/07\/Selon-Gift-Kadzamira-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Davis Weddi","author_link":"https:\/\/sgciafrica.org\/pt\/author\/davisweddi\/"},"uagb_comment_info":0,"uagb_excerpt":"As colabora\u00e7\u00f5es com as empresas e o governo ajudam os investigadores do Malawi a resolver &#8220;problemas do mundo real&#8221;. Por: Michael Kaloki A Iniciativa dos Conselhos de Concess\u00e3o de Apoio Cient\u00edfico est\u00e1 a utilizar a chamada &#8220;abordagem da h\u00e9lice tripla&#8221; para permitir que os investigadores africanos colaborem com os seus governos, o sector privado e&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/21404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/comments?post=21404"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/21404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media\/20952"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media?parent=21404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/categories?post=21404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/tags?post=21404"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/country?post=21404"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/objective?post=21404"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/sg_theme?post=21404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}