{"id":18126,"date":"2023-07-20T14:14:00","date_gmt":"2023-07-20T13:14:00","guid":{"rendered":"https:\/\/sgciafrica.org\/?p=18126"},"modified":"2026-02-11T14:00:07","modified_gmt":"2026-02-11T14:00:07","slug":"acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/","title":{"rendered":"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica"},"content":{"rendered":"\n<p><strong>S\u00e3o necess\u00e1rios mais esfor\u00e7os para combater as desigualdades de tratamento que persistem entre homens e mulheres, apesar dos progressos alcan\u00e7ados nos \u00faltimos anos.<\/strong><\/p>\n\n<p>No seu Relat\u00f3rio Nacional de Perspetivas da Investiga\u00e7\u00e3o de 2022, o Conselho Nacional para a Ci\u00eancia e Tecnologia do Uganda (UNCST) destaca que a propor\u00e7\u00e3o de mulheres nas institui\u00e7\u00f5es de investiga\u00e7\u00e3o e de ensino superior do pa\u00eds aumentou ao longo dos \u00faltimos 15 anos.<\/p>\n\n<p>No entanto, o mesmo documento refere que apenas 28% dos investigadores ugandeses s\u00e3o mulheres. Uma percentagem que tende a ser ainda mais baixa em \u00e1reas tradicionalmente dominadas por homens, como a engenharia e a tecnologia. <\/p>\n\n<p>Al\u00e9m disso, soubemos que, entre 2010 e 2020, menos de um quarto (24%) dos doutorados no Uganda eram mulheres.<\/p>\n\n<p>Estes n\u00fameros evidenciam o problema da desigualdade de g\u00e9nero que prevalece na investiga\u00e7\u00e3o cient\u00edfica em \u00c1frica.<\/p>\n\n<p>Um tema que se encontra entre as principais \u00e1reas de interesse da SGCI (Science Granting Councils Initiative), um programa implementado na \u00c1frica Ocidental, na \u00c1frica Oriental e na \u00c1frica Austral para refor\u00e7ar a capacidade dos organismos financiadores de investiga\u00e7\u00e3o.<\/p>\n\n<p>Com o apoio do International Development Research Center (IDRC) e de outras cinco organiza\u00e7\u00f5es<a href=\"#_ftn1\" id=\"_ftnref1\">[1]<\/a>, a SGCI visa apoiar a investiga\u00e7\u00e3o e as pol\u00edticas baseadas em evid\u00eancia que contribuir\u00e3o para o desenvolvimento econ\u00f3mico e social.<\/p>\n\n<p>Diakalia Sanogo, Especialista S\u00e9nior de Programa do Escrit\u00f3rio Regional do IDRC para a \u00c1frica Ocidental e Central, sediado em Dakar, Senegal, tem uma ideia clara sobre o motivo pelo qual a desigualdade de g\u00e9nero persiste.<\/p>\n\n<p>De facto, defende que a falta de legisla\u00e7\u00e3o adequada e a fraca implementa\u00e7\u00e3o de pol\u00edticas de financiamento da ci\u00eancia e da investiga\u00e7\u00e3o constitu\u00edram entraves \u00e0 concretiza\u00e7\u00e3o da igualdade de g\u00e9nero e da inclus\u00e3o.<\/p>\n\n<p>\u201cTem sido feito muito para tornar a igualdade de g\u00e9nero e a inclus\u00e3o uma prioridade transversal, especialmente na ci\u00eancia, tecnologia e inova\u00e7\u00e3o, mas a transforma\u00e7\u00e3o de g\u00e9nero precisa de solu\u00e7\u00f5es reais\u201d, afirma o investigador.<\/p>\n\n<p>Diakalia Sanogo refere, de passagem, que estas desigualdades se manifestam \u201cem disparidades salariais, no comportamento humano; \u00e9 por isso que dizemos que \u00e9 importante eliminar os comportamentos negativos, sensibilizando atrav\u00e9s do di\u00e1logo\u201d.<\/p>\n\n<p>Ingrid Lynch, Investigadora Principal do Projeto de Igualdade de G\u00e9nero e Inclus\u00e3o da SGCI, considera que as manifesta\u00e7\u00f5es desta desigualdade s\u00e3o observadas bastante cedo no sistema educativo. Segundo as suas explica\u00e7\u00f5es, um dos primeiros pontos em que as raparigas se perdem no sistema educativo \u00e9 ao n\u00edvel do ensino prim\u00e1rio. <\/p>\n\n<p>\u201cTemos muitas respostas pol\u00edticas a tentar abordar esta parte da fuga na progress\u00e3o\u201d, afirma Ingrid Lynch, que tamb\u00e9m trabalha no Human Sciences Research Council, na \u00c1frica do Sul.<\/p>\n\n<p>Chama ainda a aten\u00e7\u00e3o para o facto de apenas um pequeno n\u00famero de pa\u00edses dispor de chamadas pol\u00edticas de continuidade, nas quais as raparigas s\u00e3o verdadeiramente apoiadas para acederem plenamente aos seus direitos \u00e0 educa\u00e7\u00e3o.<\/p>\n\n<p>Por exemplo, refere que, na Serra Leoa, as raparigas podem permanecer na escola durante o tempo que desejarem e regressar ap\u00f3s o parto.<\/p>\n\n<p>Steven Sebbale, membro do Conselho Nacional para a Ci\u00eancia e Tecnologia do Uganda, acredita que encontrar a solu\u00e7\u00e3o para a desigualdade de g\u00e9nero passa por examinar as contradi\u00e7\u00f5es estruturais, hist\u00f3ricas e contextuais que perpetuam as quest\u00f5es de g\u00e9nero no sistema.<\/p>\n\n<p>Como exemplo, menciona a disparidade geogr\u00e1fica entre universidades. Com as universidades p\u00fablicas a concentrarem excessivamente a atividade de investiga\u00e7\u00e3o nos centros urbanos, a maioria das universidades mais remotas fica para tr\u00e1s. Os investigadores que a\u00ed trabalham n\u00e3o t\u00eam acesso a oportunidades de financiamento.  <\/p>\n\n<p>\u201cCri\u00e1mos uma Alian\u00e7a para a Equidade de G\u00e9nero na Investiga\u00e7\u00e3o, que essencialmente reuniu estes investigadores destas diferentes universidades sat\u00e9lite, sentou-os \u00e0 mesa, ouviu as suas hist\u00f3rias e, depois, conseguimos elaborar um roteiro de atribui\u00e7\u00e3o inclusiva de financiamento para a investiga\u00e7\u00e3o e de educa\u00e7\u00e3o\u201d, afirma Steven Sebbale.<\/p>\n\n<p>Segundo o mesmo, o objetivo era \u201cpermitir que as suas universidades tamb\u00e9m desenvolvessem pol\u00edticas de g\u00e9nero e desconstru\u00edssem algumas dessas nuances h\u00e1 muito enraizadas\u201d.<\/p>\n\n<p>Da\u00ed a observa\u00e7\u00e3o de Diakalia Sanogo, que declara que, embora a SGCI n\u00e3o tenha for\u00e7ado a mudan\u00e7a usando o financiamento como um instrumento de press\u00e3o, instou os Conselhos \u2014 alguns dos quais tinham sido cegos ao g\u00e9nero \u2014 a verem os benef\u00edcios da inclus\u00e3o de g\u00e9nero atrav\u00e9s de uma abordagem participativa.<\/p>\n\n<p>Participam neste programa 17 pa\u00edses africanos. Nomeadamente: Qu\u00e9nia, Ruanda, Uganda, Tanz\u00e2nia, Eti\u00f3pia, Burkina Faso, Costa do Marfim, Gana, Nig\u00e9ria, Senegal, Serra Leoa, Botsuana, Mal\u00e1ui, Nam\u00edbia, Mo\u00e7ambique, Z\u00e2mbia e Zimbabu\u00e9. <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> A Ag\u00eancia Sueca de Coopera\u00e7\u00e3o para o Desenvolvimento Internacional (Sida), a Ag\u00eancia Norueguesa para a Coopera\u00e7\u00e3o para o Desenvolvimento (Norad), o Foreign, Commonwealth and Development Office (FCDO) do Reino Unido, a National Research Foundation (NRF) da \u00c1frica do Sul e a Funda\u00e7\u00e3o Alem\u00e3 de Investiga\u00e7\u00e3o (DFG).<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o necess\u00e1rios mais esfor\u00e7os para combater as desigualdades de tratamento que persistem entre homens e mulheres, apesar dos progressos alcan\u00e7ados nos \u00faltimos anos. No seu Relat\u00f3rio Nacional de Perspetivas da Investiga\u00e7\u00e3o de 2022, o Conselho Nacional para a Ci\u00eancia e Tecnologia do Uganda (UNCST) destaca que a propor\u00e7\u00e3o de mulheres nas institui\u00e7\u00f5es de investiga\u00e7\u00e3o e&hellip;<\/p>\n","protected":false},"author":1,"featured_media":22213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[159],"tags":[],"country":[246],"objective":[],"sg_theme":[],"class_list":["post-18126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","country-uganda-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica - SGCI Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica\" \/>\n<meta property=\"og:description\" content=\"S\u00e3o necess\u00e1rios mais esfor\u00e7os para combater as desigualdades de tratamento que persistem entre homens e mulheres, apesar dos progressos alcan\u00e7ados nos \u00faltimos anos. No seu Relat\u00f3rio Nacional de Perspetivas da Investiga\u00e7\u00e3o de 2022, o Conselho Nacional para a Ci\u00eancia e Tecnologia do Uganda (UNCST) destaca que a propor\u00e7\u00e3o de mulheres nas institui\u00e7\u00f5es de investiga\u00e7\u00e3o e&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-20T13:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T14:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"modular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"modular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/\"},\"author\":{\"name\":\"modular\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/ad6aec2baf31e79490a348ed706cb80e\"},\"headline\":\"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica\",\"datePublished\":\"2023-07-20T13:14:00+00:00\",\"dateModified\":\"2026-02-11T14:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/\"},\"wordCount\":870,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Gender_Issues.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/\",\"name\":\"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Gender_Issues.jpg\",\"datePublished\":\"2023-07-20T13:14:00+00:00\",\"dateModified\":\"2026-02-11T14:00:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Gender_Issues.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Gender_Issues.jpg\",\"width\":996,\"height\":567,\"caption\":\"Freepik (www.freepik.com)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/ad6aec2baf31e79490a348ed706cb80e\",\"name\":\"modular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"caption\":\"modular\"},\"sameAs\":[\"http:\\\/\\\/178.62.24.76\"],\"url\":\"https:\\\/\\\/sgciafrica.org\\\/pt\\\/author\\\/modular\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica - SGCI Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/","og_locale":"pt_BR","og_type":"article","og_title":"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica","og_description":"S\u00e3o necess\u00e1rios mais esfor\u00e7os para combater as desigualdades de tratamento que persistem entre homens e mulheres, apesar dos progressos alcan\u00e7ados nos \u00faltimos anos. No seu Relat\u00f3rio Nacional de Perspetivas da Investiga\u00e7\u00e3o de 2022, o Conselho Nacional para a Ci\u00eancia e Tecnologia do Uganda (UNCST) destaca que a propor\u00e7\u00e3o de mulheres nas institui\u00e7\u00f5es de investiga\u00e7\u00e3o e&hellip;","og_url":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/","og_site_name":"SGCI Africa","article_published_time":"2023-07-20T13:14:00+00:00","article_modified_time":"2026-02-11T14:00:07+00:00","og_image":[{"width":996,"height":567,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg","type":"image\/jpeg"}],"author":"modular","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"Escrito por":"modular","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/"},"author":{"name":"modular","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/ad6aec2baf31e79490a348ed706cb80e"},"headline":"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica","datePublished":"2023-07-20T13:14:00+00:00","dateModified":"2026-02-11T14:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/"},"wordCount":870,"commentCount":0,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/","url":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/","name":"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg","datePublished":"2023-07-20T13:14:00+00:00","dateModified":"2026-02-11T14:00:07+00:00","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg","width":996,"height":567,"caption":"Freepik (www.freepik.com)"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/pt\/acabando-com-a-desigualdade-de-genero-na-ciencia-na-africa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Acabar com a desigualdade de g\u00e9nero na ci\u00eancia em \u00c1frica"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/ad6aec2baf31e79490a348ed706cb80e","name":"modular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","caption":"modular"},"sameAs":["http:\/\/178.62.24.76"],"url":"https:\/\/sgciafrica.org\/pt\/author\/modular\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg",996,567,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues-300x171.jpg",300,171,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues-768x437.jpg",768,437,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg",996,567,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg",996,567,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg",996,567,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg",996,567,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg",996,567,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg",996,567,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues.jpg",996,567,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/07\/Gender_Issues-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"modular","author_link":"https:\/\/sgciafrica.org\/pt\/author\/modular\/"},"uagb_comment_info":0,"uagb_excerpt":"S\u00e3o necess\u00e1rios mais esfor\u00e7os para combater as desigualdades de tratamento que persistem entre homens e mulheres, apesar dos progressos alcan\u00e7ados nos \u00faltimos anos. No seu Relat\u00f3rio Nacional de Perspetivas da Investiga\u00e7\u00e3o de 2022, o Conselho Nacional para a Ci\u00eancia e Tecnologia do Uganda (UNCST) destaca que a propor\u00e7\u00e3o de mulheres nas institui\u00e7\u00f5es de investiga\u00e7\u00e3o e&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/18126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/comments?post=18126"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/posts\/18126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media\/22213"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/media?parent=18126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/categories?post=18126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/tags?post=18126"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/country?post=18126"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/objective?post=18126"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/pt\/wp-json\/wp\/v2\/sg_theme?post=18126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}