{"id":24207,"date":"2025-07-01T11:55:12","date_gmt":"2025-07-01T10:55:12","guid":{"rendered":"https:\/\/sgciafrica.org\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/"},"modified":"2025-07-01T11:56:56","modified_gmt":"2025-07-01T10:56:56","slug":"promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation","status":"publish","type":"resource","link":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/","title":{"rendered":"Promouvoir l&rsquo;\u00e9galit\u00e9 entre les hommes et les femmes dans le syst\u00e8me namibien de la science et de l&rsquo;innovation"},"content":{"rendered":"\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-30525373\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-87902b17 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Strengthening-Gender-and-Inclusivity-in-Namibia.pdf\" rel=\"follow noopener\" target=\"_blank\" role=\"button\"><div class=\"uagb-button__link\">T\u00c9L\u00c9CHARGER LE RAPPORT<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M438.6 278.6l-160 160C272.4 444.9 264.2 448 256 448s-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L338.8 288H32C14.33 288 .0016 273.7 .0016 256S14.33 224 32 224h306.8l-105.4-105.4c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l160 160C451.1 245.9 451.1 266.1 438.6 278.6z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n\n<p><\/p>\n\n<p>La Namibie a fait des progr\u00e8s notables dans le renforcement de l&rsquo;\u00e9galit\u00e9 des sexes et de l&rsquo;inclusion, en particulier dans les domaines de la science, de la technologie et de l&rsquo;innovation (STI). Cependant, de nombreux d\u00e9fis subsistent, en particulier pour les femmes et les filles dans les communaut\u00e9s rurales et dans les carri\u00e8res scientifiques. Un nouveau rapport soutenu par la Science Granting Councils Initiative (SGCI) d\u00e9crit comment la Namibie peut exploiter \u00e0 100 % son potentiel de d\u00e9veloppement humain pour une croissance socio-\u00e9conomique durable.  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-key-gaps-and-challenges\"><strong>Principales lacunes et d\u00e9fis<\/strong><\/h2>\n\n<p>Malgr\u00e9 une base juridique solide, les disparit\u00e9s entre les sexes persistent dans la STI :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Faible repr\u00e9sentation des femmes dans les domaines des STIM : Les femmes sont sous-repr\u00e9sent\u00e9es dans les domaines de l&rsquo;ing\u00e9nierie, de la technologie et des sciences naturelles, alors qu&rsquo;elles sont plus nombreuses dans les sciences sociales et l&rsquo;\u00e9ducation.<\/li>\n\n\n\n<li>L&rsquo;abandon apr\u00e8s l&rsquo;\u00e9ducation : Les femmes sont plus nombreuses \u00e0 s&rsquo;inscrire dans l&rsquo;enseignement sup\u00e9rieur, mais elles sont moins nombreuses \u00e0 acc\u00e9der \u00e0 des carri\u00e8res professionnelles dans le domaine des STIM.<\/li>\n\n\n\n<li>Des normes sociales persistantes : Les r\u00f4les traditionnels et la discrimination limitent la progression des femmes et leurs possibilit\u00e9s de leadership dans le domaine de la science, de la technologie et de l&rsquo;innovation.<\/li>\n\n\n\n<li>Manque de donn\u00e9es : Les donn\u00e9es ventil\u00e9es par sexe sont limit\u00e9es, ce qui rend difficile le suivi des progr\u00e8s et l&rsquo;\u00e9laboration d&rsquo;interventions cibl\u00e9es.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-s-working\"><strong>Qu&rsquo;est-ce qui fonctionne ?<\/strong><\/h2>\n\n<p>Le paysage politique de la Namibie offre une base solide pour la transformation :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>La politique nationale r\u00e9vis\u00e9e en mati\u00e8re de STI (2020-2030) fait de l&rsquo;\u00e9quit\u00e9 entre les sexes un principe directeur.<\/li>\n\n\n\n<li>La politique nationale en mati\u00e8re de genre et la loi sur l&rsquo;action positive promeuvent les droits des femmes dans les domaines de l&rsquo;\u00e9ducation et de l&#8217;emploi.<\/li>\n\n\n\n<li>Des programmes tels que <a href=\"https:\/\/wisci.worldlearning.org\/\">WiSci Girls Camps<\/a>, <a href=\"https:\/\/na.linkedin.com\/company\/namwie\">NAMWIE<\/a> et <a href=\"https:\/\/www.fawena.org\/\">FAWENA<\/a> encouragent les filles \u00e0 poursuivre des \u00e9tudes scientifiques et soutiennent les femmes dans les carri\u00e8res STIM.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"h-recommendations-for-inclusive-growth\"><strong>Recommandations pour une croissance inclusive<\/strong><\/h3>\n\n<p>Pour renforcer l&rsquo;\u00e9galit\u00e9 des sexes dans le syst\u00e8me STI namibien, le rapport appelle \u00e0<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Un ciblage plus clair : Les politiques devraient sp\u00e9cifier les groupes marginalis\u00e9s (par exemple, les femmes rurales ou les personnes handicap\u00e9es) pour une action plus efficace.<\/li>\n\n\n\n<li>Renforcer les fili\u00e8res de carri\u00e8re : Soutenir les filles depuis l&rsquo;\u00e9cole primaire jusqu&rsquo;aux carri\u00e8res dans les STIM, par le biais du mentorat et de la formation au leadership.<\/li>\n\n\n\n<li>Am\u00e9lioration de la collecte de donn\u00e9es : Suivez le genre, la localisation et les indicateurs socio-\u00e9conomiques dans la participation et le financement de la recherche.<\/li>\n\n\n\n<li>Soutien et collaboration continus : Engagez les principales parties prenantes, notamment les gouvernements, les universit\u00e9s et la soci\u00e9t\u00e9 civile, afin de garantir une responsabilit\u00e9 partag\u00e9e.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"h-moving-forward-to-promote-gender-equality-in-namibia\"><strong>Aller de l&rsquo;avant pour promouvoir l&rsquo;\u00e9galit\u00e9 entre les hommes et les femmes en Namibie<\/strong><\/h3>\n\n<p>La Namibie est en passe de devenir une \u00e9conomie fond\u00e9e sur la connaissance. Pour atteindre cet objectif, elle doit int\u00e9grer pleinement toutes les voix &#8211; en particulier celles des femmes et des filles &#8211; dans ses syst\u00e8mes de science et d&rsquo;innovation. En comblant les lacunes existantes et en adoptant des politiques inclusives, la Namibie peut parvenir \u00e0 un d\u00e9veloppement \u00e9quitable et durable pour tous.  <\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Namibie a fait des progr\u00e8s notables dans le renforcement de l&rsquo;\u00e9galit\u00e9 des sexes et de l&rsquo;inclusion, en particulier dans les domaines de la science, de la technologie et de l&rsquo;innovation (STI). Cependant, de nombreux d\u00e9fis subsistent, en particulier pour les femmes et les filles dans les communaut\u00e9s rurales et dans les carri\u00e8res scientifiques. Un&hellip;<\/p>\n","protected":false},"featured_media":24205,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_country":0,"wds_primary_resource-category":0,"wds_primary_sg_theme":0,"wds_primary_sg_type":0},"country":[253],"resource-category":[],"sg_theme":[287],"sg_type":[],"class_list":["post-24207","resource","type-resource","status-publish","has-post-thumbnail","hentry","country-namibia-fr","sg_theme-questions-degalite-des-sexes-et-dinclusion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Promouvoir l&#039;\u00e9galit\u00e9 entre les hommes et les femmes dans le syst\u00e8me namibien de la science et de l&#039;innovation - SGCI Africa<\/title>\n<meta name=\"description\" content=\"En abordant la question de l&#039;\u00e9galit\u00e9 des sexes en Namibie, le pays peut parvenir \u00e0 un d\u00e9veloppement \u00e9quitable et durable de la science et de l&#039;innovation pour tous.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Promouvoir l&#039;\u00e9galit\u00e9 entre les hommes et les femmes dans le syst\u00e8me namibien de la science et de l&#039;innovation\" \/>\n<meta property=\"og:description\" content=\"En abordant la question de l&#039;\u00e9galit\u00e9 des sexes en Namibie, le pays peut parvenir \u00e0 un d\u00e9veloppement \u00e9quitable et durable de la science et de l&#039;innovation pour tous.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-01T10:56:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\\\/\",\"name\":\"Promouvoir l'\u00e9galit\u00e9 entre les hommes et les femmes dans le syst\u00e8me namibien de la science et de l'innovation - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Namibian-flag.jpg\",\"datePublished\":\"2025-07-01T10:55:12+00:00\",\"dateModified\":\"2025-07-01T10:56:56+00:00\",\"description\":\"En abordant la question de l'\u00e9galit\u00e9 des sexes en Namibie, le pays peut parvenir \u00e0 un d\u00e9veloppement \u00e9quitable et durable de la science et de l'innovation pour tous.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Namibian-flag.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Namibian-flag.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Namibian flag\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Promouvoir l&rsquo;\u00e9galit\u00e9 entre les hommes et les femmes dans le syst\u00e8me namibien de la science et de l&rsquo;innovation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Promouvoir l'\u00e9galit\u00e9 entre les hommes et les femmes dans le syst\u00e8me namibien de la science et de l'innovation - SGCI Africa","description":"En abordant la question de l'\u00e9galit\u00e9 des sexes en Namibie, le pays peut parvenir \u00e0 un d\u00e9veloppement \u00e9quitable et durable de la science et de l'innovation pour tous.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/","og_locale":"fr_FR","og_type":"article","og_title":"Promouvoir l'\u00e9galit\u00e9 entre les hommes et les femmes dans le syst\u00e8me namibien de la science et de l'innovation","og_description":"En abordant la question de l'\u00e9galit\u00e9 des sexes en Namibie, le pays peut parvenir \u00e0 un d\u00e9veloppement \u00e9quitable et durable de la science et de l'innovation pour tous.","og_url":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/","og_site_name":"SGCI Africa","article_modified_time":"2025-07-01T10:56:56+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SGCIAfrica","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/","url":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/","name":"Promouvoir l'\u00e9galit\u00e9 entre les hommes et les femmes dans le syst\u00e8me namibien de la science et de l'innovation - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag.jpg","datePublished":"2025-07-01T10:55:12+00:00","dateModified":"2025-07-01T10:56:56+00:00","description":"En abordant la question de l'\u00e9galit\u00e9 des sexes en Namibie, le pays peut parvenir \u00e0 un d\u00e9veloppement \u00e9quitable et durable de la science et de l'innovation pour tous.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag.jpg","width":1920,"height":1080,"caption":"Namibian flag"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/resource\/promouvoir-legalite-entre-les-hommes-et-les-femmes-dans-le-systeme-namibien-de-la-science-et-de-linnovation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Promouvoir l&rsquo;\u00e9galit\u00e9 entre les hommes et les femmes dans le syst\u00e8me namibien de la science et de l&rsquo;innovation"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag.jpg",1920,1080,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag-300x169.jpg",300,169,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag-768x432.jpg",768,432,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag.jpg",1920,1080,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag.jpg",1920,1080,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag-1696x954.jpg",1696,954,true],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag-1352x761.jpg",1352,761,true],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag-1294x852.jpg",1294,852,true],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Namibian-flag-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Emily Skivington","author_link":"https:\/\/sgciafrica.org\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"La Namibie a fait des progr\u00e8s notables dans le renforcement de l&rsquo;\u00e9galit\u00e9 des sexes et de l&rsquo;inclusion, en particulier dans les domaines de la science, de la technologie et de l&rsquo;innovation (STI). Cependant, de nombreux d\u00e9fis subsistent, en particulier pour les femmes et les filles dans les communaut\u00e9s rurales et dans les carri\u00e8res scientifiques. Un&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/resource\/24207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/24205"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=24207"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=24207"},{"taxonomy":"resource-category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/resource-category?post=24207"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=24207"},{"taxonomy":"sg_type","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_type?post=24207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}