{"id":21050,"date":"2024-04-12T14:20:24","date_gmt":"2024-04-12T13:20:24","guid":{"rendered":"https:\/\/sgciafrica.org\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/"},"modified":"2026-02-11T13:40:30","modified_gmt":"2026-02-11T13:40:30","slug":"eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique","status":"publish","type":"resource","link":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/","title":{"rendered":"Cadre et directives de candidature du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19"},"content":{"rendered":"\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-59d1b3ee\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-a897ade7 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2022\/03\/ENG-COVID-19_Africa-RGF_Framework-and-Application-Guidelines-1.pdf\" rel=\"follow noopener\" target=\"_blank\" role=\"button\"><div class=\"uagb-button__link\">T\u00c9L\u00c9CHARGER LE CADRE<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M438.6 278.6l-160 160C272.4 444.9 264.2 448 256 448s-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L338.8 288H32C14.33 288 .0016 273.7 .0016 256S14.33 224 32 224h306.8l-105.4-105.4c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l160 160C451.1 245.9 451.1 266.1 438.6 278.6z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n\n<p><\/p>\n\n<p>Le <a href=\"https:\/\/idrc-crdi.ca\/en\/what-we-do\/projects-we-support\/project\/covid-19-africa-rapid-grant-fund\">Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19<\/a> a \u00e9t\u00e9 cr\u00e9\u00e9 en tant qu\u2019initiative visant \u00e0 pr\u00e9parer les communaut\u00e9s africaines de recherche et d\u2019engagement scientifique \u00e0 relever les d\u00e9fis pos\u00e9s par la pand\u00e9mie de COVID-19. En r\u00e9ponse \u00e0 la crise de sant\u00e9 publique urgente et \u00e9volutive<strong><em>,<\/em><\/strong> le Fonds a cherch\u00e9 \u00e0 soutenir des interventions rapides, pertinentes et dirig\u00e9es localement. Plus pr\u00e9cis\u00e9ment, le Fonds visait \u00e0 catalyser des r\u00e9ponses ancr\u00e9es localement \u00e0 travers l\u2019Afrique.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-strategic-objectives\"><strong>Objectifs strat\u00e9giques<\/strong><\/h2>\n\n<p>Conform\u00e9ment \u00e0 sa mission, le Fonds a \u00e9t\u00e9 con\u00e7u pour :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Premi\u00e8rement, soutenir les r\u00e9ponses continentales et nationales de l\u2019Afrique \u00e0 la COVID-19.<\/li>\n\n\n\n<li>Deuxi\u00e8mement, permettre la production et la diffusion de connaissances sp\u00e9cifiques au contexte pour \u00e9clairer les strat\u00e9gies de diagnostic, de pr\u00e9vention et de traitement.<\/li>\n\n\n\n<li>Troisi\u00e8mement, renforcer l\u2019engagement scientifique pour contrer la d\u00e9sinformation et promouvoir une communication publique fond\u00e9e sur des donn\u00e9es probantes.<\/li>\n\n\n\n<li>Enfin, am\u00e9liorer les m\u00e9canismes de conseil scientifique et politique gr\u00e2ce \u00e0 l\u2019apport rapide et coordonn\u00e9 d\u2019experts.<\/li>\n<\/ul>\n\n<p>Collectivement, ces objectifs visaient \u00e0 renforcer le r\u00f4le de l\u2019\u00e9cosyst\u00e8me scientifique dans la lutte contre les impacts socio-\u00e9conomiques et de sant\u00e9 publique de la COVID-19 en Afrique subsaharienne.<\/p>\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"h-scope-and-priority-areas\"><strong>Port\u00e9e et domaines prioritaires<\/strong><\/h3>\n\n<p>Pour atteindre ses objectifs<strong><em>,<\/em><\/strong> le Fonds de subvention rapide comprenait trois volets principaux, chacun r\u00e9pondant aux d\u00e9fis et opportunit\u00e9s cl\u00e9s identifi\u00e9s sur le continent :<\/p>\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>La recherche, ax\u00e9e sur la production de nouvelles connaissances dans des domaines prioritaires tels que :\n<ul class=\"wp-block-list\">\n<li>La virologie et la transmission de la COVID-19<\/li>\n\n\n\n<li>Les strat\u00e9gies de pr\u00e9vention et de contr\u00f4le localis\u00e9es<\/li>\n\n\n\n<li>La gouvernance et les r\u00e9ponses des syst\u00e8mes de sant\u00e9<\/li>\n\n\n\n<li>Les dynamiques socioculturelles et les populations vuln\u00e9rables<\/li>\n\n\n\n<li>La sant\u00e9 mentale et la r\u00e9silience communautaire<\/li>\n\n\n\n<li>La d\u00e9sinformation et les d\u00e9fis de la communication scientifique<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Le journalisme et la communication, visant \u00e0 renforcer le r\u00f4le des communicateurs scientifiques et de sant\u00e9 dans :\n<ul class=\"wp-block-list\">\n<li>La diffusion d\u2019informations pr\u00e9cises sur la sant\u00e9 publique<\/li>\n\n\n\n<li>La lutte contre la d\u00e9sinformation et la stigmatisation<\/li>\n\n\n\n<li>La mise en \u00e9vidence des impacts socio-\u00e9conomiques et culturels sous-estim\u00e9s de la pand\u00e9mie<\/li>\n\n\n\n<li>La promotion des connaissances autochtones et des innovations locales<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Le soutien aux politiques et aux conseils, con\u00e7u pour appuyer les acad\u00e9mies nationales et les organismes d\u2019experts africains dans :\n<ul class=\"wp-block-list\">\n<li>La fourniture de conseils scientifiques rapides aux d\u00e9cideurs politiques<\/li>\n\n\n\n<li>La r\u00e9union de groupes d\u2019experts multidisciplinaires<\/li>\n\n\n\n<li>Le renforcement de la prospective et de la pr\u00e9paration aux futures urgences sanitaires<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"h-eligibility-and-implementation\"><strong>\u00c9ligibilit\u00e9 et mise en \u0153uvre<\/strong><\/h3>\n\n<p>En ce qui concerne la participation, les candidatures \u00e9taient ouvertes aux individus et aux organisations de 17 pays participant \u00e0 l\u2019IOSC. En particulier, pour le financement de la recherche, la priorit\u00e9 a \u00e9t\u00e9 donn\u00e9e aux membres de l\u2019Alliance des universit\u00e9s de recherche africaines (ARUA) au Nigeria et en Afrique du Sud, avec des possibilit\u00e9s de partenariats collaboratifs entre institutions. <\/p>\n\n<p>De plus<strong><em>,<\/em><\/strong> les crit\u00e8res d\u2019\u00e9ligibilit\u00e9 garantissaient que les principaux candidats poss\u00e9daient une solide exp\u00e9rience acad\u00e9mique ou professionnelle, avec au moins cinq ans dans des domaines pertinents.<\/p>\n\n<p>En outre, l\u2019accent a \u00e9t\u00e9 mis sur la diversit\u00e9 et l\u2019inclusion. Pour garantir une large accessibilit\u00e9, tous les r\u00e9sultats financ\u00e9s devaient \u00eatre mis \u00e0 disposition en libre acc\u00e8s, conform\u00e9ment aux principes plus larges de transparence et d\u2019\u00e9quit\u00e9 des connaissances. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-funding-overview\"><strong>Aper\u00e7u du financement<\/strong><\/h2>\n\n<p>Le financement a soutenu des activit\u00e9s telles que le travail de terrain, la diffusion, les \u00e9v\u00e9nements de partage des connaissances et le renforcement des capacit\u00e9s.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Subventions de recherche : jusqu\u2019\u00e0 100 000 USD pour 24 mois<\/li>\n\n\n\n<li>Projets de communication scientifique : jusqu\u2019\u00e0 20 000 USD pour 18 mois<\/li>\n\n\n\n<li>Initiatives de conseil scientifique : jusqu\u2019\u00e0 50 000 USD pour 24 mois<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"h-review-and-evaluation\"><strong>Examen et \u00e9valuation<\/strong><\/h3>\n\n<p>Toutes les propositions ont fait l\u2019objet d\u2019un examen rigoureux par les pairs ou d\u2019une \u00e9valuation par rapport \u00e0 des crit\u00e8res tels que :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>La pertinence et la qualit\u00e9 des activit\u00e9s propos\u00e9es<\/li>\n\n\n\n<li>L\u2019exp\u00e9rience et la composition des \u00e9quipes de projet<\/li>\n\n\n\n<li>La contribution potentielle aux r\u00e9ponses nationales, r\u00e9gionales ou continentales \u00e0 la COVID-19<\/li>\n\n\n\n<li>L\u2019int\u00e9gration des consid\u00e9rations de genre et de diversit\u00e9<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"h-summarising-the-covid-19-africa-rapid-grant-fund-nbsp-frame\"><strong>R\u00e9sum\u00e9 du cadre du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19<\/strong><\/h3>\n\n<p>Le Fonds a repr\u00e9sent\u00e9 un tournant important vers des r\u00e9ponses dirig\u00e9es par l\u2019Afrique et adapt\u00e9es au contexte face \u00e0 une crise mondiale. \u00c0 l\u2019avenir, les enseignements tir\u00e9s de cette initiative continueront d\u2019\u00e9clairer le programme plus large de renforcement des \u00e9cosyst\u00e8mes de recherche et des m\u00e9canismes de subvention scientifique en Afrique. <\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19 a \u00e9t\u00e9 cr\u00e9\u00e9 en tant qu\u2019initiative visant \u00e0 pr\u00e9parer les communaut\u00e9s africaines de recherche et d\u2019engagement scientifique \u00e0 relever les d\u00e9fis pos\u00e9s par la pand\u00e9mie de COVID-19. En r\u00e9ponse \u00e0 la crise de sant\u00e9 publique urgente et \u00e9volutive, le Fonds a cherch\u00e9 \u00e0 soutenir des&hellip;<\/p>\n","protected":false},"featured_media":23198,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_country":0,"wds_primary_resource-category":0,"wds_primary_sg_theme":0,"wds_primary_sg_type":0},"country":[],"resource-category":[],"sg_theme":[282],"sg_type":[],"class_list":["post-21050","resource","type-resource","status-publish","has-post-thumbnail","hentry","sg_theme-research-and-innovation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cadre et directives du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19<\/title>\n<meta name=\"description\" content=\"Le Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19 a repr\u00e9sent\u00e9 un tournant important vers des r\u00e9ponses dirig\u00e9es par l\u2019Afrique et adapt\u00e9es au contexte face \u00e0 une crise mondiale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cadre et directives de candidature du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19\" \/>\n<meta property=\"og:description\" content=\"Le Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19 a repr\u00e9sent\u00e9 un tournant important vers des r\u00e9ponses dirig\u00e9es par l\u2019Afrique et adapt\u00e9es au contexte face \u00e0 une crise mondiale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:40:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\\\/\",\"name\":\"Cadre et directives du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/scientist-looking-into-microscope.jpg\",\"datePublished\":\"2024-04-12T13:20:24+00:00\",\"dateModified\":\"2026-02-11T13:40:30+00:00\",\"description\":\"Le Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19 a repr\u00e9sent\u00e9 un tournant important vers des r\u00e9ponses dirig\u00e9es par l\u2019Afrique et adapt\u00e9es au contexte face \u00e0 une crise mondiale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/scientist-looking-into-microscope.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/scientist-looking-into-microscope.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"scientist looking into microscope\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cadre et directives de candidature du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cadre et directives du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19","description":"Le Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19 a repr\u00e9sent\u00e9 un tournant important vers des r\u00e9ponses dirig\u00e9es par l\u2019Afrique et adapt\u00e9es au contexte face \u00e0 une crise mondiale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Cadre et directives de candidature du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19","og_description":"Le Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19 a repr\u00e9sent\u00e9 un tournant important vers des r\u00e9ponses dirig\u00e9es par l\u2019Afrique et adapt\u00e9es au contexte face \u00e0 une crise mondiale.","og_url":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/","og_site_name":"SGCI Africa","article_modified_time":"2026-02-11T13:40:30+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SGCIAfrica","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/","url":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/","name":"Cadre et directives du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope.jpg","datePublished":"2024-04-12T13:20:24+00:00","dateModified":"2026-02-11T13:40:30+00:00","description":"Le Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19 a repr\u00e9sent\u00e9 un tournant important vers des r\u00e9ponses dirig\u00e9es par l\u2019Afrique et adapt\u00e9es au contexte face \u00e0 une crise mondiale.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope.jpg","width":1920,"height":1080,"caption":"scientist looking into microscope"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/resource\/eng-cadre-et-lignes-directrices-du-fonds-de-subvention-rapide-covid-19-pour-lafrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Cadre et directives de candidature du Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope.jpg",1920,1080,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope-300x169.jpg",300,169,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope-768x432.jpg",768,432,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope.jpg",1920,1080,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope.jpg",1920,1080,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope-1696x954.jpg",1696,954,true],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope-1352x761.jpg",1352,761,true],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope-1294x852.jpg",1294,852,true],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/scientist-looking-into-microscope-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Juliet Tumeo","author_link":"https:\/\/sgciafrica.org\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Le Fonds de subvention rapide pour l\u2019Afrique contre la COVID-19 a \u00e9t\u00e9 cr\u00e9\u00e9 en tant qu\u2019initiative visant \u00e0 pr\u00e9parer les communaut\u00e9s africaines de recherche et d\u2019engagement scientifique \u00e0 relever les d\u00e9fis pos\u00e9s par la pand\u00e9mie de COVID-19. En r\u00e9ponse \u00e0 la crise de sant\u00e9 publique urgente et \u00e9volutive, le Fonds a cherch\u00e9 \u00e0 soutenir des&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/resource\/21050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/23198"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=21050"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=21050"},{"taxonomy":"resource-category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/resource-category?post=21050"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=21050"},{"taxonomy":"sg_type","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_type?post=21050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}