{"id":20992,"date":"2024-04-12T14:20:27","date_gmt":"2024-04-12T13:20:27","guid":{"rendered":"https:\/\/sgciafrica.org\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/"},"modified":"2025-07-31T17:32:44","modified_gmt":"2025-07-31T16:32:44","slug":"fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche","status":"publish","type":"resource","link":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/","title":{"rendered":"Fonds de subvention rapide Covid-19 Afrique : R\u00e9sum\u00e9s de projets de recherche"},"content":{"rendered":"\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-b6bce759\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-5d3cda7a wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2022\/03\/Project-Abstracts_-Research-Strand-1.pdf\" rel=\"follow noopener\" target=\"_blank\" role=\"button\"><div class=\"uagb-button__link\">T\u00c9L\u00c9CHARGER LES R\u00c9SUM\u00c9S<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M438.6 278.6l-160 160C272.4 444.9 264.2 448 256 448s-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L338.8 288H32C14.33 288 .0016 273.7 .0016 256S14.33 224 32 224h306.8l-105.4-105.4c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l160 160C451.1 245.9 451.1 266.1 438.6 278.6z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">De nombreux projets de recherche ont \u00e9t\u00e9 propos\u00e9s dans toute l&rsquo;Afrique, dans le but d&rsquo;am\u00e9liorer la compr\u00e9hension, la pr\u00e9vention et la r\u00e9ponse au COVID-19 au niveau local. Les r\u00e9sum\u00e9s des subventions de recherche d\u00e9crivent les diff\u00e9rents projets qui seront r\u00e9alis\u00e9s gr\u00e2ce au financement du <a href=\"https:\/\/idrc-crdi.ca\/en\/what-we-do\/projects-we-support\/project\/covid-19-africa-rapid-grant-fund#:~:text=The%20Fund%20will%20support%20up,respond%20to%20future%20shared%20challenges.\">Fonds de subvention rapide COVID-19 pour l&rsquo;Afrique.<\/a>  <\/p>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-projects-in-botswana\"><strong>Projets au Botswana<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Au Botswana, de nombreux projets ont fait l&rsquo;objet de recherches sur le COVID-19. Il s&rsquo;agit notamment des projets suivants <\/p>\n\n<ul class=\"wp-block-list\">\n<li>L&rsquo;un des projets vise \u00e0 identifier les biomarqueurs pour la gestion de la maladie. Pour ce faire, il s&rsquo;agit d&rsquo;\u00e9tudier la mani\u00e8re dont COVID-10 affecte le syst\u00e8me immunitaire. Par exemple, en analysant les cellules immunitaires, les cytokines et les anticorps chez les patients atteints de la maladie.  <\/li>\n\n\n\n<li>Un autre travail de recherche consisterait \u00e0 comparer les facteurs sociaux affectant la vuln\u00e9rabilit\u00e9 COVID-19 au Botswana et au Malawi. Ces facteurs comprennent le sexe, le revenu et le handicap. <\/li>\n\n\n\n<li>Un troisi\u00e8me projet visait \u00e0 examiner les risques de propagation du COVID-19 par les eaux us\u00e9es utilis\u00e9es dans l&rsquo;agriculture. Pour ce faire, les chercheurs ont test\u00e9 le virus dans les eaux us\u00e9es et \u00e9tudi\u00e9 son interaction avec d&rsquo;autres microbes. <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-abstracts-from-cote-d-ivoire\"><strong>R\u00e9sum\u00e9s de la C\u00f4te d&rsquo;Ivoire<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La recherche en C\u00f4te d&rsquo;Ivoire s&rsquo;est concentr\u00e9e sur<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Les chercheurs \u00e9valueront la mani\u00e8re dont l&rsquo;information et la communication en mati\u00e8re de sant\u00e9 publique ont \u00e9t\u00e9 g\u00e9r\u00e9es pendant la pand\u00e9mie. L&rsquo;objectif \u00e9tant d&rsquo;am\u00e9liorer les messages et d&rsquo;int\u00e9grer les perspectives de genre. <\/li>\n\n\n\n<li>De m\u00eame, un autre projet visait \u00e0 am\u00e9liorer les strat\u00e9gies de communication pendant les crises sanitaires en \u00e9tudiant la mani\u00e8re dont les messages \u00e9taient partag\u00e9s, qui les recevait et comment les communaut\u00e9s r\u00e9agissaient.<\/li>\n\n\n\n<li>Une \u00e9tude porterait sur le lien entre les march\u00e9s de viande de brousse et la propagation des virus. Elle implique la collecte d&rsquo;\u00e9chantillons d&rsquo;animaux sauvages et la sensibilisation aux risques sanitaires. <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-covid-19-research-in-burkina-faso\">COVID-19 <strong>Recherche au Burkina Faso<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Pour comprendre comment le virus se propage et \u00e9volue dans le temps, les scientifiques proc\u00e9deront \u00e0 une analyse g\u00e9n\u00e9tique et mutationnelle des souches de SRAS-CoV-2 dans le pays. Ils cartographieront \u00e9galement les r\u00e9seaux de transmission et \u00e9tudieront le lien entre les diff\u00e9rentes variantes du virus et les sympt\u00f4mes cliniques. L&rsquo;objectif de la recherche est d&rsquo;aider \u00e0 adapter les strat\u00e9gies de sant\u00e9 publique en comprenant quelles sont les mutations du virus qui circulent et qui pourraient r\u00e9sister aux traitements ou aux vaccins.  <\/p>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-projects-in-ethiopia\"><strong>Projets en \u00c9thiopie<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Les projets en \u00c9thiopie ont \u00e9t\u00e9 examin\u00e9s :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Un projet s&rsquo;est concentr\u00e9 sur la d\u00e9tection du virus dans les eaux us\u00e9es et les syst\u00e8mes fluviaux afin d&rsquo;identifier les points chauds de la contamination et d&rsquo;\u00e9laborer des strat\u00e9gies de pr\u00e9vention.<\/li>\n\n\n\n<li>Une autre \u00e9quipe de recherche se penchera sur les raisons pour lesquelles les gens choisissent de suivre ou non les mesures de s\u00e9curit\u00e9. Pour ce faire, elle utiliserait un mod\u00e8le socio-\u00e9cologique afin de comprendre les facteurs personnels et sociaux. <\/li>\n\n\n\n<li>L&rsquo;objectif d&rsquo;une troisi\u00e8me \u00e9tude \u00e9tait de d\u00e9velopper des programmes de soutien pour la sant\u00e9 mentale et la r\u00e9int\u00e9gration des migrants rapatri\u00e9s qui avaient \u00e9t\u00e9 mis en quarantaine.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-research-in-ghana\"><strong>La recherche au Ghana<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Au Ghana, la recherche s&rsquo;est concentr\u00e9e sur les moyens d&rsquo;am\u00e9liorer la vie quotidienne. Par exemple : <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Une \u00e9quipe de recherche testera une m\u00e9thode de d\u00e9tection du COVID-19 plus rapide et moins co\u00fbteuse, qui pourrait \u00eatre utilis\u00e9e dans les \u00e9tablissements de sant\u00e9 disposant de peu de ressources.<\/li>\n\n\n\n<li>Une autre \u00e9tude examinera si les bains de bouche peuvent r\u00e9duire temporairement la charge virale chez les patients asymptomatiques, ce qui pourrait rendre les cliniques plus s\u00fbres.<\/li>\n\n\n\n<li>Un dernier volet de la recherche porterait sur la sant\u00e9 mentale pendant la pand\u00e9mie, en se concentrant sur l&rsquo;influence de l&rsquo;activit\u00e9 physique sur le stress et sur la mani\u00e8re dont les survivants ont fait face \u00e0 la stigmatisation et aux d\u00e9fis \u00e9motionnels.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-projects-in-kenya\"><strong>Projets au Kenya<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Au Kenya, les propositions de recherche portaient sur divers domaines. Il s&rsquo;agit notamment de <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Un groupe de chercheurs utilisera les eaux us\u00e9es et les \u00e9chantillons de sang pour suivre la propagation du virus et \u00e9valuer l&rsquo;efficacit\u00e9 des soins \u00e0 domicile. Cela permettrait \u00e9galement de cr\u00e9er un outil num\u00e9rique pour la surveillance en temps r\u00e9el. <\/li>\n\n\n\n<li>Une autre \u00e9tude a examin\u00e9 les attitudes et les comportements du public \u00e0 l&rsquo;\u00e9gard des mesures de pr\u00e9vention gouvernementales. Ils testeront \u00e9galement des plantes m\u00e9dicinales en vue d&rsquo;un \u00e9ventuel traitement contre le COVID-19. <\/li>\n\n\n\n<li>Un troisi\u00e8me projet consistera \u00e0 \u00e9tudier l&rsquo;impact de la pand\u00e9mie sur la s\u00e9curit\u00e9 alimentaire, l&rsquo;alimentation et l&rsquo;activit\u00e9 physique dans les zones rurales et urbaines.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-research-abstracts-in-malawi\"><strong>R\u00e9sum\u00e9s de recherche au Malawi<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Les r\u00e9sum\u00e9s des \u00e9quipes de recherche du Malawi ont \u00e9t\u00e9 pr\u00e9sent\u00e9s :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Les chercheurs \u00e9tudieront les effets de la pand\u00e9mie sur les moyens de subsistance des communaut\u00e9s vuln\u00e9rables, en particulier dans les r\u00e9gions semi-arides. En outre, ils \u00e9tudieront la mani\u00e8re dont les restrictions de circulation ont perturb\u00e9 les liaisons entre les zones rurales et les zones urbaines. <\/li>\n\n\n\n<li>Une autre \u00e9quipe \u00e9valuera l&rsquo;impact du COVID-19 sur la sant\u00e9 mentale, en se concentrant sur les travailleurs de la sant\u00e9 et les adolescents. L&rsquo;objectif est d&rsquo;influencer la politique en mati\u00e8re de sant\u00e9 mentale et d&rsquo;accro\u00eetre le soutien aux personnes touch\u00e9es par la pand\u00e9mie. <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-projects-in-mozambique\"><strong>Projets au Mozambique<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Au Mozambique, les domaines de recherche privil\u00e9gi\u00e9s \u00e9taient les suivants :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Une \u00e9tude \u00e0 grande \u00e9chelle qui se concentrerait sur l&rsquo;impact des fermetures d&rsquo;\u00e9coles sur la sant\u00e9 mentale, y compris la d\u00e9pression et l&rsquo;anxi\u00e9t\u00e9, chez les \u00e9l\u00e8ves et les enseignants.<\/li>\n\n\n\n<li>Un autre projet vise \u00e0 mod\u00e9liser la propagation du virus en fonction des mouvements de population et des comportements culturels, afin d&rsquo;aider les d\u00e9cideurs politiques \u00e0 prendre de meilleures d\u00e9cisions. Il s&rsquo;agirait notamment d&rsquo;examiner les difficult\u00e9s li\u00e9es \u00e0 l&rsquo;application de mesures de sant\u00e9 publique dans les zones d&rsquo;habitat informel disposant de ressources limit\u00e9es. <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-research-in-nigeria\"><strong>La recherche au Nigeria<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Au Nigeria, les chercheurs exploreront les plantes m\u00e9dicinales nig\u00e9rianes pour trouver des compos\u00e9s susceptibles d&#8217;emp\u00eacher le virus de p\u00e9n\u00e9trer dans les cellules humaines, en se concentrant sur les herbes antivirales traditionnelles. Les scientifiques ont pour objectif d&rsquo;isoler les ingr\u00e9dients actifs, de tester leur s\u00e9curit\u00e9 et de d\u00e9velopper \u00e9ventuellement de nouveaux traitements contre le COVID-19. <\/p>\n\n<h3 class=\"wp-block-heading has-medium-font-size\" id=\"h-in-summary\"><strong>En r\u00e9sum\u00e9<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Dans l&rsquo;ensemble, ces projets visaient \u00e0 fournir des id\u00e9es et des outils fond\u00e9s sur des donn\u00e9es probantes, pratiques, abordables et adapt\u00e9s aux communaut\u00e9s africaines.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De nombreux projets de recherche ont \u00e9t\u00e9 propos\u00e9s dans toute l&rsquo;Afrique, dans le but d&rsquo;am\u00e9liorer la compr\u00e9hension, la pr\u00e9vention et la r\u00e9ponse au COVID-19 au niveau local. Les r\u00e9sum\u00e9s des subventions de recherche d\u00e9crivent les diff\u00e9rents projets qui seront r\u00e9alis\u00e9s gr\u00e2ce au financement du Fonds de subvention rapide COVID-19 pour l&rsquo;Afrique. Projets au Botswana Au&hellip;<\/p>\n","protected":false},"featured_media":23033,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_country":0,"wds_primary_resource-category":0,"wds_primary_sg_theme":0,"wds_primary_sg_type":0},"country":[165,256,170,122,72,73,250,123,171],"resource-category":[],"sg_theme":[282],"sg_type":[],"class_list":["post-20992","resource","type-resource","status-publish","has-post-thumbnail","hentry","country-botswana","country-burkina-faso-2","country-cote-d-ivoire","country-ethiopia","country-ghana","country-kenya","country-malawi-2","country-mozambique","country-nigeria","sg_theme-research-and-innovation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fonds de subvention rapide COVID-19 Afrique : R\u00e9sum\u00e9s de projets de recherche<\/title>\n<meta name=\"description\" content=\"De nombreux projets de recherche sur le COVID-19 ont \u00e9t\u00e9 propos\u00e9s dans toute l&#039;Afrique, dans le but d&#039;am\u00e9liorer la compr\u00e9hension, la pr\u00e9vention et la r\u00e9ponse au niveau local.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fonds de subvention rapide Covid-19 Afrique : R\u00e9sum\u00e9s de projets de recherche\" \/>\n<meta property=\"og:description\" content=\"De nombreux projets de recherche sur le COVID-19 ont \u00e9t\u00e9 propos\u00e9s dans toute l&#039;Afrique, dans le but d&#039;am\u00e9liorer la compr\u00e9hension, la pr\u00e9vention et la r\u00e9ponse au niveau local.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T16:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\\\/\",\"name\":\"Fonds de subvention rapide COVID-19 Afrique : R\u00e9sum\u00e9s de projets de recherche\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Illustration-of-virus.jpg\",\"datePublished\":\"2024-04-12T13:20:27+00:00\",\"dateModified\":\"2025-07-31T16:32:44+00:00\",\"description\":\"De nombreux projets de recherche sur le COVID-19 ont \u00e9t\u00e9 propos\u00e9s dans toute l'Afrique, dans le but d'am\u00e9liorer la compr\u00e9hension, la pr\u00e9vention et la r\u00e9ponse au niveau local.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Illustration-of-virus.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Illustration-of-virus.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Illustration of virus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/resource\\\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fonds de subvention rapide Covid-19 Afrique : R\u00e9sum\u00e9s de projets de recherche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fonds de subvention rapide COVID-19 Afrique : R\u00e9sum\u00e9s de projets de recherche","description":"De nombreux projets de recherche sur le COVID-19 ont \u00e9t\u00e9 propos\u00e9s dans toute l'Afrique, dans le but d'am\u00e9liorer la compr\u00e9hension, la pr\u00e9vention et la r\u00e9ponse au niveau local.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/","og_locale":"fr_FR","og_type":"article","og_title":"Fonds de subvention rapide Covid-19 Afrique : R\u00e9sum\u00e9s de projets de recherche","og_description":"De nombreux projets de recherche sur le COVID-19 ont \u00e9t\u00e9 propos\u00e9s dans toute l'Afrique, dans le but d'am\u00e9liorer la compr\u00e9hension, la pr\u00e9vention et la r\u00e9ponse au niveau local.","og_url":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/","og_site_name":"SGCI Africa","article_modified_time":"2025-07-31T16:32:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SGCIAfrica","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/","url":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/","name":"Fonds de subvention rapide COVID-19 Afrique : R\u00e9sum\u00e9s de projets de recherche","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus.jpg","datePublished":"2024-04-12T13:20:27+00:00","dateModified":"2025-07-31T16:32:44+00:00","description":"De nombreux projets de recherche sur le COVID-19 ont \u00e9t\u00e9 propos\u00e9s dans toute l'Afrique, dans le but d'am\u00e9liorer la compr\u00e9hension, la pr\u00e9vention et la r\u00e9ponse au niveau local.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus.jpg","width":1920,"height":1080,"caption":"Illustration of virus"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/resource\/fonds-de-subvention-rapide-covid-19-afrique-resumes-de-projets-de-recherche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Fonds de subvention rapide Covid-19 Afrique : R\u00e9sum\u00e9s de projets de recherche"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus.jpg",1920,1080,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus-300x169.jpg",300,169,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus-768x432.jpg",768,432,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus.jpg",1920,1080,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus.jpg",1920,1080,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus-1696x954.jpg",1696,954,true],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus-1352x761.jpg",1352,761,true],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus-1294x852.jpg",1294,852,true],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/Illustration-of-virus-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Juliet Tumeo","author_link":"https:\/\/sgciafrica.org\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"De nombreux projets de recherche ont \u00e9t\u00e9 propos\u00e9s dans toute l&rsquo;Afrique, dans le but d&rsquo;am\u00e9liorer la compr\u00e9hension, la pr\u00e9vention et la r\u00e9ponse au COVID-19 au niveau local. Les r\u00e9sum\u00e9s des subventions de recherche d\u00e9crivent les diff\u00e9rents projets qui seront r\u00e9alis\u00e9s gr\u00e2ce au financement du Fonds de subvention rapide COVID-19 pour l&rsquo;Afrique. Projets au Botswana Au&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/resource\/20992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/23033"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=20992"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=20992"},{"taxonomy":"resource-category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/resource-category?post=20992"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=20992"},{"taxonomy":"sg_type","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_type?post=20992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}