{"id":25696,"date":"2026-03-06T11:29:30","date_gmt":"2026-03-06T11:29:30","guid":{"rendered":"https:\/\/sgciafrica.org\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/"},"modified":"2026-03-06T11:30:50","modified_gmt":"2026-03-06T11:30:50","slug":"la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/","title":{"rendered":"La Namibie lance le rapport national d&rsquo;enqu\u00eate sur les infrastructures de recherche"},"content":{"rendered":"\n<p>La Commission <a href=\"https:\/\/www.ncrst.na\/\">nationale<\/a> de la recherche, de la science et de la technologie de Namibie a officiellement lanc\u00e9 le rapport d&rsquo;enqu\u00eate sur les infrastructures de recherche du pays, d\u00e9crivant les installations de recherche existantes, les lacunes cl\u00e9s et les domaines prioritaires pour le d\u00e9veloppement.<\/p>\n\n<p>Le rapport a \u00e9t\u00e9 pr\u00e9sent\u00e9 le 3 mars au Centre culturel franco-namibien \u00e0 Windhoek devant un public de parties prenantes issues du gouvernement, du milieu universitaire et de l&rsquo;industrie.<\/p>\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-92040767 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-at-the-launch-of-NCRST-survey-1-1024x683.jpg ,https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-at-the-launch-of-NCRST-survey-1.jpg 780w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-at-the-launch-of-NCRST-survey-1.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-at-the-launch-of-NCRST-survey-1-1024x683.jpg\" alt=\"\" class=\"uag-image-25689\" width=\"408\" height=\"272\" title=\"Anicia Peters lors du lancement de l'enqu\u00eate de la NCRST\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n<p>La directrice g\u00e9n\u00e9rale de la NCRST, Anicia Peters, a d\u00e9clar\u00e9 que les conclusions auraient des implications concr\u00e8tes pour le d\u00e9veloppement du secteur.<\/p>\n\n<p>\u00ab Le rapport guidera notre planification strat\u00e9gique, \u00e9clairera les d\u00e9cisions d&rsquo;investissement et renforcera la coordination dans l&rsquo;ensemble du secteur de la recherche, de la science et de l&rsquo;innovation en Namibie \u00bb, a-t-elle d\u00e9clar\u00e9.<\/p>\n\n<p>Le rapport fournit une \u00e9valuation compl\u00e8te des infrastructures de recherche de la Namibie, cartographiant les installations existantes \u00e0 travers le pays, \u00e9valuant les capacit\u00e9s institutionnelles et identifiant les besoins nationaux en mati\u00e8re de recherche ainsi que les domaines prioritaires critiques.<\/p>\n\n<p>Il s&rsquo;appuie \u00e9galement sur les donn\u00e9es de r\u00e9f\u00e9rence de l&rsquo;enqu\u00eate de 2017, permettant une vue longitudinale de l&rsquo;\u00e9volution du paysage et renfor\u00e7ant la base factuelle pour l&rsquo;\u00e9laboration future de politiques en mati\u00e8re de recherche, de science et de technologie.<\/p>\n\n<p class=\"has-large-font-size\"><strong>Le lancement<\/strong><strong><\/strong><\/p>\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-aca60c87 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-and-staff-of-the-NCRST-at-the-launch-of-the-survey-report-1024x683.jpg ,https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-and-staff-of-the-NCRST-at-the-launch-of-the-survey-report.jpg 780w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-and-staff-of-the-NCRST-at-the-launch-of-the-survey-report.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Anicia-Peters-and-staff-of-the-NCRST-at-the-launch-of-the-survey-report-1024x683.jpg\" alt=\"\" class=\"uag-image-25690\" width=\"1080\" height=\"720\" title=\"Anicia Peters et le personnel de la NCRST lors du lancement du rapport d'enqu\u00eate\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n<p>Les remarques d&rsquo;ouverture ont \u00e9t\u00e9 prononc\u00e9es par Nhlanhla Lupahla, directeur g\u00e9n\u00e9ral du soutien \u00e0 la recherche, \u00e0 la science, \u00e0 la technologie et \u00e0 l&rsquo;innovation.<\/p>\n\n<p>Il a d\u00e9crit le lancement comme \u00ab une \u00e9tape importante vers le renforcement du paysage des infrastructures de recherche de la Namibie, la promotion d&rsquo;un acc\u00e8s \u00e9quitable aux installations et la promotion de l&rsquo;agenda national de recherche \u00bb.<\/p>\n\n<p>Les conclusions de l&rsquo;enqu\u00eate ont ensuite \u00e9t\u00e9 pr\u00e9sent\u00e9es par Hilya Shikongo, directrice g\u00e9n\u00e9rale par int\u00e9rim de la Division du d\u00e9veloppement de l&rsquo;innovation et de la technologie, qui a guid\u00e9 les participants \u00e0 travers la m\u00e9thodologie, les donn\u00e9es et les principales recommandations du rapport.<\/p>\n\n<p><strong>De l&rsquo;enqu\u00eate \u00e0 l&rsquo;action<\/strong><strong><\/strong><\/p>\n\n<p>Le rapport sert de fondement \u00e0 un travail plus large de renforcement des capacit\u00e9s. Les conseils de subventions <a href=\"https:\/\/sgciafrica.org\/pt\/council\/comissao-nacional-de-pesquisa-em-ciencia-e-tecnologia-namibia\/\">scientifiques<\/a> \u00e0 travers le continent ont appris que les \u00e9cosyst\u00e8mes de recherche durables n\u00e9cessitent plus que du financement.<\/p>\n\n<p>Ils n\u00e9cessitent des infrastructures accessibles, bien entretenues et r\u00e9parties de mani\u00e8re \u00e0 servir l&rsquo;ensemble du pays, et non seulement ses principaux centres.<\/p>\n\n<p>Avec le rapport d&rsquo;enqu\u00eate d\u00e9sormais public, la Namibie a une vision plus claire du chemin parcouru et de celui qu&rsquo;il reste \u00e0 parcourir.<\/p>\n\n<p><strong><em>Consultez les <\/em><\/strong><a href=\"https:\/\/sgciafrica.org\/fr\/actualites\/\"><em>histoires<\/em><\/a><strong><em> et dites-nous ce que vous en pensez. Nous serions ravis d&rsquo;avoir de vos nouvelles ! <\/em><\/strong><em><\/em><\/p>\n\n<p><em>Poursuivons la conversation<\/em><em> sur nos m\u00e9dias sociaux<\/em><\/p>\n\n<p><em>Suivez-nous sur <\/em><a href=\"https:\/\/www.linkedin.com\/company\/science-granting-councils-initiative\/\"><em>LinkedIn<\/em><\/a><em> et <\/em><a href=\"https:\/\/x.com\/SGCIAfrica\"><em>X<\/em><\/a><em><\/em><\/p>\n\n<p><em>Publi\u00e9 le 6 mars 2026<\/em><\/p>\n\n<p><em>R\u00e9dig\u00e9 par Jackie Opara-Fatoye,<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Commission nationale de la recherche, de la science et de la technologie de Namibie a officiellement lanc\u00e9 le rapport d&rsquo;enqu\u00eate sur les infrastructures de recherche du pays, d\u00e9crivant les installations de recherche existantes, les lacunes cl\u00e9s et les domaines prioritaires pour le d\u00e9veloppement. Le rapport a \u00e9t\u00e9 pr\u00e9sent\u00e9 le 3 mars au Centre culturel&hellip;<\/p>\n","protected":false},"author":14,"featured_media":25697,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[161],"tags":[422,213,210,368],"country":[253],"objective":[272],"sg_theme":[146],"class_list":["post-25696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-infrastructure","tag-namibie","tag-research-fr","tag-sgci-fr","country-namibia-fr","objective-develop-industry-fr","sg_theme-research-management"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rapport sur l&#039;am\u00e9lioration des infrastructures de recherche en Namibie - SGCI Africa<\/title>\n<meta name=\"description\" content=\"Le nouveau rapport sur l&#039;am\u00e9lioration des infrastructures de recherche en Namibie r\u00e9v\u00e8le les lacunes cl\u00e9s et les domaines prioritaires pour le d\u00e9veloppement et l&#039;investissement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Namibie lance le rapport national d&#039;enqu\u00eate sur les infrastructures de recherche\" \/>\n<meta property=\"og:description\" content=\"Le nouveau rapport sur l&#039;am\u00e9lioration des infrastructures de recherche en Namibie r\u00e9v\u00e8le les lacunes cl\u00e9s et les domaines prioritaires pour le d\u00e9veloppement et l&#039;investissement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-06T11:29:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-06T11:30:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Titilope Fadare\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Titilope Fadare\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/\"},\"author\":{\"name\":\"Titilope Fadare\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/805409d9d7ecdd7dd47541c544a540ad\"},\"headline\":\"La Namibie lance le rapport national d&rsquo;enqu\u00eate sur les infrastructures de recherche\",\"datePublished\":\"2026-03-06T11:29:30+00:00\",\"dateModified\":\"2026-03-06T11:30:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/\"},\"wordCount\":500,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Launching-of-the-survey-report.jpg\",\"keywords\":[\"Infrastructure\",\"Namibie\",\"Research\",\"SGCI\"],\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/\",\"name\":\"Rapport sur l'am\u00e9lioration des infrastructures de recherche en Namibie - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Launching-of-the-survey-report.jpg\",\"datePublished\":\"2026-03-06T11:29:30+00:00\",\"dateModified\":\"2026-03-06T11:30:50+00:00\",\"description\":\"Le nouveau rapport sur l'am\u00e9lioration des infrastructures de recherche en Namibie r\u00e9v\u00e8le les lacunes cl\u00e9s et les domaines prioritaires pour le d\u00e9veloppement et l'investissement.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Launching-of-the-survey-report.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Launching-of-the-survey-report.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Lancement du rapport d'enqu\u00eate\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Namibie lance le rapport national d&#8217;enqu\u00eate sur les infrastructures de recherche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/805409d9d7ecdd7dd47541c544a540ad\",\"name\":\"Titilope Fadare\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/b7b\\\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/b7b\\\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/b7b\\\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg\",\"caption\":\"Titilope Fadare\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/author\\\/titilopefadare\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rapport sur l'am\u00e9lioration des infrastructures de recherche en Namibie - SGCI Africa","description":"Le nouveau rapport sur l'am\u00e9lioration des infrastructures de recherche en Namibie r\u00e9v\u00e8le les lacunes cl\u00e9s et les domaines prioritaires pour le d\u00e9veloppement et l'investissement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/","og_locale":"fr_FR","og_type":"article","og_title":"La Namibie lance le rapport national d'enqu\u00eate sur les infrastructures de recherche","og_description":"Le nouveau rapport sur l'am\u00e9lioration des infrastructures de recherche en Namibie r\u00e9v\u00e8le les lacunes cl\u00e9s et les domaines prioritaires pour le d\u00e9veloppement et l'investissement.","og_url":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/","og_site_name":"SGCI Africa","article_published_time":"2026-03-06T11:29:30+00:00","article_modified_time":"2026-03-06T11:30:50+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","type":"image\/jpeg"}],"author":"Titilope Fadare","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"\u00c9crit par":"Titilope Fadare","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/"},"author":{"name":"Titilope Fadare","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/805409d9d7ecdd7dd47541c544a540ad"},"headline":"La Namibie lance le rapport national d&rsquo;enqu\u00eate sur les infrastructures de recherche","datePublished":"2026-03-06T11:29:30+00:00","dateModified":"2026-03-06T11:30:50+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/"},"wordCount":500,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","keywords":["Infrastructure","Namibie","Research","SGCI"],"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/","url":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/","name":"Rapport sur l'am\u00e9lioration des infrastructures de recherche en Namibie - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","datePublished":"2026-03-06T11:29:30+00:00","dateModified":"2026-03-06T11:30:50+00:00","description":"Le nouveau rapport sur l'am\u00e9lioration des infrastructures de recherche en Namibie r\u00e9v\u00e8le les lacunes cl\u00e9s et les domaines prioritaires pour le d\u00e9veloppement et l'investissement.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg","width":1080,"height":720,"caption":"Lancement du rapport d'enqu\u00eate"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/la-namibie-lance-le-rapport-national-denquete-sur-les-infrastructures-de-recherche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"La Namibie lance le rapport national d&#8217;enqu\u00eate sur les infrastructures de recherche"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/805409d9d7ecdd7dd47541c544a540ad","name":"Titilope Fadare","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/b7b\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/b7b\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/b7b\/b7b2d6983e10bece6f6b2e19c2ef6976x96.jpg","caption":"Titilope Fadare"},"url":"https:\/\/sgciafrica.org\/fr\/author\/titilopefadare\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-300x200.jpg",300,200,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-768x512.jpg",768,512,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report.jpg",1080,720,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2026\/03\/Launching-of-the-survey-report-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Titilope Fadare","author_link":"https:\/\/sgciafrica.org\/fr\/author\/titilopefadare\/"},"uagb_comment_info":0,"uagb_excerpt":"La Commission nationale de la recherche, de la science et de la technologie de Namibie a officiellement lanc\u00e9 le rapport d&rsquo;enqu\u00eate sur les infrastructures de recherche du pays, d\u00e9crivant les installations de recherche existantes, les lacunes cl\u00e9s et les domaines prioritaires pour le d\u00e9veloppement. Le rapport a \u00e9t\u00e9 pr\u00e9sent\u00e9 le 3 mars au Centre culturel&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/25696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=25696"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/25696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/25697"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=25696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=25696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=25696"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=25696"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/objective?post=25696"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=25696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}