{"id":25338,"date":"2025-11-18T14:51:12","date_gmt":"2025-11-18T14:51:12","guid":{"rendered":"https:\/\/sgciafrica.org\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/"},"modified":"2025-11-21T11:45:09","modified_gmt":"2025-11-21T11:45:09","slug":"lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/","title":{"rendered":"L&rsquo;Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC"},"content":{"rendered":"\n<p>Les leaders africains de la recherche appellent \u00e0 une recherche ax\u00e9e sur l&rsquo;engagement communautaire et la curiosit\u00e9 afin de renforcer l&rsquo;\u00e9cosyst\u00e8me scientifique du continent et de veiller \u00e0 ce que la recherche r\u00e9ponde mieux aux besoins locaux.<\/p>\n\n<p>Cet appel \u00e0 l&rsquo;action a occup\u00e9 le devant de la sc\u00e8ne lors de la r\u00e9union r\u00e9gionale 2025 du <a href=\"https:\/\/www.nrf.ac.za\/from-regional-dialogue-to-global-impact-2025-grc-sub-saharan-africa-regional-meeting-and-sgci-academic-symposium\/\">Conseil mondial de la recherche<\/a> (GRC) pour l&rsquo;Afrique subsaharienne et du symposium acad\u00e9mique de l&rsquo;Initiative des conseils de subventions scientifiques (SGCI), qui se sont tenus \u00e0 Bulawayo, au Zimbabwe, du 10 au 14 novembre. <\/p>\n\n<p>Organis\u00e9 conjointement par le <a href=\"http:\/\/rcz.ac.zw\/\">Conseil de la recherche du Zimbabwe (RCZ)<\/a> et la Fondation nationale pour la recherche (NRF) d&rsquo;Afrique du Sud, cet \u00e9v\u00e9nement a rassembl\u00e9 des responsables du financement de la recherche, des d\u00e9cideurs politiques et des universitaires afin de faire progresser les priorit\u00e9s africaines sous le th\u00e8me <em>\u00ab\u00a0Du dialogue r\u00e9gional \u00e0 l&rsquo;impact mondial<\/em>\u00ab\u00a0.<\/p>\n\n<p>  Il a \u00e9galement \u00e9t\u00e9 l&rsquo;occasion de lancer une nouvelle cohorte de projets de recherche bilat\u00e9raux financ\u00e9s par le SGCI dans toute la r\u00e9gion.<\/p>\n\n<p>Cette ann\u00e9e, les discussions au sein du GRC ont port\u00e9 sur les th\u00e8mes suivants : \u00ab\u00a0R\u00e9imaginer une science ouverte et inclusive pour l&rsquo;\u00e9quit\u00e9, la justice et la durabilit\u00e9\u00a0\u00bb et \u00ab\u00a0La recherche pour des communaut\u00e9s durables\u00a0\u00bb.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"408\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-3_BODY.jpeg\" alt=\"\" class=\"wp-image-25320\" srcset=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-3_BODY.jpeg 996w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-3_BODY-300x123.jpeg 300w, https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-3_BODY-768x315.jpeg 768w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/><\/figure>\n\n<p>D\u00e9velopp\u00e9s par les h\u00f4tes conjoints de la r\u00e9union annuelle du GRC 2026, le <a href=\"https:\/\/www.nserc-crsng.gc.ca\/index_eng.asp\">Conseil de recherches en sciences naturelles et en g\u00e9nie du Canada (CRSNG)<\/a> et le <a href=\"https:\/\/www.tsri.or.th\/\">Thailand Science Research and Innovation (TSRI), les<\/a> th\u00e8mes encouragent les bailleurs de fonds africains \u00e0 r\u00e9fl\u00e9chir \u00e0 la mani\u00e8re dont la science peut profiter \u00e9quitablement aux populations et \u00e0 la plan\u00e8te.<\/p>\n\n<p>La double plateforme de la r\u00e9union r\u00e9gionale du GRC et du symposium acad\u00e9mique du SGCI a permis des \u00e9changes au niveau politique et l&rsquo;engagement des chercheurs, renfor\u00e7ant ainsi les liens entre les m\u00e9canismes de financement et les r\u00e9sultats pratiques de la recherche.<\/p>\n\n<p>Les participants se sont r\u00e9unis lors de tables rondes sur le leadership et de sessions de synth\u00e8se destin\u00e9es \u00e0 fa\u00e7onner la voix de l&rsquo;Afrique en vue de la r\u00e9union annuelle du GRC de 2027.<\/p>\n\n<p>Fulufhelo Nelwamondo, directeur g\u00e9n\u00e9ral de la NRF et membre du conseil d&rsquo;administration du GRC pour l&rsquo;Afrique subsaharienne, s&rsquo;est pench\u00e9 sur le r\u00f4le croissant de l&rsquo;Afrique dans la collaboration mondiale en mati\u00e8re de recherche.<\/p>\n\n<p>Il a appel\u00e9 le continent \u00e0 d\u00e9fendre la recherche guid\u00e9e par la curiosit\u00e9 (CDR) en tant que pierre angulaire du progr\u00e8s scientifique.<\/p>\n\n<p>\u00ab\u00a0La route vers le GRC 2027 commence ici, en Afrique\u00a0\u00bb, a-t-il d\u00e9clar\u00e9. \u00ab\u00a0La recherche fond\u00e9e sur la curiosit\u00e9 est essentielle pour d\u00e9bloquer des d\u00e9couvertes et des innovations transformatrices, et notre d\u00e9fi collectif est de cr\u00e9er des environnements propices \u00e0 l&rsquo;\u00e9panouissement de la curiosit\u00e9.\u00a0\u00bb <\/p>\n\n<p>Il a ajout\u00e9 qu&rsquo;un nouveau programme multilat\u00e9ral de CDR \u00e9tait en cours d&rsquo;\u00e9laboration en collaboration avec les bailleurs de fonds africains et la Fondation allemande pour la recherche (DFG), dans le cadre des efforts visant \u00e0 promouvoir l&rsquo;investissement dans la recherche fondamentale.<\/p>\n\n<p>Le partenariat de longue date entre la NRF et la DFG, y compris les contributions conjointes au GRC, a \u00e9t\u00e9 pr\u00e9sent\u00e9 comme un mod\u00e8le de collaboration.<\/p>\n\n<p>\u00ab\u00a0La NRF se consacre \u00e0 la promotion d&rsquo;un \u00e9cosyst\u00e8me de recherche plus connect\u00e9 et plus collaboratif. Gr\u00e2ce au partenariat, \u00e0 l&rsquo;inclusion et \u00e0 la curiosit\u00e9, nous jetons les bases d&rsquo;un avenir de la recherche mondiale qui profite \u00e0 tous\u00a0\u00bb, a d\u00e9clar\u00e9 M. Nelwamondo.<\/p>\n\n<p>En pronon\u00e7ant le discours d&rsquo;ouverture, Obert Jiri, secr\u00e9taire permanent du Zimbabwe pour les terres, l&rsquo;agriculture, la p\u00eache, l&rsquo;eau et le d\u00e9veloppement rural, a soulign\u00e9 la n\u00e9cessit\u00e9 d&rsquo;une recherche qui r\u00e9ponde directement aux r\u00e9alit\u00e9s de la communaut\u00e9.<\/p>\n\n<p>\u00ab\u00a0La mesure ultime de la recherche r\u00e9side dans son impact sur le terrain, dans la r\u00e9silience et le bien-\u00eatre des communaut\u00e9s\u00a0\u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n\n<p>S&rsquo;appuyant sur des exemples tels que la recherche sur la s\u00e9cheresse avec les petits exploitants agricoles, il a exhort\u00e9 les bailleurs de fonds \u00e0 encourager les propositions ayant des liens \u00e9troits avec la communaut\u00e9 et \u00e0 soutenir les collaborations transfrontali\u00e8res.<\/p>\n\n<p><em>N&rsquo;h\u00e9sitez pas \u00e0 lire les <a href=\"https:\/\/sgciafrica.org\/fr\/actualites\/\">histoires<\/a> et \u00e0 nous faire part de vos commentaires. Nous serions ravis d&rsquo;avoir de vos nouvelles ! <\/em><\/p>\n\n<p><em>Poursuivons la conversation<\/em><em> sur nos m\u00e9dias sociaux<\/em><\/p>\n\n<p><em>Suivez-nous sur <\/em><a href=\"https:\/\/www.linkedin.com\/company\/science-granting-councils-initiative\/\"><em>LinkedIn<\/em><\/a><em> et <\/em><a href=\"https:\/\/x.com\/SGCIAfrica\"><em>X<\/em><\/a><em><\/em><\/p>\n\n<p><em>Publi\u00e9 le 18 novembre 2025<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les leaders africains de la recherche appellent \u00e0 une recherche ax\u00e9e sur l&rsquo;engagement communautaire et la curiosit\u00e9 afin de renforcer l&rsquo;\u00e9cosyst\u00e8me scientifique du continent et de veiller \u00e0 ce que la recherche r\u00e9ponde mieux aux besoins locaux. Cet appel \u00e0 l&rsquo;action a occup\u00e9 le devant de la sc\u00e8ne lors de la r\u00e9union r\u00e9gionale 2025 du&hellip;<\/p>\n","protected":false},"author":13,"featured_media":25324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[161],"tags":[],"country":[],"objective":[],"sg_theme":[],"class_list":["post-25338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC - SGCI Africa<\/title>\n<meta name=\"description\" content=\"Les leaders africains de la recherche appellent \u00e0 une recherche ax\u00e9e sur l&#039;engagement communautaire et la curiosit\u00e9 afin de renforcer l&#039;\u00e9cosyst\u00e8me scientifique du continent et de veiller \u00e0 ce que la recherche r\u00e9ponde mieux aux besoins locaux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC\" \/>\n<meta property=\"og:description\" content=\"Les leaders africains de la recherche appellent \u00e0 une recherche ax\u00e9e sur l&#039;engagement communautaire et la curiosit\u00e9 afin de renforcer l&#039;\u00e9cosyst\u00e8me scientifique du continent et de veiller \u00e0 ce que la recherche r\u00e9ponde mieux aux besoins locaux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-18T14:51:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T11:45:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davis Weddi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davis Weddi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/\"},\"author\":{\"name\":\"Davis Weddi\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\"},\"headline\":\"L&rsquo;Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC\",\"datePublished\":\"2025-11-18T14:51:12+00:00\",\"dateModified\":\"2025-11-21T11:45:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/\"},\"wordCount\":774,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GRC-meeting-Zimbabwe-MAIN.jpeg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/\",\"name\":\"L'Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GRC-meeting-Zimbabwe-MAIN.jpeg\",\"datePublished\":\"2025-11-18T14:51:12+00:00\",\"dateModified\":\"2025-11-21T11:45:09+00:00\",\"description\":\"Les leaders africains de la recherche appellent \u00e0 une recherche ax\u00e9e sur l'engagement communautaire et la curiosit\u00e9 afin de renforcer l'\u00e9cosyst\u00e8me scientifique du continent et de veiller \u00e0 ce que la recherche r\u00e9ponde mieux aux besoins locaux.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GRC-meeting-Zimbabwe-MAIN.jpeg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GRC-meeting-Zimbabwe-MAIN.jpeg\",\"width\":996,\"height\":567,\"caption\":\"GRC meeting Zimbabwe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\",\"name\":\"Davis Weddi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"caption\":\"Davis Weddi\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/author\\\/davisweddi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC - SGCI Africa","description":"Les leaders africains de la recherche appellent \u00e0 une recherche ax\u00e9e sur l'engagement communautaire et la curiosit\u00e9 afin de renforcer l'\u00e9cosyst\u00e8me scientifique du continent et de veiller \u00e0 ce que la recherche r\u00e9ponde mieux aux besoins locaux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC","og_description":"Les leaders africains de la recherche appellent \u00e0 une recherche ax\u00e9e sur l'engagement communautaire et la curiosit\u00e9 afin de renforcer l'\u00e9cosyst\u00e8me scientifique du continent et de veiller \u00e0 ce que la recherche r\u00e9ponde mieux aux besoins locaux.","og_url":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/","og_site_name":"SGCI Africa","article_published_time":"2025-11-18T14:51:12+00:00","article_modified_time":"2025-11-21T11:45:09+00:00","og_image":[{"width":996,"height":567,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg","type":"image\/jpeg"}],"author":"Davis Weddi","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"\u00c9crit par":"Davis Weddi","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/"},"author":{"name":"Davis Weddi","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92"},"headline":"L&rsquo;Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC","datePublished":"2025-11-18T14:51:12+00:00","dateModified":"2025-11-21T11:45:09+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/"},"wordCount":774,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/","url":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/","name":"L'Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg","datePublished":"2025-11-18T14:51:12+00:00","dateModified":"2025-11-21T11:45:09+00:00","description":"Les leaders africains de la recherche appellent \u00e0 une recherche ax\u00e9e sur l'engagement communautaire et la curiosit\u00e9 afin de renforcer l'\u00e9cosyst\u00e8me scientifique du continent et de veiller \u00e0 ce que la recherche r\u00e9ponde mieux aux besoins locaux.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg","width":996,"height":567,"caption":"GRC meeting Zimbabwe"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/lafrique-encourage-la-recherche-communautaire-et-la-curiosite-lors-de-la-reunion-du-grc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Afrique encourage la recherche communautaire et la curiosit\u00e9 lors de la r\u00e9union du GRC"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92","name":"Davis Weddi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","caption":"Davis Weddi"},"url":"https:\/\/sgciafrica.org\/fr\/author\/davisweddi\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg",996,567,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN-150x150.jpeg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN-300x171.jpeg",300,171,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN-768x437.jpeg",768,437,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg",996,567,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg",996,567,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg",996,567,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg",996,567,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg",996,567,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg",996,567,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN.jpeg",996,567,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/GRC-meeting-Zimbabwe-MAIN-90x90.jpeg",90,90,true]},"uagb_author_info":{"display_name":"Davis Weddi","author_link":"https:\/\/sgciafrica.org\/fr\/author\/davisweddi\/"},"uagb_comment_info":0,"uagb_excerpt":"Les leaders africains de la recherche appellent \u00e0 une recherche ax\u00e9e sur l&rsquo;engagement communautaire et la curiosit\u00e9 afin de renforcer l&rsquo;\u00e9cosyst\u00e8me scientifique du continent et de veiller \u00e0 ce que la recherche r\u00e9ponde mieux aux besoins locaux. Cet appel \u00e0 l&rsquo;action a occup\u00e9 le devant de la sc\u00e8ne lors de la r\u00e9union r\u00e9gionale 2025 du&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/25338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=25338"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/25338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/25324"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=25338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=25338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=25338"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=25338"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/objective?post=25338"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=25338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}