{"id":25288,"date":"2025-11-06T13:31:54","date_gmt":"2025-11-06T13:31:54","guid":{"rendered":"https:\/\/sgciafrica.org\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/"},"modified":"2025-11-11T12:09:47","modified_gmt":"2025-11-11T12:09:47","slug":"un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/","title":{"rendered":"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l&rsquo;an\u00e9mie"},"content":{"rendered":"\n<p>Dans de nombreux villages d&rsquo;Ouganda, la fatigue de l&rsquo;an\u00e9mie est le compagnon silencieux d&rsquo;innombrables femmes et enfants.<\/p>\n\n<p>Les m\u00e8res se l\u00e8vent avant l&rsquo;aube pour cuisiner et aller chercher de l&rsquo;eau, tout en luttant contre les vertiges et la faiblesse. Les enfants, eux aussi, luttent pour suivre \u00e0 l&rsquo;\u00e9cole, l&rsquo;esprit embrum\u00e9 par une fatigue chronique et un manque de concentration. <\/p>\n\n<p>Pour Francis Omujal, il \u00e9tait impossible d&rsquo;ignorer ces luttes quotidiennes.<\/p>\n\n<p>\u00ab\u00a0Pr\u00e8s de la moiti\u00e9 des enfants ougandais de moins de cinq ans et plus d&rsquo;un tiers des femmes enceintes souffrent d&rsquo;an\u00e9mie. \u00ab\u00a0Derri\u00e8re ces chiffres se cachent des visages de m\u00e8res qui ne peuvent pas travailler parce qu&rsquo;elles sont faibles, et des enfants dont l&rsquo;apprentissage et la croissance sont retard\u00e9s.\u00a0\u00bb <\/p>\n\n<p>L&rsquo;Ouganda s&rsquo;est engag\u00e9 \u00e0 r\u00e9duire les taux d&rsquo;an\u00e9mie dans le cadre des objectifs mondiaux en mati\u00e8re de nutrition, mais les progr\u00e8s sont au point mort.<\/p>\n\n<p>Les prescriptions habituelles de comprim\u00e9s de fer et d&rsquo;aliments enrichis sont souvent insuffisantes, en particulier dans les communaut\u00e9s rurales o\u00f9 l&rsquo;acc\u00e8s, le co\u00fbt et les effets secondaires d\u00e9sagr\u00e9ables d\u00e9couragent l&rsquo;utilisation continue.<\/p>\n\n<p>Omujal, responsable de la recherche au <a href=\"https:\/\/ncri.go.ug\/\">Natural Chemotherapeutics Research Institute<\/a> en Ouganda, a donc d\u00e9cid\u00e9 de s&rsquo;int\u00e9resser de plus pr\u00e8s aux aliments traditionnels ougandais pour trouver une solution.<\/p>\n\n<p>Ce qu&rsquo;il a trouv\u00e9 dans les jardins locaux s&rsquo;est av\u00e9r\u00e9 \u00eatre une perc\u00e9e scientifique.<\/p>\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-9037b166 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\"  sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_atLocal-market_BODY.jpg\" alt=\"\" width=\"400\" height=\"371\" title=\"\" loading=\"lazy\" role=\"img\"><figcaption class=\"uagb-image-caption\"><em>Betteraves sur un march\u00e9 local.<\/em><\/figcaption><\/figure><\/div>\n\n<p>Soutenue par la Science Granting Councils Initiative (SGCI) par l&rsquo;interm\u00e9diaire du <a href=\"https:\/\/uncst.go.ug\/\">Conseil national ougandais pour la science et la technologie (UNCST)<\/a>, sa recherche s&rsquo;est concentr\u00e9e sur le d\u00e9veloppement d&rsquo;un nutraceutique enrichi en fer \u00e0 base de betterave pour lutter contre l&rsquo;an\u00e9mie en utilisant des aliments disponibles localement.<\/p>\n\n<p>Les nutraceutiques font partie des aliments qui offrent des avantages suppl\u00e9mentaires pour la sant\u00e9 au-del\u00e0 de leur valeur nutritionnelle de base, tels que les produits \u00e0 base de plantes et les compl\u00e9ments alimentaires.<\/p>\n\n<p>Son \u00e9quipe a d\u00e9couvert que la consommation r\u00e9guli\u00e8re de betteraves enrichies en fer pouvait acc\u00e9l\u00e9rer la gu\u00e9rison de l&rsquo;an\u00e9mie chez les m\u00e8res et les enfants de moins de cinq ans, r\u00e9duisant ainsi la mortalit\u00e9 et am\u00e9liorant le bien-\u00eatre.<\/p>\n\n<p>Les compos\u00e9s de b\u00e9tala\u00efne naturellement pr\u00e9sents dans la betterave am\u00e9liorent l&rsquo;absorption du fer jusqu&rsquo;\u00e0 50 %, ce qui favorise l&rsquo;augmentation du taux d&rsquo;h\u00e9moglobine, la r\u00e9duction de la fatigue et une plus grande vitalit\u00e9. La production locale de betteraves rouges peut \u00e9galement cr\u00e9er des emplois dans les domaines de l&rsquo;agriculture et de la transformation, ce qui permet aux communaut\u00e9s rurales de se prendre en charge. <\/p>\n\n<p><strong>Alimentation locale, science locale<\/strong><strong><\/strong><\/p>\n\n<p>\u00ab\u00a0En Ouganda, les gens utilisent d\u00e9j\u00e0 la betterave comme rem\u00e8de maison contre l&rsquo;an\u00e9mie\u00a0\u00bb, explique M. Omujal. \u00ab\u00a0Mais personne ne comprenait vraiment comment cela fonctionnait. <\/p>\n\n<p>Curieux, il a explor\u00e9 la chimie nutritionnelle de la betterave et d\u00e9couvert que ses pigments naturels, les b\u00e9tala\u00efnes, ne se contentent pas de lui donner une couleur rouge profond, mais aident l&rsquo;organisme \u00e0 absorber le fer plus efficacement.<\/p>\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-7e6e07ff wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\"  sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Powdered-beetroot-ready-for-sale_BODY.jpg\" alt=\"Betterave en poudre pr\u00eate \u00e0 la vente\" width=\"500\" height=\"404\" title=\"Betterave en poudre\" loading=\"lazy\" role=\"img\"><figcaption class=\"uagb-image-caption\"><em>Betterave en poudre pr\u00eate \u00e0 la vente<\/em><\/figcaption><\/figure><\/div>\n\n<p>La betterave contient des acides organiques et des antioxydants qui rendent le fer alimentaire plus biodisponible. \u00ab\u00a0Nous avons vu qu&rsquo;il \u00e9tait possible de transformer cet aliment traditionnel en un produit nutraceutique scientifiquement valid\u00e9. <\/p>\n\n<p>Son \u00e9quipe a enrichi la betterave en fer en utilisant une m\u00e9thode de traitement \u00e0 froid, une technique qui pr\u00e9serve les compos\u00e9s de b\u00e9tala\u00efne et la vitamine C, tous deux essentiels \u00e0 l&rsquo;absorption du fer.<\/p>\n\n<p>\u00ab\u00a0Si vous chauffez trop la betterave, vous d\u00e9truisez ces compos\u00e9s\u00a0\u00bb, explique-t-il. \u00ab\u00a0Notre m\u00e9thode de traitement \u00e0 froid les maintient actifs, ce qui rend le produit plus efficace. <\/p>\n\n<p>Les r\u00e9sultats des tests effectu\u00e9s en laboratoire sont frappants.<\/p>\n\n<p>En l&rsquo;espace de dix jours, les principaux marqueurs sanguins tels que l&rsquo;h\u00e9moglobine et le nombre de globules rouges ont montr\u00e9 une am\u00e9lioration significative.<\/p>\n\n<p>Les r\u00e9sultats ont \u00e9galement d\u00e9montr\u00e9 l&rsquo;innocuit\u00e9 du produit, qui ne pr\u00e9sente aucune modification des enzymes h\u00e9patiques, des biomarqueurs r\u00e9naux ou des profils lipidiques.<\/p>\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-50c4456c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\"  sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Powdered-beetroot_Satchets_BODY.jpg\" alt=\"Des betteraves magnifiquement emball\u00e9es\" width=\"500\" height=\"404\" title=\"Des betteraves magnifiquement emball\u00e9es\" loading=\"lazy\" role=\"img\"><figcaption class=\"uagb-image-caption\"><em>Des betteraves magnifiquement emball\u00e9es<\/em><\/figcaption><\/figure><\/div>\n\n<p>\u00ab\u00a0Il \u00e9tait passionnant de constater une gu\u00e9rison aussi rapide\u00a0\u00bb, d\u00e9clare Omujal. \u00ab\u00a0La formulation s&rsquo;est av\u00e9r\u00e9e s\u00fbre pour les enfants et les femmes enceintes. <\/p>\n\n<p>La betterave est un excellent candidat pour un suppl\u00e9ment antian\u00e9mique enrichi, car elle est naturelle, disponible localement tout au long de l&rsquo;ann\u00e9e et facile \u00e0 transformer et \u00e0 stocker, explique M. Omujal.<\/p>\n\n<p>La poudre se dissout facilement dans l&rsquo;eau froide, ne n\u00e9cessite pas de cuisson et offre un go\u00fbt agr\u00e9able et une couleur attrayante, ce qui la rend pratique pour un usage quotidien.<\/p>\n\n<p><strong>Au-del\u00e0 des pilules  <\/strong><strong><\/strong><\/p>\n\n<p>Contrairement aux suppl\u00e9ments import\u00e9s, le produit d&rsquo;Omujal, \u00e0 base de betterave, s&rsquo;appuie sur les propres ressources agricoles de l&rsquo;Ouganda. La poudre est con\u00e7ue pour \u00eatre facilement m\u00e9lang\u00e9e \u00e0 du jus ou de l&rsquo;eau, offrant ainsi un moyen abordable, familier et naturel de g\u00e9rer l&rsquo;an\u00e9mie. <\/p>\n\n<p>\u00ab\u00a0Les betteraves poussent localement tout au long de l&rsquo;ann\u00e9e\u00a0\u00bb, explique-t-il. \u00ab\u00a0Nous nous approvisionnons aupr\u00e8s de petits exploitants agricoles, nous transformons le produit \u00e0 proximit\u00e9 et nous maintenons la cha\u00eene de valeur au sein de la communaut\u00e9. <\/p>\n\n<p>Ce lien local a des effets en cha\u00eene. Il cr\u00e9e de nouvelles sources de revenus pour les producteurs et les transformateurs ruraux, en particulier les femmes. <\/p>\n\n<p>\u00ab\u00a0Si nous parvenons \u00e0 augmenter la production, nous ne nous contenterons pas d&rsquo;am\u00e9liorer la sant\u00e9, nous renforcerons \u00e9galement les moyens de subsistance\u00a0\u00bb, note M. Omujal.<\/p>\n\n<p><strong>Pourquoi les approches actuelles sont insuffisantes<\/strong><strong><\/strong><\/p>\n\n<p>Les programmes ougandais de pr\u00e9vention de l&rsquo;an\u00e9mie reposent essentiellement sur des comprim\u00e9s de fer et des aliments enrichis. Mais de nombreuses femmes arr\u00eatent de prendre les comprim\u00e9s en raison de naus\u00e9es, de constipation ou d&rsquo;un go\u00fbt m\u00e9tallique. <\/p>\n\n<p>Dans les r\u00e9gions recul\u00e9es, les cha\u00eenes d&rsquo;approvisionnement ne sont pas fiables et les aliments enrichis ne parviennent souvent pas aux familles les plus pauvres.<\/p>\n\n<p>\u00ab\u00a0M\u00eame lorsque les gens consomment des aliments contenant du fer, la plupart d&rsquo;entre eux sont du type non h\u00e9mique provenant des plantes\u00a0\u00bb, explique Omujal.<\/p>\n\n<p>Le fer non h\u00e9minique est le fer alimentaire que l&rsquo;on trouve dans les aliments d&rsquo;origine v\u00e9g\u00e9tale tels que les haricots, les lentilles, les \u00e9pinards, les noix, les graines et les c\u00e9r\u00e9ales enrichies. Cette forme de fer est moins facilement absorb\u00e9e par l&rsquo;organisme. <\/p>\n\n<p>\u00ab\u00a0Il est plus difficile pour l&rsquo;organisme de l&rsquo;absorber, surtout lorsque l&rsquo;alimentation comprend \u00e9galement du th\u00e9, du caf\u00e9 ou du lait, qui inhibent l&rsquo;absorption du fer.\u00a0\u00bb<\/p>\n\n<p>De nombreux r\u00e9gimes alimentaires ougandais reposent fortement sur des f\u00e9culents tels que le matooke, le manioc et le ma\u00efs, qui ont une faible teneur en fer biodisponible et autres micronutriments essentiels.<\/p>\n\n<p>Ensuite, la cuisson prolong\u00e9e des l\u00e9gumes d\u00e9truit la vitamine C, qui favorise l&rsquo;absorption du fer.<\/p>\n\n<p>Les tabous culturels emp\u00eachent les femmes enceintes de manger des \u0153ufs ou du foie et, dans certains foyers, les hommes et les membres plus \u00e2g\u00e9s de la famille sont servis en premier, laissant aux femmes et aux enfants des portions moins nutritives.<\/p>\n\n<p>\u00ab\u00a0La culture alimentaire, la pauvret\u00e9 et le manque d&rsquo;\u00e9ducation nutritionnelle se conjuguent pour cr\u00e9er une temp\u00eate parfaite\u00a0\u00bb, explique-t-il.<\/p>\n\n<p>Les programmes qui se concentrent \u00e9troitement sur le fer n\u00e9gligent \u00e9galement les r\u00f4les de l&rsquo;acide folique, de la vitamine B12 et de la vitamine C dans la formation des globules rouges, et les fr\u00e9quentes ruptures de stock ainsi que le co\u00fbt \u00e9lev\u00e9 des suppl\u00e9ments en limitent encore l&rsquo;acc\u00e8s.<\/p>\n\n<p><strong>De la recherche \u00e0 l&rsquo;impact sur le monde r\u00e9el<\/strong><strong><\/strong><\/p>\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-3fefc362 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\"  sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/The-researchers-demonstrating-the-cold-processing-method-for-beetroot_BODY.jpg\" alt=\"Les chercheurs d\u00e9montrent la m\u00e9thode de traitement \u00e0 froid de la betterave.\" width=\"425\" height=\"567\" title=\"Les chercheurs d\u00e9montrent la m\u00e9thode de traitement \u00e0 froid de la betterave.\" loading=\"lazy\" role=\"img\"><figcaption class=\"uagb-image-caption\"><em>D\u00e9monstration de la m\u00e9thode de transformation \u00e0 froid de la betterave rouge<\/em><\/figcaption><\/figure><\/div>\n\n<p>Gr\u00e2ce au financement de la SGCI et de l&rsquo;UNCST, Omujal et son \u00e9quipe ont fait passer leur innovation de la phase conceptuelle \u00e0 la phase pilote, en formulant le produit \u00e0 base de betteraves enrichies, en menant des exp\u00e9riences et en mettant en place une production, un conditionnement et une distribution \u00e0 petite \u00e9chelle.<\/p>\n\n<p>\u00ab\u00a0L&rsquo;aide nous a permis d&rsquo;acheter de la betterave brute \u00e0 des agriculteurs locaux, des ingr\u00e9dients de fortification et de mettre en place une production \u00e0 petite \u00e9chelle\u00a0\u00bb, explique-t-il.<\/p>\n\n<p>\u00ab\u00a0Aujourd&rsquo;hui, les gens peuvent se procurer le produit sous forme de poudre dans les pharmacies et les supermarch\u00e9s.<\/p>\n\n<p>Des essais cliniques sont pr\u00e9vus pour d\u00e9terminer le dosage optimal, la s\u00e9curit\u00e9 et les effets \u00e0 long terme.<\/p>\n\n<p>Les versions futures pourraient inclure des collations adapt\u00e9es aux enfants ou des boissons enrichies con\u00e7ues pour les femmes en \u00e2ge de procr\u00e9er.<\/p>\n\n<p><strong>Une vision pour des g\u00e9n\u00e9rations plus saines<\/strong><strong><\/strong><\/p>\n\n<p>Pour Omujal, la vision va bien au-del\u00e0 du laboratoire.<\/p>\n\n<p>Le projet s&rsquo;inscrit dans le cadre de l&rsquo;engagement de l&rsquo;Ouganda envers les <a href=\"https:\/\/www.who.int\/teams\/nutrition-and-food-safety\/global-targets-2030\">objectifs mondiaux de nutrition de l&rsquo;Assembl\u00e9e mondiale de la sant\u00e9<\/a> et illustre la mani\u00e8re dont la recherche men\u00e9e au niveau local peut \u00e9clairer les politiques et renforcer les syst\u00e8mes de sant\u00e9 communautaires.<\/p>\n\n<p>Il incarne la vision de la SGCI, qui consiste \u00e0 donner aux scientifiques africains les moyens de concevoir des solutions ancr\u00e9es dans les r\u00e9alit\u00e9s locales et fond\u00e9es sur l&rsquo;excellence scientifique.<\/p>\n\n<p>\u00ab\u00a0Cette innovation ne se limite pas au traitement de l&rsquo;an\u00e9mie\u00a0\u00bb, pr\u00e9cise-t-il. \u00ab\u00a0Il s&rsquo;agit de donner de la force aux m\u00e8res, d&rsquo;aider les enfants \u00e0 devenir plus intelligents et plus forts, et d&rsquo;utiliser nos propres aliments pour r\u00e9soudre nos propres probl\u00e8mes\u00a0\u00bb. <\/p>\n\n<p><em>Consultez les <\/em><a href=\"https:\/\/sgciafrica.org\/fr\/actualites\/\"><em>histoires<\/em><\/a><em>  et dites-nous ce que vous en pensez. Nous serions ravis d&rsquo;avoir de vos nouvelles ! <\/em><\/p>\n\n<p><em>Poursuivons la conversation<\/em><em> sur nos m\u00e9dias sociaux<\/em><\/p>\n\n<p><em>Suivez-nous sur <\/em><a href=\"https:\/\/www.linkedin.com\/company\/science-granting-councils-initiative\/\"><em>LinkedIn<\/em><\/a><em> et <\/em><a href=\"https:\/\/x.com\/SGCIAfrica\"><em>X<\/em><\/a><em><\/em><\/p>\n\n<p><em>Publi\u00e9 le 6 novembre 2025<\/em><\/p>\n\n<p><em>\u00c9crit par Jackie Opara-Fatoye<\/em><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans de nombreux villages d&rsquo;Ouganda, la fatigue de l&rsquo;an\u00e9mie est le compagnon silencieux d&rsquo;innombrables femmes et enfants. Les m\u00e8res se l\u00e8vent avant l&rsquo;aube pour cuisiner et aller chercher de l&rsquo;eau, tout en luttant contre les vertiges et la faiblesse. Les enfants, eux aussi, luttent pour suivre \u00e0 l&rsquo;\u00e9cole, l&rsquo;esprit embrum\u00e9 par une fatigue chronique et&hellip;<\/p>\n","protected":false},"author":13,"featured_media":25255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[161],"tags":[],"country":[],"objective":[],"sg_theme":[],"class_list":["post-25288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un scientifique ougandais transforme la betterave en rem\u00e8de contre l&#039;an\u00e9mie - SGCI Africa<\/title>\n<meta name=\"description\" content=\"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l&#039;an\u00e9mie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l&#039;an\u00e9mie\" \/>\n<meta property=\"og:description\" content=\"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l&#039;an\u00e9mie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T13:31:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T12:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davis Weddi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davis Weddi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/\"},\"author\":{\"name\":\"Davis Weddi\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\"},\"headline\":\"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l&rsquo;an\u00e9mie\",\"datePublished\":\"2025-11-06T13:31:54+00:00\",\"dateModified\":\"2025-11-11T12:09:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/\"},\"wordCount\":1715,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Beetroot_Main.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/\",\"name\":\"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l'an\u00e9mie - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Beetroot_Main.jpg\",\"datePublished\":\"2025-11-06T13:31:54+00:00\",\"dateModified\":\"2025-11-11T12:09:47+00:00\",\"description\":\"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l'an\u00e9mie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Beetroot_Main.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Beetroot_Main.jpg\",\"width\":996,\"height\":567,\"caption\":\"Photo by Marcelo Verfe: https:\\\/\\\/www.pexels.com\\\/photo\\\/fresh-organic-beetroots-on-wooden-surface-29436276\\\/\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l&rsquo;an\u00e9mie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\",\"name\":\"Davis Weddi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"caption\":\"Davis Weddi\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/author\\\/davisweddi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l'an\u00e9mie - SGCI Africa","description":"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l'an\u00e9mie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/","og_locale":"fr_FR","og_type":"article","og_title":"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l'an\u00e9mie","og_description":"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l'an\u00e9mie","og_url":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/","og_site_name":"SGCI Africa","article_published_time":"2025-11-06T13:31:54+00:00","article_modified_time":"2025-11-11T12:09:47+00:00","og_image":[{"width":996,"height":567,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg","type":"image\/jpeg"}],"author":"Davis Weddi","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"\u00c9crit par":"Davis Weddi","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/"},"author":{"name":"Davis Weddi","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92"},"headline":"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l&rsquo;an\u00e9mie","datePublished":"2025-11-06T13:31:54+00:00","dateModified":"2025-11-11T12:09:47+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/"},"wordCount":1715,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/","url":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/","name":"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l'an\u00e9mie - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg","datePublished":"2025-11-06T13:31:54+00:00","dateModified":"2025-11-11T12:09:47+00:00","description":"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l'an\u00e9mie","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg","width":996,"height":567,"caption":"Photo by Marcelo Verfe: https:\/\/www.pexels.com\/photo\/fresh-organic-beetroots-on-wooden-surface-29436276\/"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/un-scientifique-ougandais-transforme-la-betterave-en-remede-contre-lanemie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Un scientifique ougandais transforme la betterave en rem\u00e8de contre l&rsquo;an\u00e9mie"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92","name":"Davis Weddi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","caption":"Davis Weddi"},"url":"https:\/\/sgciafrica.org\/fr\/author\/davisweddi\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg",996,567,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main-300x171.jpg",300,171,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main-768x437.jpg",768,437,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg",996,567,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg",996,567,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg",996,567,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg",996,567,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg",996,567,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg",996,567,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main.jpg",996,567,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/11\/Beetroot_Main-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Davis Weddi","author_link":"https:\/\/sgciafrica.org\/fr\/author\/davisweddi\/"},"uagb_comment_info":0,"uagb_excerpt":"Dans de nombreux villages d&rsquo;Ouganda, la fatigue de l&rsquo;an\u00e9mie est le compagnon silencieux d&rsquo;innombrables femmes et enfants. Les m\u00e8res se l\u00e8vent avant l&rsquo;aube pour cuisiner et aller chercher de l&rsquo;eau, tout en luttant contre les vertiges et la faiblesse. Les enfants, eux aussi, luttent pour suivre \u00e0 l&rsquo;\u00e9cole, l&rsquo;esprit embrum\u00e9 par une fatigue chronique et&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/25288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=25288"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/25288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/25255"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=25288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=25288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=25288"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=25288"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/objective?post=25288"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=25288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}