{"id":25156,"date":"2025-10-06T13:16:28","date_gmt":"2025-10-06T12:16:28","guid":{"rendered":"https:\/\/sgciafrica.org\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/"},"modified":"2025-10-06T13:17:42","modified_gmt":"2025-10-06T12:17:42","slug":"appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/","title":{"rendered":"Appel \u00e0 consultation d&rsquo;experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est"},"content":{"rendered":"\n<p>L&rsquo;Institut international pour l&rsquo;analyse des syst\u00e8mes appliqu\u00e9s (IIASA) et la Commission du bassin du lac Victoria (LVBC) invitent des experts qualifi\u00e9s \u00e0 contribuer \u00e0 une \u00e9tude de cadrage et \u00e0 un rapport d&rsquo;\u00e9valuation sur \u00ab\u00a0La dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est\u00a0\u00bb.<\/p>\n\n<p>La consultance fournira une contribution technique au projet d&rsquo;\u00e9tude de recherche pour le d\u00e9veloppement, <em>Enhancing Resilience to Extreme Drought Events in East Africa (INTERVENE)<\/em>, qui est financ\u00e9 par la Coop\u00e9ration autrichienne au d\u00e9veloppement.<\/p>\n\n<p><strong>Contexte et historique<\/strong><\/p>\n\n<p>Le changement climatique augmente la fr\u00e9quence et l&rsquo;intensit\u00e9 des s\u00e9cheresses en Afrique de l&rsquo;Est, mena\u00e7ant la croissance \u00e9conomique, les \u00e9cosyst\u00e8mes et les moyens de subsistance. Une gestion efficace de la s\u00e9cheresse n\u00e9cessite des strat\u00e9gies, des comp\u00e9tences et des technologies d&rsquo;adaptation. En Afrique subsaharienne, les femmes jouent un r\u00f4le essentiel dans l&rsquo;adaptation \u00e0 la s\u00e9cheresse en raison de leur contribution \u00e0 l&rsquo;agriculture et de leurs responsabilit\u00e9s en mati\u00e8re d&rsquo;eau, d&rsquo;assainissement et d&rsquo;hygi\u00e8ne (WASH).  <\/p>\n\n<p>Le projet INTERVENE vise \u00e0 renforcer la r\u00e9sistance \u00e0 la s\u00e9cheresse en am\u00e9liorant la compr\u00e9hension des impacts de la s\u00e9cheresse et en identifiant les voies d&rsquo;adaptation dans la Communaut\u00e9 d&rsquo;Afrique de l&rsquo;Est (CAE). Le projet de trois ans, mis en \u0153uvre par le groupe de s\u00e9curit\u00e9 de l&rsquo;eau de l&rsquo;IIASA en partenariat avec LVBC, se concentre sur trois domaines de r\u00e9sultats interconnect\u00e9s : <\/p>\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Sensibilisation aux aspects sexosp\u00e9cifiques de la r\u00e9sistance \u00e0 la s\u00e9cheresse.<\/li>\n\n\n\n<li>\u00c9laborer des strat\u00e9gies et des plans d&rsquo;action de pr\u00e9paration et de r\u00e9action \u00e0 la s\u00e9cheresse.<\/li>\n\n\n\n<li>Am\u00e9liorer la capacit\u00e9 de r\u00e9sistance \u00e0 la s\u00e9cheresse pour informer les politiques et les pratiques.<\/li>\n<\/ol>\n\n<p><strong>Objectif de la mission<\/strong><\/p>\n\n<p>L&rsquo;objectif est de faire le point sur la pr\u00e9paration \u00e0 la s\u00e9cheresse dans les pays de l&rsquo;EAC :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Examiner les politiques, la planification et les cadres de gestion actuels en mati\u00e8re de s\u00e9cheresse, y compris les aspects li\u00e9s \u00e0 l&rsquo;\u00e9galit\u00e9 entre les hommes et les femmes.<\/li>\n\n\n\n<li>Identifier l&rsquo;exp\u00e9rience et les connaissances existantes en mati\u00e8re de lutte contre la s\u00e9cheresse.<\/li>\n<\/ul>\n\n<p>L&rsquo;objectif est d&rsquo;identifier les lacunes et les possibilit\u00e9s de renforcer la pr\u00e9paration \u00e0 la s\u00e9cheresse et de fournir des informations essentielles pour les activit\u00e9s en cours et les cadres de mod\u00e9lisation du projet INTERVENE.<\/p>\n\n<p><strong>Description de la mission<\/strong><\/p>\n\n<p>Chaque consultant se concentrera sur un pays de la CAE &#8211; Burundi, RD Congo, Kenya, Rwanda, Somalie, Soudan du Sud, Tanzanie ou Ouganda &#8211; et compilera des informations sur :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Les cadres politiques et institutionnels actuels pour la r\u00e9silience \u00e0 la s\u00e9cheresse.<\/li>\n\n\n\n<li>L&rsquo;importance de la dimension de genre dans les politiques et strat\u00e9gies li\u00e9es \u00e0 la s\u00e9cheresse.<\/li>\n\n\n\n<li>Strat\u00e9gies historiques de r\u00e9ponse \u00e0 la s\u00e9cheresse.<\/li>\n<\/ul>\n\n<p>L&rsquo;\u00e9valuation comprendra une \u00e9tude documentaire et des entretiens avec les parties prenantes (5-6 par pays). Les consultants participeront \u00e0 des r\u00e9unions d&rsquo;information et de coordination, rempliront un questionnaire sur la s\u00e9cheresse, pr\u00e9pareront un rapport national de 12 pages et pr\u00e9senteront les r\u00e9sultats lors d&rsquo;un s\u00e9minaire virtuel. Ils contribueront \u00e9galement au rapport d&rsquo;\u00e9valuation final sur la gestion de la s\u00e9cheresse sensible au genre.  <\/p>\n\n<p><strong>Qualifications et comp\u00e9tences<\/strong><\/p>\n\n<p>Les candidats doivent \u00eatre titulaires d&rsquo;un dipl\u00f4me universitaire et avoir au moins trois ans d&rsquo;exp\u00e9rience dans la gestion durable des ressources en eau et en terres, l&rsquo;adaptation au changement climatique et les consid\u00e9rations de genre dans les \u00e9valuations de la r\u00e9silience. De solides comp\u00e9tences en communication et en r\u00e9daction de rapports en anglais sont requises. <\/p>\n\n<p><strong>Dur\u00e9e et r\u00e9mun\u00e9ration<\/strong><\/p>\n\n<p>La mission commence \u00e0 la signature du contrat et dure un an. Le budget maximum allou\u00e9 est de 5 000 euros par pays, tout compris. Les paiements seront effectu\u00e9s en trois tranches :  <\/p>\n\n<ul class=\"wp-block-list\">\n<li>20 % apr\u00e8s avoir accompli les t\u00e2ches 1-2<\/li>\n\n\n\n<li>60 % apr\u00e8s avoir soumis le questionnaire rempli (t\u00e2ches 3 \u00e0 7)<\/li>\n\n\n\n<li>20 % apr\u00e8s l&rsquo;examen final et la contribution au rapport d&rsquo;\u00e9valuation<\/li>\n<\/ul>\n\n<p><strong>Modalit\u00e9s de gestion<\/strong><\/p>\n\n<p>La consultation sera coordonn\u00e9e par l&rsquo;\u00e9quipe INTERVENE de l&rsquo;IIASA, dirig\u00e9e par Sylvia Tramberend<a href=\"mailto:trambers@iiasa.ac.at\">(trambers@iiasa.ac.at)<\/a>, avec le soutien de LVBC.<\/p>\n\n<p><strong>Proc\u00e9dure de candidature<\/strong><\/p>\n\n<p>Les experts int\u00e9ress\u00e9s doivent :<\/p>\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Compl\u00e9tez le formulaire en ligne <a href=\"https:\/\/forms.office.com\/e\/TqrEqaqkVh\">: https:\/\/forms.office.com\/e\/TqrEqaqkVh<\/a><\/li>\n\n\n\n<li>Soumettez votre CV et vos qualifications par courrier \u00e9lectronique.<\/li>\n\n\n\n<li>Joignez une offre financi\u00e8re (en euros) couvrant les frais de personnel et les frais divers.<\/li>\n<\/ol>\n\n<p>Les candidatures doivent \u00eatre soumises avant le 15 octobre 2025 \u00e0 l&rsquo;adresse suivante :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Sylvia Tramberend<a href=\"mailto:trambers@iiasa.ac.at\">(trambers@iiasa.ac.at)<\/a><\/li>\n\n\n\n<li>CC<strong>:<\/strong> Sam Knights<a href=\"mailto:knights@iiasa.ac.at\">(knights@iiasa.ac.at<\/a>) et Paul Kariuki<a href=\"mailto:kariuki@lvbcom.org\">(kariuki@lvbcom.org<\/a>)<\/li>\n<\/ul>\n\n<p>Objet de l&rsquo;e-mail : <em>Expert local INTERVENE &#8211; [Nom du pays]<\/em> (par exemple, \u00ab\u00a0Expert local INTERVENE &#8211; BURUNDI\u00a0\u00bb).<\/p>\n\n<p>Les experts peuvent poser leur candidature pour deux pays au maximum s&rsquo;ils s&rsquo;appuient sur leur expertise.<\/p>\n\n<p><strong>T\u00e9l\u00e9chargez TOR &gt;&gt;<a href=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/ToR_Local-Expert_INTERVENE.pdf\">ICI<\/a><\/strong>&lt;&lt;<\/p>\n\n<p>N&rsquo;h\u00e9sitez pas \u00e0 lire les <a href=\"https:\/\/sgciafrica.org\/fr\/actualites\/\">histoires<\/a> et \u00e0 nous faire part de vos commentaires. Nous serions ravis d&rsquo;avoir de vos nouvelles ! <\/p>\n\n<p>Poursuivons la conversation sur nos m\u00e9dias sociaux<\/p>\n\n<p>Suivez-nous sur <a href=\"https:\/\/www.linkedin.com\/company\/science-granting-councils-initiative\/\">LinkedIn<\/a> et <a href=\"https:\/\/x.com\/SGCIAfrica\">X<\/a><\/p>\n\n<p><em>Publi\u00e9 le 6 octobre 2025<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Institut international pour l&rsquo;analyse des syst\u00e8mes appliqu\u00e9s (IIASA) et la Commission du bassin du lac Victoria (LVBC) invitent des experts qualifi\u00e9s \u00e0 contribuer \u00e0 une \u00e9tude de cadrage et \u00e0 un rapport d&rsquo;\u00e9valuation sur \u00ab\u00a0La dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est\u00a0\u00bb. La consultance fournira une contribution&hellip;<\/p>\n","protected":false},"author":13,"featured_media":25150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[161],"tags":[],"country":[],"objective":[],"sg_theme":[],"class_list":["post-25156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Appel \u00e0 consultation d&#039;experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&#039;Est - SGCI Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appel \u00e0 consultation d&#039;experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&#039;Est\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;Institut international pour l&rsquo;analyse des syst\u00e8mes appliqu\u00e9s (IIASA) et la Commission du bassin du lac Victoria (LVBC) invitent des experts qualifi\u00e9s \u00e0 contribuer \u00e0 une \u00e9tude de cadrage et \u00e0 un rapport d&rsquo;\u00e9valuation sur \u00ab\u00a0La dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est\u00a0\u00bb. La consultance fournira une contribution&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-06T12:16:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T12:17:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davis Weddi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davis Weddi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/\"},\"author\":{\"name\":\"Davis Weddi\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\"},\"headline\":\"Appel \u00e0 consultation d&rsquo;experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est\",\"datePublished\":\"2025-10-06T12:16:28+00:00\",\"dateModified\":\"2025-10-06T12:17:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/\"},\"wordCount\":907,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/\",\"name\":\"Appel \u00e0 consultation d'experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l'Est - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg\",\"datePublished\":\"2025-10-06T12:16:28+00:00\",\"dateModified\":\"2025-10-06T12:17:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg\",\"width\":996,\"height\":567,\"caption\":\"A cross section of SGCI members at the 2025 all partners meeting\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appel \u00e0 consultation d&rsquo;experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\",\"name\":\"Davis Weddi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"caption\":\"Davis Weddi\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/author\\\/davisweddi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Appel \u00e0 consultation d'experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l'Est - SGCI Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/","og_locale":"fr_FR","og_type":"article","og_title":"Appel \u00e0 consultation d'experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l'Est","og_description":"L&rsquo;Institut international pour l&rsquo;analyse des syst\u00e8mes appliqu\u00e9s (IIASA) et la Commission du bassin du lac Victoria (LVBC) invitent des experts qualifi\u00e9s \u00e0 contribuer \u00e0 une \u00e9tude de cadrage et \u00e0 un rapport d&rsquo;\u00e9valuation sur \u00ab\u00a0La dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est\u00a0\u00bb. La consultance fournira une contribution&hellip;","og_url":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/","og_site_name":"SGCI Africa","article_published_time":"2025-10-06T12:16:28+00:00","article_modified_time":"2025-10-06T12:17:42+00:00","og_image":[{"width":996,"height":567,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg","type":"image\/jpeg"}],"author":"Davis Weddi","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"\u00c9crit par":"Davis Weddi","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/"},"author":{"name":"Davis Weddi","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92"},"headline":"Appel \u00e0 consultation d&rsquo;experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est","datePublished":"2025-10-06T12:16:28+00:00","dateModified":"2025-10-06T12:17:42+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/"},"wordCount":907,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/","url":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/","name":"Appel \u00e0 consultation d'experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l'Est - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg","datePublished":"2025-10-06T12:16:28+00:00","dateModified":"2025-10-06T12:17:42+00:00","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg","width":996,"height":567,"caption":"A cross section of SGCI members at the 2025 all partners meeting"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/appel-a-consultation-dexperts-dimension-intersectionnelle-de-la-gestion-de-la-secheresse-sensible-au-genre-en-afrique-de-lest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Appel \u00e0 consultation d&rsquo;experts : Dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92","name":"Davis Weddi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","caption":"Davis Weddi"},"url":"https:\/\/sgciafrica.org\/fr\/author\/davisweddi\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg",996,567,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN-300x171.jpg",300,171,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN-768x437.jpg",768,437,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg",996,567,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg",996,567,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg",996,567,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg",996,567,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg",996,567,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg",996,567,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN.jpg",996,567,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/10\/A-cross-section-of-SGCI-members-at-the-2025-all-partners-meeting_MAIN-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Davis Weddi","author_link":"https:\/\/sgciafrica.org\/fr\/author\/davisweddi\/"},"uagb_comment_info":0,"uagb_excerpt":"L&rsquo;Institut international pour l&rsquo;analyse des syst\u00e8mes appliqu\u00e9s (IIASA) et la Commission du bassin du lac Victoria (LVBC) invitent des experts qualifi\u00e9s \u00e0 contribuer \u00e0 une \u00e9tude de cadrage et \u00e0 un rapport d&rsquo;\u00e9valuation sur \u00ab\u00a0La dimension intersectionnelle de la gestion de la s\u00e9cheresse sensible au genre en Afrique de l&rsquo;Est\u00a0\u00bb. La consultance fournira une contribution&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/25156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=25156"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/25156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/25150"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=25156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=25156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=25156"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=25156"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/objective?post=25156"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=25156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}