{"id":24753,"date":"2025-07-25T12:56:34","date_gmt":"2025-07-25T11:56:34","guid":{"rendered":"https:\/\/sgciafrica.org\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/"},"modified":"2025-09-08T13:24:34","modified_gmt":"2025-09-08T12:24:34","slug":"les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/","title":{"rendered":"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens"},"content":{"rendered":"<p>[A Ayigbe, une communaut\u00e9 rurale de la r\u00e9gion de Bono au Ghana, Michael Kyereme, 35 ans, a rembours\u00e9 une dette universitaire de 3 500 GHS (335 USD) en seulement trois mois.<\/p>\n<p>Il y est parvenu non pas en obtenant un emploi salari\u00e9 bien r\u00e9mun\u00e9r\u00e9, mais en vendant du jus fabriqu\u00e9 \u00e0 partir de la partie charnue du fruit de l&rsquo;anacardier que la plupart des agriculteurs jettent.<\/p>\n<p>\u00ab\u00a0Les pommes de cajou sont faciles \u00e0 trouver et gratuites\u00a0\u00bb, explique-t-il \u00e0 <em>SciDev.Net.<\/em><\/p>\n<p>\u00ab\u00a0Aujourd&rsquo;hui, je fabrique environ 60 bouteilles de jus par cycle et par jour, et je les vends par l&rsquo;interm\u00e9diaire du magasin de ma femme et des plateformes de m\u00e9dias sociaux comme TikTok et WhatsApp.\u00a0\u00bb<\/p>\n<p>Les pommes de cajou, fruits attach\u00e9s \u00e0 la noix de cajou, sont g\u00e9n\u00e9ralement jet\u00e9es lors de la r\u00e9colte.<\/p>\n<div id=\"attachment_1985956\" style=\"width: 1006px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1985956\" class=\"size-full wp-image-1985956\" src=\"https:\/\/www.scidev.net\/global\/wp-content\/uploads\/Cashew_Ghana_BODY1.jpg\" alt=\"Michael Kyereme a rembours\u00e9 une dette universitaire\" width=\"996\" height=\"400\"><p id=\"caption-attachment-1985956\" class=\"wp-caption-text\"><em>Michael Kyereme a rembours\u00e9 une dette universitaire en vendant du jus fabriqu\u00e9 \u00e0 partir de la partie charnue du fruit de la noix de cajou. Copyright : Francisca Aba Ansah\/CSIR-FRI\/SciDev.Net <\/em><\/p><\/div>\n<p>Mais dans le cadre d&rsquo;un projet soutenu par la recherche, les jeunes apprennent \u00e0 transformer les pommes en jus, en snacks, en compost et en aliments pour animaux.<\/p>\n<p>L&rsquo;initiative, appel\u00e9e Maximising Gains from Cashew Production for Youth Development (MA-CASH), est g\u00e9r\u00e9e par le Conseil de la recherche scientifique et industrielle du Ghana, avec le soutien du minist\u00e8re de l&rsquo;environnement, de la science et de la technologie et un financement du Centre de recherches pour le d\u00e9veloppement international (CRDI) du Canada.<\/p>\n<p>Elle forme des jeunes \u00e0 la transformation des pommes de cajou en produits qui r\u00e9duisent le gaspillage alimentaire et procurent des revenus dans les zones rurales.<\/p>\n<p>\u00ab\u00a0La plupart des moyens de subsistance alternatifs n\u00e9cessitent un capital, mais pas celui-ci. C&rsquo;est pourquoi je l&rsquo;ai imm\u00e9diatement adopt\u00e9e\u00a0\u00bb, explique Kyereme.<\/p>\n<p>Il esp\u00e8re investir dans des \u00e9quipements de transformation et tester de nouveaux produits tels que les brochettes de pommes de cajou et les aliments pour volailles.<\/p>\n<h3>D\u00e9chets alimentaires<\/h3>\n<p>\u00c0 l&rsquo;\u00e9chelle mondiale, environ <a href=\"https:\/\/www.tandfonline.com\/doi\/full\/10.1080\/10408398.2023.2180616#abstract\">37 millions de tonnes m\u00e9triques<\/a> de pommes de cajou sont produites chaque ann\u00e9e. Mais seulement <a href=\"https:\/\/www.tandfonline.com\/doi\/full\/10.1080\/10408398.2023.2180616#d1e117\">1,3 million de tonnes<\/a> sont transform\u00e9es commercialement, selon l&rsquo;Organisation des Nations unies pour l&rsquo;alimentation et l&rsquo;agriculture. <\/p>\n<p>George Asare, chercheur au Conseil ghan\u00e9en pour la recherche scientifique et industrielle, qui a particip\u00e9 au projet, indique que le Ghana a produit plus de 1,6 million de tonnes de pommes de cajou en 2024, dont 90 % ont \u00e9t\u00e9 gaspill\u00e9es.<\/p>\n<p>\u00ab\u00a0Cela repr\u00e9sente environ 1 449 000 tonnes m\u00e9triques de produits perdus\u00a0\u00bb, explique M. Asare. \u00ab\u00a0Il s&rsquo;agit d&rsquo;une perte importante tant sur le plan \u00e9conomique que nutritionnel. <\/p>\n<p>MA-CASH forme les jeunes \u00e0 la transformation des fruits en jus, en substituts de viande et en d&rsquo;autres produits. Il encourage \u00e9galement le compostage et la production d&rsquo;aliments pour animaux, cr\u00e9ant ainsi de petites entreprises qui utilisent toutes les parties du fruit. <\/p>\n<p>\u00ab\u00a0Ce projet ne concerne pas seulement le jus\u00a0\u00bb, explique Sefakor Heloo, responsable de la planification du d\u00e9veloppement au minist\u00e8re ghan\u00e9en de l&rsquo;environnement, de la science et de la technologie.<\/p>\n<p>\u00ab\u00a0Il s&rsquo;agit de la durabilit\u00e9, de la s\u00e9curit\u00e9 alimentaire, de la r\u00e9silience climatique et de l&rsquo;acquisition de comp\u00e9tences pratiques par les jeunes.<\/p>\n<h3>R\u00e9actions allergiques<\/h3>\n<p>L&rsquo;id\u00e9e du projet est n\u00e9e lors d&rsquo;une visite sur le terrain de la phytotechnicienne Francisca Aba Ansah, qui a vu des piles de pommes de cajou pourries et s&rsquo;est demand\u00e9e pourquoi personne ne les mangeait.<\/p>\n<p>De retour au laboratoire, l&rsquo;\u00e9quipe s&rsquo;est heurt\u00e9e \u00e0 deux difficult\u00e9s : la forte teneur en tanins du fruit, qui peut bloquer l&rsquo;absorption des nutriments, et la n\u00e9cessit\u00e9 de trouver un ingr\u00e9dient riche en prot\u00e9ines qui ne d\u00e9clenche pas d&rsquo;allergies.<\/p>\n<p>\u00ab\u00a0Nous avons utilis\u00e9 des proc\u00e9d\u00e9s scientifiques pour r\u00e9duire les niveaux de tannins dans le jus\u00a0\u00bb, explique M. Ansah.<\/p>\n<p>Pour augmenter la teneur en prot\u00e9ines, ils ont ajout\u00e9 une l\u00e9gumineuse, afin de mettre au point un aliment riche en prot\u00e9ines pour les v\u00e9g\u00e9tariens, semblable \u00e0 une saucisse.<\/p>\n<div id=\"attachment_1985957\" style=\"width: 1006px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1985957\" class=\"size-full wp-image-1985957\" src=\"https:\/\/www.scidev.net\/global\/wp-content\/uploads\/Cashew_Ghana_BODY2.jpg\" alt=\"Brochette de noix de cajou pr\u00e9sent\u00e9e\" width=\"996\" height=\"450\"><p id=\"caption-attachment-1985957\" class=\"wp-caption-text\"><em>Brochette de noix de cajou en exposition. Les chercheurs travaillent sur l&rsquo;allongement de la dur\u00e9e de conservation des produits \u00e0 base de noix de cajou. Copyright : Francisca Aba Ansah\/CSIR-FRI\/SciDev.Net  <\/em><\/p><\/div>\n<p>L&rsquo;\u00e9quipe a test\u00e9 la nouvelle saucisse \u00e0 Accra apr\u00e8s avoir re\u00e7u l&rsquo;autorisation \u00e9thique et men\u00e9 une petite campagne dans les m\u00e9dias sociaux pour recruter des d\u00e9gustateurs.<\/p>\n<p>\u00ab\u00a0Il n&rsquo;y avait pas de diff\u00e9rence significative entre notre saucisse et la saucisse v\u00e9g\u00e9talienne commerciale\u00a0\u00bb, dit-elle.<\/p>\n<p>Jusqu&rsquo;\u00e0 pr\u00e9sent, plus de 300 jeunes ont \u00e9t\u00e9 form\u00e9s dans six communaut\u00e9s, et la prochaine session de formation, pr\u00e9vue pour janvier 2026, est d\u00e9j\u00e0 compl\u00e8te.<\/p>\n<h3>Dur\u00e9e de conservation plus longue<\/h3>\n<p>MA-CASH se concentre \u00e9galement sur la r\u00e9duction des d\u00e9chets. Les restes de pulpe sont utilis\u00e9s pour le compost et l&rsquo;alimentation animale, et le projet exp\u00e9rimente des technologies de refroidissement simples pour prolonger la dur\u00e9e de conservation des fruits. <\/p>\n<p>\u00ab\u00a0Nous avons mis au point et test\u00e9 un refroidisseur d&rsquo;argile qui prolonge la dur\u00e9e de conservation de 24 heures \u00e0 six jours\u00a0\u00bb, explique M. Ansah.<\/p>\n<p>\u00ab\u00a0Mais nous \u00e9tudions des technologies permettant d&rsquo;allonger ce d\u00e9lai \u00e0 trois mois ou plus\u00a0\u00bb.<\/p>\n<p>Le projet encourage \u00e9galement l&rsquo;apiculture sous les anacardiers afin d&rsquo;am\u00e9liorer la pollinisation et de stimuler la production de miel.<\/p>\n<p>Avec l&rsquo;aide d&rsquo;Opportunity International Savings and Loans, une institution d&rsquo;\u00e9pargne et de pr\u00eat agr\u00e9\u00e9e par la Banque du Ghana, des groupes d&rsquo;\u00e9pargne ont \u00e9t\u00e9 mis en place pour soutenir les participants qui ont besoin de pr\u00eats pour acheter du mat\u00e9riel ou d\u00e9velopper leur activit\u00e9. Les participants re\u00e7oivent \u00e9galement une formation en mati\u00e8re d&rsquo;\u00e9ducation financi\u00e8re et d&rsquo;outils num\u00e9riques. <\/p>\n<p>Paul Adu-Gyamfi, directeur de recherche au Consultative International Cashew Council, explique que le cajou est le premier produit d&rsquo;exportation non traditionnel du Ghana et qu&rsquo;il pourrait se d\u00e9velopper davantage si la pomme \u00e9tait mieux utilis\u00e9e.<\/p>\n<p>\u00ab\u00a0La pomme de cajou pr\u00e9sente un potentiel pour les produits \u00e0 valeur ajout\u00e9e\u00a0\u00bb, d\u00e9clare-t-il.<\/p>\n<p>\u00ab\u00a0Sa diffusion dans des r\u00e9gions telles que la r\u00e9gion orientale cr\u00e9e plus d&rsquo;espace pour la transformation et les entreprises locales.<\/p>\n<p>Selon lui, plus de 4 000 agriculteurs sont impliqu\u00e9s dans la culture de la noix de cajou, tandis que d&rsquo;autres travaillent dans la transformation et l&rsquo;exportation. Des institutions telles que l&rsquo;Institut ghan\u00e9en de recherche sur le cacao aident \u00e0 relever les d\u00e9fis agricoles, tandis que des agences telles que la Food and Drugs Authority travaillent sur la qualit\u00e9 et la s\u00e9curit\u00e9 des produits. <\/p>\n<h3>Avantages nutritionnels<\/h3>\n<p>Les pommes de cajou sont riches en nutriments, explique Daniel Kwame Antwi, responsable de la nutrition au sous-district de Dormaah du Service de sant\u00e9 du Ghana dans la municipalit\u00e9 de Sunyani au Ghana, qui n&rsquo;a pas particip\u00e9 \u00e0 l&rsquo;\u00e9tude.<\/p>\n<div id=\"attachment_1985958\" style=\"width: 1006px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1985958\" class=\"size-full wp-image-1985958\" src=\"https:\/\/www.scidev.net\/global\/wp-content\/uploads\/Cashew_Ghana_BODY3.jpg\" alt=\"Jus en bouteille fabriqu\u00e9 \u00e0 partir de la partie charnue du fruit de la noix de cajou\" width=\"996\" height=\"567\"><p id=\"caption-attachment-1985958\" class=\"wp-caption-text\"><em>Jus en bouteille fabriqu\u00e9 \u00e0 partir de la partie charnue du fruit de la noix de cajou. Copyright : Francisca Aba Ansah\/CSIR-FRI\/SciDev.Net <\/em><\/p><\/div>\n<p>\u00ab\u00a0Il est riche en glucides, en magn\u00e9sium, en potassium, en vitamine C et en antioxydants. Il renforce l&rsquo;immunit\u00e9, favorise la sant\u00e9 cardiaque et peut r\u00e9duire les risques d&rsquo;ob\u00e9sit\u00e9\u00a0\u00bb, ajoute-t-il.<\/p>\n<p>\u00ab\u00a0Le jus de cajou est bon pour tous les groupes d&rsquo;\u00e2ge. Nous nous sommes trop longtemps concentr\u00e9s sur la noix. Il est temps d&rsquo;explorer le fruit\u00a0\u00bb.<\/p>\n<p>Le mod\u00e8le MA-CASH est en train d&rsquo;\u00eatre \u00e9tendu \u00e0 des r\u00e9gions telles que Ahafo, Ashanti et le nord du Ghana, avec du mat\u00e9riel de formation d\u00e9sormais disponible dans les langues locales.<\/p>\n<p>Pour Michael Kyereme, ce changement a boulevers\u00e9 sa vie.<\/p>\n<p>\u00ab\u00a0Cette comp\u00e9tence a chang\u00e9 ma vie\u00a0\u00bb, explique-t-il. \u00ab\u00a0C&rsquo;est une activit\u00e9 rentable, et de plus en plus de jeunes veulent la rejoindre. Nous avons juste besoin de machines et de soutien pour nous d\u00e9velopper\u00a0\u00bb. <\/p>\n<p><a href=\"https:\/\/www.scidev.net\/sub-saharan-africa\/supported-content\/cashew-waste-a-lucrative-business-for-ghanas-youth\/\"><em>Cet article a \u00e9t\u00e9 produit par le bureau anglais de SciDev.Net pour l&rsquo;Afrique sub-saharienne.<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[A Ayigbe, une communaut\u00e9 rurale de la r\u00e9gion de Bono au Ghana, Michael Kyereme, 35 ans, a rembours\u00e9 une dette universitaire de 3 500 GHS (335 USD) en seulement trois mois. Il y est parvenu non pas en obtenant un emploi salari\u00e9 bien r\u00e9mun\u00e9r\u00e9, mais en vendant du jus fabriqu\u00e9 \u00e0 partir de la partie&hellip;<\/p>\n","protected":false},"author":13,"featured_media":24637,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[161],"tags":[],"country":[232],"objective":[],"sg_theme":[],"class_list":["post-24753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","country-ghana-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens - SGCI Africa<\/title>\n<meta name=\"description\" content=\"Au Ghana, un projet scientifique transforme les d\u00e9chets de pommes de cajou en jus, en saucisses et en compost, g\u00e9n\u00e9rant ainsi des revenus pour les jeunes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens\" \/>\n<meta property=\"og:description\" content=\"Au Ghana, un projet scientifique transforme les d\u00e9chets de pommes de cajou en jus, en saucisses et en compost, g\u00e9n\u00e9rant ainsi des revenus pour les jeunes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-25T11:56:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T12:24:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davis Weddi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davis Weddi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/\"},\"author\":{\"name\":\"Davis Weddi\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\"},\"headline\":\"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens\",\"datePublished\":\"2025-07-25T11:56:34+00:00\",\"dateModified\":\"2025-09-08T12:24:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/\"},\"wordCount\":1392,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cashew_Ghana_MAIN.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/\",\"name\":\"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cashew_Ghana_MAIN.jpg\",\"datePublished\":\"2025-07-25T11:56:34+00:00\",\"dateModified\":\"2025-09-08T12:24:34+00:00\",\"description\":\"Au Ghana, un projet scientifique transforme les d\u00e9chets de pommes de cajou en jus, en saucisses et en compost, g\u00e9n\u00e9rant ainsi des revenus pour les jeunes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cashew_Ghana_MAIN.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cashew_Ghana_MAIN.jpg\",\"width\":996,\"height\":567,\"caption\":\"Youth participating in one of the training sessions. The science-led project trains them to make juice, sausage and compost, with zero waste. Copyright: Albert Oppong-Ansah \\\/ SciDev.Net\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/428f9ad4d83bdadcb2d6d2110d2fcf92\",\"name\":\"Davis Weddi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/e61\\\/e6106b7cc637f81191024d3ee67d2d36x96.jpg\",\"caption\":\"Davis Weddi\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/author\\\/davisweddi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens - SGCI Africa","description":"Au Ghana, un projet scientifique transforme les d\u00e9chets de pommes de cajou en jus, en saucisses et en compost, g\u00e9n\u00e9rant ainsi des revenus pour les jeunes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/","og_locale":"fr_FR","og_type":"article","og_title":"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens","og_description":"Au Ghana, un projet scientifique transforme les d\u00e9chets de pommes de cajou en jus, en saucisses et en compost, g\u00e9n\u00e9rant ainsi des revenus pour les jeunes.","og_url":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/","og_site_name":"SGCI Africa","article_published_time":"2025-07-25T11:56:34+00:00","article_modified_time":"2025-09-08T12:24:34+00:00","og_image":[{"width":996,"height":567,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg","type":"image\/jpeg"}],"author":"Davis Weddi","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"\u00c9crit par":"Davis Weddi","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/"},"author":{"name":"Davis Weddi","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92"},"headline":"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens","datePublished":"2025-07-25T11:56:34+00:00","dateModified":"2025-09-08T12:24:34+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/"},"wordCount":1392,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/","url":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/","name":"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg","datePublished":"2025-07-25T11:56:34+00:00","dateModified":"2025-09-08T12:24:34+00:00","description":"Au Ghana, un projet scientifique transforme les d\u00e9chets de pommes de cajou en jus, en saucisses et en compost, g\u00e9n\u00e9rant ainsi des revenus pour les jeunes.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg","width":996,"height":567,"caption":"Youth participating in one of the training sessions. The science-led project trains them to make juice, sausage and compost, with zero waste. Copyright: Albert Oppong-Ansah \/ SciDev.Net"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/les-dechets-de-noix-de-cajou-une-activite-lucrative-pour-les-jeunes-ghaneens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les d\u00e9chets de noix de cajou, une activit\u00e9 lucrative pour les jeunes ghan\u00e9ens"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/428f9ad4d83bdadcb2d6d2110d2fcf92","name":"Davis Weddi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/e61\/e6106b7cc637f81191024d3ee67d2d36x96.jpg","caption":"Davis Weddi"},"url":"https:\/\/sgciafrica.org\/fr\/author\/davisweddi\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg",996,567,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN-300x171.jpg",300,171,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN-768x437.jpg",768,437,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg",996,567,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg",996,567,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg",996,567,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg",996,567,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg",996,567,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg",996,567,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN.jpg",996,567,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2025\/07\/Cashew_Ghana_MAIN-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Davis Weddi","author_link":"https:\/\/sgciafrica.org\/fr\/author\/davisweddi\/"},"uagb_comment_info":0,"uagb_excerpt":"[A Ayigbe, une communaut\u00e9 rurale de la r\u00e9gion de Bono au Ghana, Michael Kyereme, 35 ans, a rembours\u00e9 une dette universitaire de 3 500 GHS (335 USD) en seulement trois mois. Il y est parvenu non pas en obtenant un emploi salari\u00e9 bien r\u00e9mun\u00e9r\u00e9, mais en vendant du jus fabriqu\u00e9 \u00e0 partir de la partie&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/24753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=24753"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/24753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/24637"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=24753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=24753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=24753"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=24753"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/objective?post=24753"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=24753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}