{"id":22413,"date":"2024-12-24T12:18:06","date_gmt":"2024-12-24T12:18:06","guid":{"rendered":"https:\/\/sgciafrica.org\/?p=22413"},"modified":"2024-12-24T12:34:44","modified_gmt":"2024-12-24T12:34:44","slug":"mieux-proteger-les-projets-de-recherche-pour-capter-des-financements","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/","title":{"rendered":"Mieux prot\u00e9ger les projets de recherche pour capter des financements"},"content":{"rendered":"\n<p>[BOUAKE] Renforcer les capacit\u00e9s des enseignants-chercheurs, chercheurs et \u00e9tudiants en mati\u00e8re de r\u00e9daction de projets capables de capter des financements et faciliter la r\u00e9alisation de ces projets, puis les prot\u00e9ger en tant que propri\u00e9t\u00e9 intellectuelle afin de mieux accompagner le d\u00e9veloppement de la C\u00f4te d\u2019Ivoire et de l\u2019Afrique.<\/p>\n\n\n\n<p>Tel est le sens de la session de formation organis\u00e9e du 16 au 19 juillet 2024 \u00e0 l\u2019universit\u00e9 Alassane Ouattara de Bouak\u00e9 en C\u00f4te d\u2019Ivoire sous la houlette du Fonds pour la science, la technologie et l\u2019innovation (FONSTI).<\/p>\n\n\n\n<p>Le FONSTI est membre de l\u2019Initiative des organismes subventionnaires de la recherche scientifiques (IOSRS \u2013 SGCI en anglais), un programme de renforcement des capacit\u00e9s des institutions publiques qui financent la recherche scientifique en Afrique subsaharienne.<\/p>\n\n\n\n<p>\u201cL\u2019enjeu de la science, ce n\u2019est pas de faire la science pour la science (\u2026), mais c\u2019est une production de connaissances qui doivent penser non seulement les probl\u00e8mes de soci\u00e9t\u00e9 mais r\u00e9soudre ces probl\u00e8mes\u201d<br>Arnaud Kevin Dagnoro, FONSTI<\/p>\n\n\n\n<p>A cette occasion, vingt-six enseignants-chercheurs et chercheurs ont \u00e9t\u00e9 sensibilis\u00e9s et form\u00e9s sur la propri\u00e9t\u00e9 intellectuelle, trente-un sur la recherche de financement et vingt-neuf \u00e9tudiants \u00e0 la r\u00e9daction de projets de recherche.<\/p>\n\n\n\n<p>L\u2019objectif \u00e9tant de rendre leurs travaux \u00e0 venir plus pertinents pour pouvoir capter des financements gr\u00e2ce \u00e0 une protection intellectuelle ad\u00e9quate et impacter le d\u00e9veloppement socio-\u00e9conomique de nos pays.<\/p>\n\n\n\n<p>Selon Arnaud Kevin Dagnoro, membre du Conseil Scientifique du FONSTI, il s\u2019agissait \u00ab&nbsp;vraiment de rapprocher la science des populations parce que l\u2019enjeu de la science, ce n\u2019est pas de faire la science pour la science (\u2026), mais c\u2019est une production de connaissances qui doivent penser non seulement les probl\u00e8mes de soci\u00e9t\u00e9 mais r\u00e9soudre ces probl\u00e8mes. Donc, les universit\u00e9s doivent s\u2019ouvrir de fa\u00e7on g\u00e9n\u00e9rale, \u00eatre en partenariat avec les entreprises, les secteurs public et priv\u00e9, travailler utile.&nbsp;\u00bb<\/p>\n\n\n\n<p>\u00ab&nbsp;On est plus dans le paradigme de la recherche utilitaire&nbsp;\u00bb, afin de permettre aux entreprises et aux communaut\u00e9s de \u00ab&nbsp;tirer profit des r\u00e9flexions des universitaires&nbsp;\u00bb, d\u00e9fend Arnaud Kevin Dagnoro qui estime qu\u2019avec le peu de financements disponibles, \u00ab&nbsp;il est possible de faire mieux&nbsp;\u00bb.<\/p>\n\n\n\n<p>Roger Lebeau, sous-directeur charg\u00e9 de la recherche \u00e0 l\u2019universit\u00e9 Alassane OUATTARA reconna\u00eet que \u00ab&nbsp;la recherche scientifique co\u00fbte cher&nbsp;\u00bb. Il pense que c\u2019est peut-\u00eatre une des raisons du peu d\u2019int\u00e9r\u00eat des enseignants d\u2019universit\u00e9 \u00e0 s\u2019int\u00e9resser \u00e0 la recherche.<\/p>\n\n\n\n<p>Il estime n\u00e9anmoins que la formation \u00e0 une meilleure pr\u00e9sentation des projets pourrait \u00eatre une solution de captation de financement. D\u2019autant plus que, soutient-il, c\u2019est la recherche qui peut bien positionner les universit\u00e9s ivoiriennes parmi les autres universit\u00e9s.<\/p>\n\n\n\n<p><strong>Universit\u00e9 innovante<\/strong><\/p>\n\n\n\n<p>Chantal Pal\u00e9, \u00e9pouse Koutouan, secr\u00e9taire g\u00e9n\u00e9rale adjointe de l\u2019universit\u00e9 Alassane Ouattara, a salu\u00e9 cet appui technique du FONSTI qui entend positionner la recherche scientifique au c\u0153ur du d\u00e9veloppement national. \u00ab&nbsp;Nous ne sommes pas encore \u00e0 la hauteur des attentes du d\u00e9veloppement. Et donc, cette formation nous aide \u00e0 atteindre notre objectif qui est d\u2019avoir une universit\u00e9 innovante&nbsp;\u00bb, a-t-elle affirm\u00e9.<\/p>\n\n\n\n<p>L\u2019expert-formateur de l\u2019UNESCO, L\u00e9on Rivi\u00e8re Komenan, a, pour sa part, mis en relief les faiblesses du syst\u00e8me universitaire ivoirien et des b\u00e9n\u00e9ficiaires de la formation en mati\u00e8re d\u2019acc\u00e8s au financement.<\/p>\n\n\n\n<p>Il a estim\u00e9 que des objectifs clairs devraient \u00eatre \u00e9dict\u00e9s pour les UFR, le tout, inclus dans la feuille de route de l\u2019universit\u00e9 elle-m\u00eame. A partir de ce paradigme, les travaux de recherche pourront s\u2019inscrire dans le Plan national de d\u00e9veloppement 2021-2025 de la C\u00f4te d\u2019Ivoire ainsi&nbsp; que dans l\u2019Agenda 2063 de l\u2019Union Africaine et les Objectifs de d\u00e9veloppement durable des Nations unies.<\/p>\n\n\n\n<p>\u00ab&nbsp;Aujourd\u2019hui, il est question d\u2019aider \u00e0 capitaliser un peu l\u2019impact social des travaux de recherche afin de pouvoir transformer la recherche de financement li\u00e9e \u00e0 l\u2019\u00e9motion pour pousser les bailleurs de fonds \u00e0 inverser la tendance&nbsp;\u00bb, recommande-t-il.<\/p>\n\n\n\n<p><strong>Plagiat<\/strong><\/p>\n\n\n\n<p>Ainsi, il a pr\u00e9conis\u00e9 l\u2019implication des industriels, des ONG et des anciens \u00e9tudiants des universit\u00e9s publiques devenus travailleurs pour pallier au d\u00e9ficit infrastructurel de leurs anciennes universit\u00e9s. \u00ab&nbsp;L\u2019africain a un certain nombre de connaissances, il est question de valoriser ces connaissances endog\u00e8nes aujourd\u2019hui reconnues par le milieu scientifique mondial&nbsp;\u00bb, ajoute L\u00e9on Rivi\u00e8re Komenan.<\/p>\n\n\n\n<p>S\u00e9v\u00e9rin Konin de l\u2019universit\u00e9 F\u00e9lix Houphou\u00ebt-Boigny s\u2019est appesanti sur la question du plagiat et des similitudes dans les projets de recherche, faisant ressortir les capacit\u00e9s des chercheurs africains dont les travaux sont peu prot\u00e9g\u00e9s.<\/p>\n\n\n\n<p>A l\u2019en croire, la protection de la propri\u00e9t\u00e9 intellectuelle est un crit\u00e8re de premier choix. \u00ab&nbsp;Car, un organisme de financement ne va pas s\u2019amuser \u00e0 financer un projet issu d\u2019un plagiat&nbsp;; l\u2019organisme va se d\u00e9cr\u00e9dibiliser ainsi que le chercheur. C\u2019est un crit\u00e8re de premier plan dans l\u2019\u00e9valuation du financement&nbsp;\u00bb, mart\u00e8le ce chercheur.<\/p>\n\n\n\n<p>Il regrette au passage le fait qu\u2019aucune universit\u00e9 de la r\u00e9gion subsaharienne ne figure dans le classement des publications scientifiques mondiales qui sont en constante augmentation. Il sollicite d\u00e8s lors une revalorisation des budgets allou\u00e9s \u00e0 la recherche scientifique dans nos pays. \u00ab&nbsp;Car, on ne peut rien faire avec 10 millions FCFA dans une universit\u00e9 publique&nbsp;\u00bb, dit-il.<\/p>\n\n\n\n<p>Selon Alexis Kouam\u00e9 de l\u2019Organisation internationale de la propri\u00e9t\u00e9 intellectuelle (OIPI), \u00ab&nbsp;entre 2010 et 2021, la proportion des brevets d\u00e9pos\u00e9s par les chercheurs africains se situe entre 0,5 et 0,6% quand la Chine, avec 67.6% repr\u00e9sente plus de la moiti\u00e9 des brevets d\u00e9pos\u00e9s dans le monde&nbsp;\u00bb.<\/p>\n\n\n\n<p>Il a soutenu que \u00ab&nbsp;la propri\u00e9t\u00e9 intellectuelle conf\u00e8re un monopole d\u2019exploitation de l\u2019actif pendant un certain temps, constitue un moyen de s\u00e9curisation des investissements et un moyen de financement de la recherche scientifique&nbsp;\u00bb.<\/p>\n\n\n\n<p>Les sanctions au plagiat ont \u00e9t\u00e9 pr\u00e9sent\u00e9s \u00e0 la cible de cette formation tout en relevant les avantages et inconv\u00e9nients du num\u00e9rique dans un monde interconnect\u00e9.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[BOUAKE] Renforcer les capacit\u00e9s des enseignants-chercheurs, chercheurs et \u00e9tudiants en mati\u00e8re de r\u00e9daction de projets capables de capter des financements et faciliter la r\u00e9alisation de ces projets, puis les prot\u00e9ger en tant que propri\u00e9t\u00e9 intellectuelle afin de mieux accompagner le d\u00e9veloppement de la C\u00f4te d\u2019Ivoire et de l\u2019Afrique. Tel est le sens de la session&hellip;<\/p>\n","protected":false},"author":15,"featured_media":22414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[161],"tags":[],"country":[],"objective":[],"sg_theme":[],"class_list":["post-22413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mieux prot\u00e9ger les projets de recherche pour capter des financements - SGCI Africa<\/title>\n<meta name=\"description\" content=\"Des sessions de formation ont appris \u00e0 pr\u00e8s de 90 enseignants de l\u2019universit\u00e9 Alassane Ouattara de Bouak\u00e9 en C\u00f4te d\u2019Ivoire \u00e0 mieux monter leurs projets de recherche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mieux prot\u00e9ger les projets de recherche pour capter des financements\" \/>\n<meta property=\"og:description\" content=\"Des sessions de formation ont appris \u00e0 pr\u00e8s de 90 enseignants de l\u2019universit\u00e9 Alassane Ouattara de Bouak\u00e9 en C\u00f4te d\u2019Ivoire \u00e0 mieux monter leurs projets de recherche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-24T12:18:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-24T12:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julien Chongwang\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julien Chongwang\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/\"},\"author\":{\"name\":\"Julien Chongwang\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/c59c7196f23b10482f8bef0ff8a88365\"},\"headline\":\"Mieux prot\u00e9ger les projets de recherche pour capter des financements\",\"datePublished\":\"2024-12-24T12:18:06+00:00\",\"dateModified\":\"2024-12-24T12:34:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/\"},\"wordCount\":1066,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/African-scientists.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/\",\"name\":\"Mieux prot\u00e9ger les projets de recherche pour capter des financements - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/African-scientists.jpg\",\"datePublished\":\"2024-12-24T12:18:06+00:00\",\"dateModified\":\"2024-12-24T12:34:44+00:00\",\"description\":\"Des sessions de formation ont appris \u00e0 pr\u00e8s de 90 enseignants de l\u2019universit\u00e9 Alassane Ouattara de Bouak\u00e9 en C\u00f4te d\u2019Ivoire \u00e0 mieux monter leurs projets de recherche.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/African-scientists.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/African-scientists.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"Des chercheurs dans un laboratoire. En C\u00f4te d'Ivoire, le FONSTI renforce les capacit\u00e9s des chercheurs en mati\u00e8re de montage des projets de recherche.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mieux prot\u00e9ger les projets de recherche pour capter des financements\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/c59c7196f23b10482f8bef0ff8a88365\",\"name\":\"Julien Chongwang\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/147\\\/1477bc347e045291a433277e11d6ce98x96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/147\\\/1477bc347e045291a433277e11d6ce98x96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/147\\\/1477bc347e045291a433277e11d6ce98x96.jpg\",\"caption\":\"Julien Chongwang\"},\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/author\\\/julienchongwang\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mieux prot\u00e9ger les projets de recherche pour capter des financements - SGCI Africa","description":"Des sessions de formation ont appris \u00e0 pr\u00e8s de 90 enseignants de l\u2019universit\u00e9 Alassane Ouattara de Bouak\u00e9 en C\u00f4te d\u2019Ivoire \u00e0 mieux monter leurs projets de recherche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/","og_locale":"fr_FR","og_type":"article","og_title":"Mieux prot\u00e9ger les projets de recherche pour capter des financements","og_description":"Des sessions de formation ont appris \u00e0 pr\u00e8s de 90 enseignants de l\u2019universit\u00e9 Alassane Ouattara de Bouak\u00e9 en C\u00f4te d\u2019Ivoire \u00e0 mieux monter leurs projets de recherche.","og_url":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/","og_site_name":"SGCI Africa","article_published_time":"2024-12-24T12:18:06+00:00","article_modified_time":"2024-12-24T12:34:44+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg","type":"image\/jpeg"}],"author":"Julien Chongwang","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"\u00c9crit par":"Julien Chongwang"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/"},"author":{"name":"Julien Chongwang","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/c59c7196f23b10482f8bef0ff8a88365"},"headline":"Mieux prot\u00e9ger les projets de recherche pour capter des financements","datePublished":"2024-12-24T12:18:06+00:00","dateModified":"2024-12-24T12:34:44+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/"},"wordCount":1066,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/","url":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/","name":"Mieux prot\u00e9ger les projets de recherche pour capter des financements - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg","datePublished":"2024-12-24T12:18:06+00:00","dateModified":"2024-12-24T12:34:44+00:00","description":"Des sessions de formation ont appris \u00e0 pr\u00e8s de 90 enseignants de l\u2019universit\u00e9 Alassane Ouattara de Bouak\u00e9 en C\u00f4te d\u2019Ivoire \u00e0 mieux monter leurs projets de recherche.","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg","width":1600,"height":1067,"caption":"Des chercheurs dans un laboratoire. En C\u00f4te d'Ivoire, le FONSTI renforce les capacit\u00e9s des chercheurs en mati\u00e8re de montage des projets de recherche."},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/mieux-proteger-les-projets-de-recherche-pour-capter-des-financements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Mieux prot\u00e9ger les projets de recherche pour capter des financements"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/c59c7196f23b10482f8bef0ff8a88365","name":"Julien Chongwang","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/147\/1477bc347e045291a433277e11d6ce98x96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/147\/1477bc347e045291a433277e11d6ce98x96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/147\/1477bc347e045291a433277e11d6ce98x96.jpg","caption":"Julien Chongwang"},"url":"https:\/\/sgciafrica.org\/fr\/author\/julienchongwang\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg",1600,1067,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists-300x200.jpg",300,200,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists-768x512.jpg",768,512,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg",1600,1067,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg",1600,1067,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists.jpg",1600,1067,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists-1352x902.jpg",1352,902,true],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists-1294x852.jpg",1294,852,true],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/African-scientists-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"Julien Chongwang","author_link":"https:\/\/sgciafrica.org\/fr\/author\/julienchongwang\/"},"uagb_comment_info":0,"uagb_excerpt":"[BOUAKE] Renforcer les capacit\u00e9s des enseignants-chercheurs, chercheurs et \u00e9tudiants en mati\u00e8re de r\u00e9daction de projets capables de capter des financements et faciliter la r\u00e9alisation de ces projets, puis les prot\u00e9ger en tant que propri\u00e9t\u00e9 intellectuelle afin de mieux accompagner le d\u00e9veloppement de la C\u00f4te d\u2019Ivoire et de l\u2019Afrique. Tel est le sens de la session&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/22413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=22413"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/22413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/22414"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=22413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=22413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=22413"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=22413"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/objective?post=22413"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=22413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}