{"id":18283,"date":"2023-11-28T14:13:34","date_gmt":"2023-11-28T14:13:34","guid":{"rendered":"https:\/\/sgciafrica.org\/?p=18283"},"modified":"2026-02-11T14:01:40","modified_gmt":"2026-02-11T14:01:40","slug":"les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/","title":{"rendered":"Les laur\u00e9ats des bourses de recherche s&rsquo;attaquent \u00e0 la crise de l&rsquo;eau et au cancer"},"content":{"rendered":"\n<p><strong>Des chercheurs sud-africains prim\u00e9s discutent de leurs travaux sur la p\u00e9nurie d&rsquo;eau et le cancer.<\/strong><\/p>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>1<\/td><td>L\u2019ing\u00e9nieure chimiste Nomthandazo Sibiya s\u2019attaque \u00e0 la crise de l\u2019eau en Afrique du Sud<\/td><\/tr><tr><td>2<\/td><td>Ses recherches sur les m\u00e9taux pr\u00e9sents dans les eaux us\u00e9es lui ont valu un prix de la National Research Foundation<\/td><\/tr><tr><td>3<\/td><td>Des prix ont \u00e9galement r\u00e9compens\u00e9 des recherches sur les cancers du pancr\u00e9as et de la v\u00e9sicule biliaire<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p>[NAIROBI] La p\u00e9nurie d\u2019eau est un probl\u00e8me majeur pour de nombreuses personnes en Afrique du Sud et, pour l\u2019ing\u00e9nieure chimiste Nomthandazo Sibiya, c\u2019\u00e9tait une question qu\u2019elle avait v\u00e9cue de premi\u00e8re main.<\/p>\n\n<p><\/p>\n\n<p>Ayant grandi dans un petit village o\u00f9 il fallait aller chercher de l&rsquo;eau potable au puits, Sibiya \u00e9tait d\u00e9termin\u00e9e \u00e0 relever ce d\u00e9fi lorsqu&rsquo;elle s&rsquo;est lanc\u00e9e dans une carri\u00e8re scientifique.<\/p>\n\n<p><\/p>\n\n<p>\u00ab\u00a0La p\u00e9nurie d&rsquo;eau est une crise majeure en Afrique du Sud\u00a0\u00bb, d\u00e9clare M. Sibiya.<\/p>\n\n<p><\/p>\n\n<p>\u00ab\u00a0J&rsquo;ai grandi dans une zone rurale o\u00f9 nous marchions de nombreux kilom\u00e8tres pour aller chercher de l&rsquo;eau.<\/p>\n\n<p><\/p>\n\n<p>\u00ab\u00a0Je voulais trouver une solution au probl\u00e8me de l&rsquo;eau et am\u00e9liorer l&rsquo;acc\u00e8s \u00e0 l&rsquo;eau potable.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0La<strong>publication est un r\u00e9sultat de la recherche, mais le fait d&rsquo;\u00eatre reconnu pour ses efforts stimule l&rsquo;enthousiasme pour aller plus loin et pour inspirer et encadrer ses pairs, y compris les jeunes scientifiques<\/strong>\u00ab\u00a0.<\/p>\n<cite>Himla Soodyall, responsable de l&rsquo;Acad\u00e9mie des sciences d&rsquo;Afrique du Sud<\/cite><\/blockquote>\n\n<p>Il y a cinq ans, Sibiya a obtenu son dipl\u00f4me de premier cycle en g\u00e9nie chimique \u00e0 l&rsquo;universit\u00e9 de technologie de Durban, en Afrique du Sud, o\u00f9 elle a ensuite poursuivi ses \u00e9tudes en vue de l&rsquo;obtention d&rsquo;une ma\u00eetrise en g\u00e9nie chimique.<\/p>\n\n<p><\/p>\n\n<p>Aujourd&rsquo;hui doctorant en g\u00e9nie chimique \u00e0 l&rsquo;universit\u00e9, Sibiya a entrepris un projet de recherche avec une mission : nettoyer les eaux us\u00e9es industrielles gr\u00e2ce \u00e0 l&rsquo;utilisation innovante de produits chimiques magn\u00e9tiques.<\/p>\n\n<p><\/p>\n\n<p>Son travail et son engagement lui ont valu l&rsquo;un des prix de la Fondation nationale pour la recherche (NRF) de cette ann\u00e9e, un prix qui r\u00e9compense les scientifiques et les chercheurs les plus innovants d&rsquo;Afrique du Sud.<\/p>\n\n<p><\/p>\n\n<p>Ces prix annuels r\u00e9compensent les personnes et les \u00e9quipes dont les r\u00e9alisations scientifiques ont consid\u00e9rablement repouss\u00e9 les limites de la connaissance pour le plus grand bien de la soci\u00e9t\u00e9.<\/p>\n\n<p><\/p>\n\n<p>\u00ab\u00a0Le syst\u00e8me d&rsquo;\u00e9valuation de la NRF sur lequel reposent ces prix nous fournit un point de r\u00e9f\u00e9rence qui permet \u00e0 notre pays de mesurer sa valeur en tant que cr\u00e9ateur de connaissances \u00e0 l&rsquo;\u00e9chelle mondiale et, bien entendu, de se comparer au reste du monde\u00a0\u00bb, a d\u00e9clar\u00e9 Mosa Moshabela, pr\u00e9sidente du conseil d&rsquo;administration de la Fondation nationale pour la recherche.<\/p>\n\n<p><\/p>\n\n<p>La victoire de Sibiya dans la cat\u00e9gorie du prix d&rsquo;excellence de la recherche pour la prochaine g\u00e9n\u00e9ration de chercheurs est la reconnaissance d&rsquo;un travail qui aborde la question cruciale de l&rsquo;acc\u00e8s \u00e0 l&rsquo;eau potable dans un pays marqu\u00e9 par une forte production industrielle d&rsquo;eaux us\u00e9es.<\/p>\n\n<p><\/p>\n\n<p>Financ\u00e9 par la NRF, son doctorat vise \u00e0 combler le d\u00e9ficit de comp\u00e9tences dans les domaines de la science, de l&rsquo;ing\u00e9nierie, de la technologie, des sciences humaines et sociales, tout en renfor\u00e7ant le vivier de talents en recherche dans le syst\u00e8me national d&rsquo;innovation de l&rsquo;Afrique du Sud.<\/p>\n\n<p><\/p>\n\n<p>Les recherches de Sibya portent sur l&rsquo;\u00e9limination des m\u00e9taux lourds des eaux us\u00e9es \u00e0 l&rsquo;aide de mat\u00e9riaux d&rsquo;absorption sp\u00e9cialis\u00e9s. Elle a identifi\u00e9 un probl\u00e8me urgent dans les traitements existants : la difficult\u00e9 de r\u00e9cup\u00e9rer les absorbants.<\/p>\n\n<p><\/p>\n\n<p>M. Sibya estime que l&rsquo;\u00e9limination magn\u00e9tique des m\u00e9taux lourds pourrait constituer une solution viable pour le traitement des eaux us\u00e9es, r\u00e9utilisable et respectueuse de l&rsquo;environnement.<\/p>\n\n<p><\/p>\n\n<p>\u00ab\u00a0Mon objectif est de proposer des solutions de traitement des eaux us\u00e9es respectueuses de l&rsquo;environnement et abordables\u00a0\u00bb, explique-t-elle.<\/p>\n\n<p><\/p>\n\n<p>Mme Sibya souhaite obtenir son doctorat et d\u00e9fendre la cause des jeunes filles de sa communaut\u00e9, en les encourageant \u00e0 poursuivre des \u00e9tudes scientifiques par le biais du mentorat.<\/p>\n\n<p><\/p>\n\n<p>Elle a \u00e9t\u00e9 honor\u00e9e, avec d&rsquo;autres laur\u00e9ats, lors d&rsquo;une c\u00e9r\u00e9monie de remise des prix qui s&rsquo;est d\u00e9roul\u00e9e en ao\u00fbt \u00e0 Durban (KwaZulu-Natal) et qui c\u00e9l\u00e9brait \u00e9galement les 20 ans du projet Square Kilometre Array (SKA) de l&rsquo;Afrique du Sud, une initiative internationale visant \u00e0 construire le plus grand radiot\u00e9lescope du monde.<\/p>\n\n<p><\/p>\n\n<p><strong>Recherche sur les \u00ab\u00a0biomarqueurs\u00a0\u00bb du cancer<\/strong><\/p>\n\n<p>Dans la cat\u00e9gorie du prix d&rsquo;excellence en recherche pour les chercheurs en d\u00e9but de carri\u00e8re et \u00e9mergents, Ekene Nweke, biologiste mol\u00e9culaire au d\u00e9partement de chirurgie de l&rsquo;universit\u00e9 du Witwatersrand, a \u00e9t\u00e9 r\u00e9compens\u00e9 pour ses travaux visant \u00e0 trouver des biomarqueurs pour guider le diagnostic pr\u00e9coce et le traitement du cancer du pancr\u00e9as et de la v\u00e9sicule biliaire, en particulier chez les personnes d&rsquo;ascendance africaine.<\/p>\n\n<p><\/p>\n\n<p>Selon M. Nweke, ces cancers mortels touchent de mani\u00e8re disproportionn\u00e9e les personnes d&rsquo;origine africaine, mais ils sont rarement pris en compte dans la recherche et le d\u00e9veloppement de m\u00e9dicaments.<\/p>\n\n<p><\/p>\n\n<p>\u00ab\u00a0Les cancers du pancr\u00e9as et de la v\u00e9sicule biliaire sont mortels\u00a0\u00bb, explique M. Nweke.<\/p>\n\n<p><\/p>\n\n<p>\u00ab\u00a0Les patients d&rsquo;origine africaine sont ceux qui souffrent le plus, la moiti\u00e9 d&rsquo;entre eux vivant moins de six mois.<\/p>\n\n<p><\/p>\n\n<p>M. Nweke \u00e9tudie les causes sous-jacentes de ces cancers et \u00e9labore des solutions de diagnostic pr\u00e9coce. Il esp\u00e8re \u00e9clairer les complexit\u00e9s de ces cancers agressifs et stimuler le d\u00e9veloppement de m\u00e9dicaments.<\/p>\n\n<p><\/p>\n\n<p>\u00ab\u00a0Nous observons des \u00e9l\u00e9ments qui pourraient rendre le cancer plus agressif\u00a0\u00bb, d\u00e9clare M. Nweke, ajoutant qu&rsquo;il est pr\u00e9vu une augmentation du nombre de cancers du pancr\u00e9as et de la v\u00e9sicule biliaire, ainsi que d&rsquo;autres cancers, en Afrique subsaharienne.<\/p>\n\n<p><\/p>\n\n<p>Himla Soodyall, professeur de recherche en g\u00e9n\u00e9tique humaine et directrice g\u00e9n\u00e9rale de l&rsquo;Acad\u00e9mie des sciences d&rsquo;Afrique du Sud (ASSAf), estime que la reconnaissance des contributions d&rsquo;universitaires comme Nweke \u00e0 l&rsquo;\u00e9cosyst\u00e8me de la science, de la technologie et de l&rsquo;innovation permet non seulement de valider leur travail, mais aussi d&rsquo;inspirer les g\u00e9n\u00e9rations futures.<\/p>\n\n<p><\/p>\n\n<p>\u00ab\u00a0La publication est un r\u00e9sultat de la recherche, mais le fait d&rsquo;\u00eatre reconnu pour ses efforts stimule l&rsquo;enthousiasme pour aller plus loin et pour inspirer et encadrer ses pairs, y compris les jeunes scientifiques\u00a0\u00bb, d\u00e9clare M. Soodyall. Selon elle, les prix tels que ceux d\u00e9cern\u00e9s par la NRF, le National Science and Technology Forum et la m\u00e9daille d&rsquo;or de l&rsquo;ASSAf constituent une plateforme essentielle pour c\u00e9l\u00e9brer ces r\u00e9alisations et motiver les chercheurs \u00e0 poursuivre leur contribution \u00e0 la soci\u00e9t\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des chercheurs sud-africains prim\u00e9s discutent de leurs travaux sur la p\u00e9nurie d&rsquo;eau et le cancer. 1 L\u2019ing\u00e9nieure chimiste Nomthandazo Sibiya s\u2019attaque \u00e0 la crise de l\u2019eau en Afrique du Sud 2 Ses recherches sur les m\u00e9taux pr\u00e9sents dans les eaux us\u00e9es lui ont valu un prix de la National Research Foundation 3 Des prix ont&hellip;<\/p>\n","protected":false},"author":1,"featured_media":21557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[161],"tags":[],"country":[],"objective":[],"sg_theme":[],"class_list":["post-18283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les laur\u00e9ats des bourses de recherche s&#039;attaquent \u00e0 la crise de l&#039;eau et au cancer - SGCI Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les laur\u00e9ats des bourses de recherche s&#039;attaquent \u00e0 la crise de l&#039;eau et au cancer\" \/>\n<meta property=\"og:description\" content=\"Des chercheurs sud-africains prim\u00e9s discutent de leurs travaux sur la p\u00e9nurie d&rsquo;eau et le cancer. 1 L\u2019ing\u00e9nieure chimiste Nomthandazo Sibiya s\u2019attaque \u00e0 la crise de l\u2019eau en Afrique du Sud 2 Ses recherches sur les m\u00e9taux pr\u00e9sents dans les eaux us\u00e9es lui ont valu un prix de la National Research Foundation 3 Des prix ont&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T14:13:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T14:01:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"491\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"modular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"modular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/\"},\"author\":{\"name\":\"modular\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/ad6aec2baf31e79490a348ed706cb80e\"},\"headline\":\"Les laur\u00e9ats des bourses de recherche s&rsquo;attaquent \u00e0 la crise de l&rsquo;eau et au cancer\",\"datePublished\":\"2023-11-28T14:13:34+00:00\",\"dateModified\":\"2026-02-11T14:01:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/\"},\"wordCount\":1185,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/communal_tap_soweto_Featured.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/\",\"name\":\"Les laur\u00e9ats des bourses de recherche s'attaquent \u00e0 la crise de l'eau et au cancer - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/communal_tap_soweto_Featured.jpg\",\"datePublished\":\"2023-11-28T14:13:34+00:00\",\"dateModified\":\"2026-02-11T14:01:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/communal_tap_soweto_Featured.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/communal_tap_soweto_Featured.jpg\",\"width\":800,\"height\":491,\"caption\":\"Robinet collectif pour l\u2019eau potable, Soweto, Afrique du Sud. Photo avec l\u2019aimable autorisation du secr\u00e9tariat SuSanA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les laur\u00e9ats des bourses de recherche s&#8217;attaquent \u00e0 la crise de l&#8217;eau et au cancer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/ad6aec2baf31e79490a348ed706cb80e\",\"name\":\"modular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"caption\":\"modular\"},\"sameAs\":[\"http:\\\/\\\/178.62.24.76\"],\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/author\\\/modular\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les laur\u00e9ats des bourses de recherche s'attaquent \u00e0 la crise de l'eau et au cancer - SGCI Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/","og_locale":"fr_FR","og_type":"article","og_title":"Les laur\u00e9ats des bourses de recherche s'attaquent \u00e0 la crise de l'eau et au cancer","og_description":"Des chercheurs sud-africains prim\u00e9s discutent de leurs travaux sur la p\u00e9nurie d&rsquo;eau et le cancer. 1 L\u2019ing\u00e9nieure chimiste Nomthandazo Sibiya s\u2019attaque \u00e0 la crise de l\u2019eau en Afrique du Sud 2 Ses recherches sur les m\u00e9taux pr\u00e9sents dans les eaux us\u00e9es lui ont valu un prix de la National Research Foundation 3 Des prix ont&hellip;","og_url":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/","og_site_name":"SGCI Africa","article_published_time":"2023-11-28T14:13:34+00:00","article_modified_time":"2026-02-11T14:01:40+00:00","og_image":[{"width":800,"height":491,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg","type":"image\/jpeg"}],"author":"modular","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"\u00c9crit par":"modular","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/"},"author":{"name":"modular","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/ad6aec2baf31e79490a348ed706cb80e"},"headline":"Les laur\u00e9ats des bourses de recherche s&rsquo;attaquent \u00e0 la crise de l&rsquo;eau et au cancer","datePublished":"2023-11-28T14:13:34+00:00","dateModified":"2026-02-11T14:01:40+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/"},"wordCount":1185,"commentCount":0,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/","url":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/","name":"Les laur\u00e9ats des bourses de recherche s'attaquent \u00e0 la crise de l'eau et au cancer - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg","datePublished":"2023-11-28T14:13:34+00:00","dateModified":"2026-02-11T14:01:40+00:00","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg","width":800,"height":491,"caption":"Robinet collectif pour l\u2019eau potable, Soweto, Afrique du Sud. Photo avec l\u2019aimable autorisation du secr\u00e9tariat SuSanA"},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/les-laureats-des-bourses-de-recherche-sattaquent-a-la-crise-de-leau-et-au-cancer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les laur\u00e9ats des bourses de recherche s&#8217;attaquent \u00e0 la crise de l&#8217;eau et au cancer"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/ad6aec2baf31e79490a348ed706cb80e","name":"modular","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","caption":"modular"},"sameAs":["http:\/\/178.62.24.76"],"url":"https:\/\/sgciafrica.org\/fr\/author\/modular\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg",800,491,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured-300x184.jpg",300,184,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured-768x471.jpg",768,471,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg",800,491,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg",800,491,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg",800,491,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg",800,491,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg",800,491,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg",800,491,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured.jpg",800,491,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2023\/11\/communal_tap_soweto_Featured-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"modular","author_link":"https:\/\/sgciafrica.org\/fr\/author\/modular\/"},"uagb_comment_info":0,"uagb_excerpt":"Des chercheurs sud-africains prim\u00e9s discutent de leurs travaux sur la p\u00e9nurie d&rsquo;eau et le cancer. 1 L\u2019ing\u00e9nieure chimiste Nomthandazo Sibiya s\u2019attaque \u00e0 la crise de l\u2019eau en Afrique du Sud 2 Ses recherches sur les m\u00e9taux pr\u00e9sents dans les eaux us\u00e9es lui ont valu un prix de la National Research Foundation 3 Des prix ont&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/18283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=18283"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/18283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/21557"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=18283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=18283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=18283"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=18283"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/objective?post=18283"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=18283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}