{"id":18063,"date":"2022-10-19T14:14:00","date_gmt":"2022-10-19T13:14:00","guid":{"rendered":"https:\/\/sgciafrica.org\/?p=18063"},"modified":"2026-02-12T13:01:45","modified_gmt":"2026-02-12T13:01:45","slug":"un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/","title":{"rendered":"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l&rsquo;action contre le cancer"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2022\/10\/vsdvsdsd.png\" alt=\"\" class=\"wp-image-5244\"\/><\/figure>\n\n<p>En octobre 2021, les professeurs Olga Lompo et Samira Ou\u00e9draogo ont officiellement commenc\u00e9 \u00e0 mettre en \u0153uvre des activit\u00e9s de recherche et de formation dans le cadre de l&rsquo;initiative des chaires de recherche africaines O.R. Tambo (ORTARChI) \u00e0 l&rsquo;<em>Universit\u00e9 <\/em>Joseph Ki-Zerbo (UJKZ) au Burkina Faso, la toute premi\u00e8re chaire de recherche attribu\u00e9e \u00e0 un pays francophone.<\/p>\n\n<p>Cette chaire de recherche a \u00e9t\u00e9 attribu\u00e9e selon un mod\u00e8le de copr\u00e9sidence. En outre, le NRF a \u00e9tabli un partenariat direct avec son agence s\u0153ur au Burkina Faso, le <em>Fonds national de la recherche et de l&rsquo;innovation pour le d\u00e9veloppement (FONRID),<\/em> pour diriger la mise en \u0153uvre de l&rsquo;ORTARChI au Burkina Faso.<\/p>\n\n<p>Un an plus tard, un plan de mise en \u0153uvre a \u00e9t\u00e9 finalis\u00e9 et l&rsquo;\u00e9thique de la recherche a \u00e9t\u00e9 approuv\u00e9e. Des responsables scientifiques et techniques ont \u00e9t\u00e9 recrut\u00e9s pour soutenir la chaire. Des bureaux et des laboratoires ont \u00e9t\u00e9 mis \u00e0 disposition par l&rsquo;universit\u00e9.<\/p>\n\n<p>En outre, cinq \u00e9tudiants en doctorat et cinq \u00e9tudiants en master, ainsi qu&rsquo;un chercheur postdoctoral ont \u00e9t\u00e9 recrut\u00e9s. La cohorte d&rsquo;\u00e9tudiants a b\u00e9n\u00e9fici\u00e9 d&rsquo;une s\u00e9rie de cours pr\u00e9paratoires propos\u00e9s par la chaire en m\u00e9thodologie de la recherche, analyse de la litt\u00e9rature, publication scientifique, gestion des donn\u00e9es et langue anglaise.<\/p>\n\n<p>En se concentrant sur les cinq cancers les plus diagnostiqu\u00e9s au Burkina Faso, \u00e0 savoir les cancers du col de l&rsquo;ut\u00e9rus, du sein, du foie, de la prostate et de l&rsquo;enfant, cette chaire de recherche contribue \u00e0 am\u00e9liorer la pr\u00e9cision des donn\u00e9es collect\u00e9es par les registres des cancers du pays. Ce travail a commenc\u00e9 avec le CHU Yalgado Ou\u00e9draogo, le plus grand h\u00f4pital universitaire du Burkina Faso, comme site pilote.<\/p>\n\n<p>Le programme de recherche vise \u00e9galement \u00e0 d\u00e9crire le parcours th\u00e9rapeutique des patients atteints de cancer au Burkina Faso et \u00e0 \u00e9laborer des strat\u00e9gies fond\u00e9es sur des donn\u00e9es probantes en vue d&rsquo;am\u00e9liorer la qualit\u00e9 des soins, la survie des patients et leur qualit\u00e9 de vie.<\/p>\n\n<p>En septembre 2022, la chaire a accueilli une conf\u00e9rence sur le d\u00e9pistage du cancer \u00e0 laquelle ont particip\u00e9 des chercheurs, des d\u00e9cideurs politiques, des industriels et des praticiens d&rsquo;Afrique francophone, dans le but de partager leurs exp\u00e9riences en mati\u00e8re de d\u00e9pistage du cancer.<\/p>\n\n<p>Pour assurer la p\u00e9rennit\u00e9 de la chaire, la direction de l&rsquo;<em>Universit\u00e9 <\/em>Joseph Ki-Zerbo a r\u00e9cemment finalis\u00e9 un plan strat\u00e9gique quinquennal qui d\u00e9finit le soutien strat\u00e9gique et op\u00e9rationnel de l&rsquo;universit\u00e9 \u00e0 la chaire. Elle indique \u00e9galement la volont\u00e9 de tirer parti de la chaire pour approfondir la strat\u00e9gie d&rsquo;internationalisation de l&rsquo;universit\u00e9, tant en Afrique francophone qu&rsquo;anglophone.<\/p>\n\n<p><em>L&rsquo;initiative des chaires de recherche africaines O.R. Tambo (ORTARChI) combine des objectifs politiques, de d\u00e9veloppement et d&rsquo;enseignement sup\u00e9rieur. Il vise \u00e0 honorer une personnalit\u00e9 de premier plan dans le d\u00e9veloppement de l&rsquo;unit\u00e9 africaine, \u00e0 avoir un impact catalytique sur le d\u00e9veloppement des infrastructures de recherche dans les pays b\u00e9n\u00e9ficiaires et \u00e0 contribuer \u00e0 la production de connaissances et de comp\u00e9tences de haut niveau conform\u00e9ment \u00e0 l&rsquo;Agenda 2063 de l&rsquo;UA et \u00e0 la STISA 2024. Dix (10) chaires de recherche africaines O.R. Tambo ont \u00e9t\u00e9 attribu\u00e9es dans sept pays, \u00e0 savoir le Botswana, le Burkina Faso, le Ghana, le Mozambique, la Tanzanie, l&rsquo;Ouganda et la Zambie. La NRF et le minist\u00e8re sud-africain de la science et de l&rsquo;innovation (DSI), ainsi que leurs principaux partenaires, la Fondation Oliver et Adelaide Tambo et le Centre de recherches pour le d\u00e9veloppement international (CRDI) du Canada, se sont associ\u00e9s aux agences s\u0153urs de la NRF dans les sept pays et aux universit\u00e9s pour mettre en \u0153uvre l&rsquo;initiative.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En octobre 2021, les professeurs Olga Lompo et Samira Ou\u00e9draogo ont officiellement commenc\u00e9 \u00e0 mettre en \u0153uvre des activit\u00e9s de recherche et de formation dans le cadre de l&rsquo;initiative des chaires de recherche africaines O.R. Tambo (ORTARChI) \u00e0 l&rsquo;Universit\u00e9 Joseph Ki-Zerbo (UJKZ) au Burkina Faso, la toute premi\u00e8re chaire de recherche attribu\u00e9e \u00e0 un pays&hellip;<\/p>\n","protected":false},"author":1,"featured_media":20920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":0,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[161],"tags":[],"country":[169],"objective":[],"sg_theme":[],"class_list":["post-18063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","country-burkina-faso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l&#039;action contre le cancer - SGCI Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l&#039;action contre le cancer\" \/>\n<meta property=\"og:description\" content=\"En octobre 2021, les professeurs Olga Lompo et Samira Ou\u00e9draogo ont officiellement commenc\u00e9 \u00e0 mettre en \u0153uvre des activit\u00e9s de recherche et de formation dans le cadre de l&rsquo;initiative des chaires de recherche africaines O.R. Tambo (ORTARChI) \u00e0 l&rsquo;Universit\u00e9 Joseph Ki-Zerbo (UJKZ) au Burkina Faso, la toute premi\u00e8re chaire de recherche attribu\u00e9e \u00e0 un pays&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-19T13:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T13:01:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"modular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"modular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/\"},\"author\":{\"name\":\"modular\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/ad6aec2baf31e79490a348ed706cb80e\"},\"headline\":\"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l&rsquo;action contre le cancer\",\"datePublished\":\"2022-10-19T13:14:00+00:00\",\"dateModified\":\"2026-02-12T13:01:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/\"},\"wordCount\":669,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/news-article.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/\",\"name\":\"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l'action contre le cancer - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/news-article.jpg\",\"datePublished\":\"2022-10-19T13:14:00+00:00\",\"dateModified\":\"2026-02-12T13:01:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/news-article.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/news-article.jpg\",\"width\":1000,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l&rsquo;action contre le cancer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/ad6aec2baf31e79490a348ed706cb80e\",\"name\":\"modular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"caption\":\"modular\"},\"sameAs\":[\"http:\\\/\\\/178.62.24.76\"],\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/author\\\/modular\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l'action contre le cancer - SGCI Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/","og_locale":"fr_FR","og_type":"article","og_title":"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l'action contre le cancer","og_description":"En octobre 2021, les professeurs Olga Lompo et Samira Ou\u00e9draogo ont officiellement commenc\u00e9 \u00e0 mettre en \u0153uvre des activit\u00e9s de recherche et de formation dans le cadre de l&rsquo;initiative des chaires de recherche africaines O.R. Tambo (ORTARChI) \u00e0 l&rsquo;Universit\u00e9 Joseph Ki-Zerbo (UJKZ) au Burkina Faso, la toute premi\u00e8re chaire de recherche attribu\u00e9e \u00e0 un pays&hellip;","og_url":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/","og_site_name":"SGCI Africa","article_published_time":"2022-10-19T13:14:00+00:00","article_modified_time":"2026-02-12T13:01:45+00:00","og_image":[{"width":1000,"height":400,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","type":"image\/jpeg"}],"author":"modular","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"\u00c9crit par":"modular","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/"},"author":{"name":"modular","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/ad6aec2baf31e79490a348ed706cb80e"},"headline":"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l&rsquo;action contre le cancer","datePublished":"2022-10-19T13:14:00+00:00","dateModified":"2026-02-12T13:01:45+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/"},"wordCount":669,"commentCount":0,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/","url":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/","name":"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l'action contre le cancer - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","datePublished":"2022-10-19T13:14:00+00:00","dateModified":"2026-02-12T13:01:45+00:00","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","width":1000,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/un-an-de-mise-en-oeuvre-de-la-chaire-de-recherche-africaine-o-r-tambo-sur-la-recherche-et-laction-contre-le-cancer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Un an de mise en \u0153uvre de la Chaire de recherche africaine O.R. Tambo sur la recherche et l&rsquo;action contre le cancer"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/ad6aec2baf31e79490a348ed706cb80e","name":"modular","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","caption":"modular"},"sameAs":["http:\/\/178.62.24.76"],"url":"https:\/\/sgciafrica.org\/fr\/author\/modular\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article-300x120.jpg",300,120,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article-768x307.jpg",768,307,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"modular","author_link":"https:\/\/sgciafrica.org\/fr\/author\/modular\/"},"uagb_comment_info":0,"uagb_excerpt":"En octobre 2021, les professeurs Olga Lompo et Samira Ou\u00e9draogo ont officiellement commenc\u00e9 \u00e0 mettre en \u0153uvre des activit\u00e9s de recherche et de formation dans le cadre de l&rsquo;initiative des chaires de recherche africaines O.R. Tambo (ORTARChI) \u00e0 l&rsquo;Universit\u00e9 Joseph Ki-Zerbo (UJKZ) au Burkina Faso, la toute premi\u00e8re chaire de recherche attribu\u00e9e \u00e0 un pays&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/18063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=18063"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/18063\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/20920"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=18063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=18063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=18063"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=18063"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/objective?post=18063"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=18063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}