{"id":17820,"date":"2022-02-28T14:14:00","date_gmt":"2022-02-28T14:14:00","guid":{"rendered":"https:\/\/sgciafrica.org\/?p=17820"},"modified":"2026-02-12T13:20:53","modified_gmt":"2026-02-12T13:20:53","slug":"genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable","status":"publish","type":"post","link":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/","title":{"rendered":"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gr\u00e2ce aux travaux men\u00e9s par le Conseil de recherche en sciences humaines (HSRC) d&rsquo;Afrique du Sud, le SGCI a adopt\u00e9 une approche intersectionnelle et participative pour int\u00e9grer les questions de genre et d&rsquo;inclusion dans les SGC. En utilisant la m\u00e9thodologie d&rsquo;apprentissage par l&rsquo;action en mati\u00e8re de genre d\u00e9velopp\u00e9e par Gender at Work, la SGCI veille \u00e0 ce que les programmes de transformation des conseils en mati\u00e8re de genre soient pris en compte et encourage un sentiment d&rsquo;appropriation du processus de changement en tant que m\u00e9canismes cl\u00e9s pour stimuler le changement individuel et syst\u00e9mique.<\/p>\n\n<p class=\"wp-block-paragraph\">Au cours des derniers mois, 9 des 15 SGC ont particip\u00e9 \u00e0 plusieurs activit\u00e9s d&rsquo;apprentissage par l&rsquo;action sur le genre, facilit\u00e9es par Gender at Work. Le premier d&rsquo;entre eux \u00e9tait une s\u00e9rie d&rsquo;ateliers intitul\u00e9s \u00ab\u00a0Hearing our Stories\u00a0\u00bb (\u00e9couter nos histoires), un processus interactif visant \u00e0 mettre en lumi\u00e8re les travaux ant\u00e9rieurs men\u00e9s par les conseils et \u00e0 d\u00e9terminer o\u00f9 en sont actuellement les SGC en termes d&rsquo;avancement de la transformation en mati\u00e8re d&rsquo;\u00e9galit\u00e9 des sexes et d&rsquo;inclusion. Ce fut \u00e9galement le d\u00e9but du processus d&rsquo;identification d&rsquo;\u00e9quipes de changement potentielles au sein des conseils qui entreprendraient des exp\u00e9riences de changement, petites mais significatives, pendant toute la dur\u00e9e de la mise en \u0153uvre du th\u00e8me SGCI sur le genre et l&rsquo;inclusion (G&amp;I). Ces exp\u00e9riences sont align\u00e9es sur les activit\u00e9s en cours au sein des conseils afin de permettre une meilleure assimilation du changement.<\/p>\n\n<p class=\"wp-block-paragraph\">La deuxi\u00e8me activit\u00e9 \u00e9tait un atelier intensif de quatre jours sur l&rsquo;apprentissage par les pairs, au cours duquel les membres de neuf conseils, r\u00e9partis en deux cohortes, ont particip\u00e9 \u00e0 un processus visant \u00e0 faire \u00e9merger leurs propres perceptions et exp\u00e9riences en mati\u00e8re d&rsquo;\u00e9galit\u00e9 des sexes et d&rsquo;inclusion au sein de leur conseil et dans le contexte de leur pays. Ce processus par les pairs et les consultations mensuelles en ligne offrent aux SGC la possibilit\u00e9 d&rsquo;apprendre les uns des autres. Certains participants affirment que le processus a \u00ab\u00a0arrach\u00e9 le sol sous leurs pieds\u00a0\u00bb ou que \u00ab\u00a0la fa\u00e7on dont nous observons ce qui se passe autour de nous a chang\u00e9 \u00e0 jamais\u00a0\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">Les SGC apprennent, parfois pour la premi\u00e8re fois, que la transformation de l&rsquo;\u00e9galit\u00e9 des sexes et de l&rsquo;inclusion ne se limite pas \u00e0 la cr\u00e9ation de politiques bien structur\u00e9es, \u00e0 l&rsquo;\u00e9quilibre entre les hommes et les femmes au sein du personnel ou \u00e0 l&rsquo;\u00e9galit\u00e9 des chances pour les femmes en mati\u00e8re d&rsquo;obtention de subventions de recherche. Au contraire, assurer un changement syst\u00e9mique durable en mati\u00e8re de genre et d&rsquo;inclusion pourrait n\u00e9cessiter davantage d&rsquo;efforts \u00e0 diff\u00e9rents niveaux, y compris des changements dans la conscience personnelle, les attitudes et les comportements du personnel et des parties prenantes, ainsi qu&rsquo;un changement culturel institutionnel dans la \u00ab\u00a0fa\u00e7on dont nous faisons les choses ici\u00a0\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Le th\u00e8me SGCI G&amp;I vise \u00e0 renforcer les capacit\u00e9s des SGC \u00e0 faire progresser le changement syst\u00e9mique vers une plus grande \u00e9galit\u00e9 des sexes dans le secteur de la science, de la technologie et de l&rsquo;innovation. Les activit\u00e9s men\u00e9es dans le cadre de ce th\u00e8me sont dirig\u00e9es par le Human Sciences Research Council (HSRC) d&rsquo;Afrique du Sud, en partenariat avec Gender at Work, le Conseil pour le d\u00e9veloppement de la recherche en sciences sociales en Afrique (CODESRIA) et Jive Media Africa.<\/em><\/p>\n\n<p class=\"wp-block-paragraph\">Pour plus d&rsquo;informations, veuillez contacter<\/p>\n\n<p class=\"wp-block-paragraph\">Dr Lorenza Fluks (HSRC) et Michal Friedman (Gender at Work)<\/p>\n\n<p class=\"wp-block-paragraph\">Courriel : <a href=\"mailto:LFluks@hsrc.ac.za\">LFluks@hsrc.ac.za<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gr\u00e2ce aux travaux men\u00e9s par le Conseil de recherche en sciences humaines (HSRC) d&rsquo;Afrique du Sud, le SGCI a adopt\u00e9 une approche intersectionnelle et participative pour int\u00e9grer les questions de genre et d&rsquo;inclusion dans les SGC. En utilisant la m\u00e9thodologie d&rsquo;apprentissage par l&rsquo;action en mati\u00e8re de genre d\u00e9velopp\u00e9e par Gender at Work, la SGCI veille&hellip;<\/p>\n","protected":false},"author":1,"featured_media":20920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wds_primary_category":160,"wds_primary_country":0,"wds_primary_objective":0,"wds_primary_sg_theme":0,"footnotes":""},"categories":[161],"tags":[],"country":[],"objective":[],"sg_theme":[287],"class_list":["post-17820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","sg_theme-questions-degalite-des-sexes-et-dinclusion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable - SGCI Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable\" \/>\n<meta property=\"og:description\" content=\"Gr\u00e2ce aux travaux men\u00e9s par le Conseil de recherche en sciences humaines (HSRC) d&rsquo;Afrique du Sud, le SGCI a adopt\u00e9 une approche intersectionnelle et participative pour int\u00e9grer les questions de genre et d&rsquo;inclusion dans les SGC. En utilisant la m\u00e9thodologie d&rsquo;apprentissage par l&rsquo;action en mati\u00e8re de genre d\u00e9velopp\u00e9e par Gender at Work, la SGCI veille&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/\" \/>\n<meta property=\"og:site_name\" content=\"SGCI Africa\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-28T14:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T13:20:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"modular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:site\" content=\"@SGCIAfrica\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"modular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/\"},\"author\":{\"name\":\"modular\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/3bf367048e540da345962ed4b2a3e65c\"},\"headline\":\"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable\",\"datePublished\":\"2022-02-28T14:14:00+00:00\",\"dateModified\":\"2026-02-12T13:20:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/\"},\"wordCount\":643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/news-article.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/\",\"name\":\"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable - SGCI Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/news-article.jpg\",\"datePublished\":\"2022-02-28T14:14:00+00:00\",\"dateModified\":\"2026-02-12T13:20:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/news-article.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/news-article.jpg\",\"width\":1000,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#website\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"name\":\"SGCI Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgciafrica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#organization\",\"name\":\"SGCI Africa\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SGCI_Logo_Secondary_Large.png\",\"width\":3888,\"height\":1080,\"caption\":\"SGCI Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SGCIAfrica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/#\\\/schema\\\/person\\\/3bf367048e540da345962ed4b2a3e65c\",\"name\":\"modular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"url\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"contentUrl\":\"https:\\\/\\\/sgciafrica.org\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/a92\\\/a92885fc969755c2afc8c34d6aed503dx96.jpg\",\"caption\":\"modular\"},\"sameAs\":[\"http:\\\/\\\/178.62.24.76\"],\"url\":\"https:\\\/\\\/sgciafrica.org\\\/fr\\\/author\\\/modular\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable - SGCI Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/","og_locale":"fr_FR","og_type":"article","og_title":"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable","og_description":"Gr\u00e2ce aux travaux men\u00e9s par le Conseil de recherche en sciences humaines (HSRC) d&rsquo;Afrique du Sud, le SGCI a adopt\u00e9 une approche intersectionnelle et participative pour int\u00e9grer les questions de genre et d&rsquo;inclusion dans les SGC. En utilisant la m\u00e9thodologie d&rsquo;apprentissage par l&rsquo;action en mati\u00e8re de genre d\u00e9velopp\u00e9e par Gender at Work, la SGCI veille&hellip;","og_url":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/","og_site_name":"SGCI Africa","article_published_time":"2022-02-28T14:14:00+00:00","article_modified_time":"2026-02-12T13:20:53+00:00","og_image":[{"width":1000,"height":400,"url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","type":"image\/jpeg"}],"author":"modular","twitter_card":"summary_large_image","twitter_creator":"@SGCIAfrica","twitter_site":"@SGCIAfrica","twitter_misc":{"\u00c9crit par":"modular","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/#article","isPartOf":{"@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/"},"author":{"name":"modular","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/3bf367048e540da345962ed4b2a3e65c"},"headline":"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable","datePublished":"2022-02-28T14:14:00+00:00","dateModified":"2026-02-12T13:20:53+00:00","mainEntityOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/"},"wordCount":643,"commentCount":0,"publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/","url":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/","name":"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable - SGCI Africa","isPartOf":{"@id":"https:\/\/sgciafrica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/#primaryimage"},"image":{"@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","datePublished":"2022-02-28T14:14:00+00:00","dateModified":"2026-02-12T13:20:53+00:00","breadcrumb":{"@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/#primaryimage","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg","width":1000,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/sgciafrica.org\/fr\/genre-et-inclusion-dans-les-conseils-de-subventionnement-scientifique-une-approche-participative-pour-parvenir-a-un-changement-systemique-durable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgciafrica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Genre et inclusion dans les conseils de subventionnement scientifique : Une approche participative pour parvenir \u00e0 un changement syst\u00e9mique durable"}]},{"@type":"WebSite","@id":"https:\/\/sgciafrica.org\/#website","url":"https:\/\/sgciafrica.org\/","name":"SGCI Africa","description":"","publisher":{"@id":"https:\/\/sgciafrica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgciafrica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sgciafrica.org\/#organization","name":"SGCI Africa","url":"https:\/\/sgciafrica.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/","url":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/12\/SGCI_Logo_Secondary_Large.png","width":3888,"height":1080,"caption":"SGCI Africa"},"image":{"@id":"https:\/\/sgciafrica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SGCIAfrica"]},{"@type":"Person","@id":"https:\/\/sgciafrica.org\/#\/schema\/person\/3bf367048e540da345962ed4b2a3e65c","name":"modular","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","url":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","contentUrl":"https:\/\/sgciafrica.org\/wp-content\/wphb-cache\/gravatar\/a92\/a92885fc969755c2afc8c34d6aed503dx96.jpg","caption":"modular"},"sameAs":["http:\/\/178.62.24.76"],"url":"https:\/\/sgciafrica.org\/fr\/author\/modular\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"thumbnail":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article-150x150.jpg",150,150,true],"medium":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article-300x120.jpg",300,120,true],"medium_large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article-768x307.jpg",768,307,true],"large":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"1536x1536":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"2048x2048":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-full-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-full-content-width":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-container-half":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-single-tile":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article.jpg",1000,400,false],"sg-council-user":["https:\/\/sgciafrica.org\/wp-content\/uploads\/2024\/04\/news-article-90x90.jpg",90,90,true]},"uagb_author_info":{"display_name":"modular","author_link":"https:\/\/sgciafrica.org\/fr\/author\/modular\/"},"uagb_comment_info":0,"uagb_excerpt":"Gr\u00e2ce aux travaux men\u00e9s par le Conseil de recherche en sciences humaines (HSRC) d&rsquo;Afrique du Sud, le SGCI a adopt\u00e9 une approche intersectionnelle et participative pour int\u00e9grer les questions de genre et d&rsquo;inclusion dans les SGC. En utilisant la m\u00e9thodologie d&rsquo;apprentissage par l&rsquo;action en mati\u00e8re de genre d\u00e9velopp\u00e9e par Gender at Work, la SGCI veille&hellip;","_links":{"self":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/17820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=17820"}],"version-history":[{"count":0,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/posts\/17820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media\/20920"}],"wp:attachment":[{"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=17820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=17820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=17820"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/country?post=17820"},{"taxonomy":"objective","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/objective?post=17820"},{"taxonomy":"sg_theme","embeddable":true,"href":"https:\/\/sgciafrica.org\/fr\/wp-json\/wp\/v2\/sg_theme?post=17820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}